{"id":23768,"date":"2017-12-04T11:45:18","date_gmt":"2017-12-04T10:45:18","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23768"},"modified":"2017-12-04T11:45:18","modified_gmt":"2017-12-04T10:45:18","slug":"jugar-al-talentum","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/jugar-al-talentum\/","title":{"rendered":"Jugar al Talentum"},"content":{"rendered":"<p>\u00bfSon ustedes jugones? \u00bfHartos de vivir a trav\u00e9s de la pantalla del m\u00f3vil-tablet-ordenador-televisi\u00f3n? \u00bfTienen ganas de volver a mirar a la cara a esos familiares cercanos y amigos de toda la vida a los que solo reconocen por su foto de perfil en las redes sociales? \u00bfLes gusta el Trivial, pero ya est\u00e1n aburridos de contestar que el sudor del hipop\u00f3tamo es rojo?<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/jugar-al-talentum\/91edd6q3gwl-_sx355_\/\" rel=\"attachment wp-att-23769\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23769\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91edd6Q3gwL._SX355_-300x221.jpg\" alt=\"\" width=\"300\" height=\"221\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91edd6Q3gwL._SX355_-300x221.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91edd6Q3gwL._SX355_.jpg 355w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Si ustedes han respondido que s\u00ed a alguna de las anteriores preguntas, apunten un nombre: Talentum. Se trata de un libro-juego reci\u00e9n salido al mercado, con 10.000 preguntas diferentes para jugar. Sin necesidad de tableros, equipos, dados, quesitos ni otros aditamentos.<\/p>\n<p>\u201cLa ontolog\u00eda es la rama de la filosof\u00eda que se ocupa del estudio del\u2026\u201d. \u201cLas ballenas cierran los o\u00eddos cuando hay demasiado ruido: \u00bfverdadero o falso?\u201d. \u201cCambia la primera letra de \u201cmina\u201d y forma una nueva palabra\u201d. \u201cEstoy en la presa de las Tres Gargantas, la mayor del mundo. \u00bfQu\u00e9 pa\u00eds visito?\u201d. \u201c\u00bfCu\u00e1ntas cuerdas tiene un viol\u00edn?\u201d.<\/p>\n<p>Esas son las cinco primeras preguntas de las veinte que figuran en la p\u00e1gina 371 de Talentum, que he abierto al azar para escribir esta columna. \u00bfQu\u00e9 les parecen? \u00bfF\u00e1ciles, dif\u00edciles, tiradas o\u2026 depende? \u00bfCu\u00e1ntas han adivinado?<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/jugar-al-talentum\/img_20170429_140359\/\" rel=\"attachment wp-att-23770\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23770\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/IMG_20170429_140359-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/IMG_20170429_140359-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/IMG_20170429_140359-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/IMG_20170429_140359-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/IMG_20170429_140359.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Ahora que se acercan el Puente de la Inmaculada Constituci\u00f3n y la Navidad, fechas para pasar mucho tiempo encerrados entre las cuatro paredes -aunque no estemos incomunicados por la nieve en un alojamiento rural- y rodeados de gente; Talentum es una excelente opci\u00f3n para divertirse y disfrutar a trav\u00e9s de un juego de marcado car\u00e1cter cultural.<\/p>\n<p>Editado por la editorial Gamebook, Talentum es el primer juego puesto en el mercado una empresa editorial granadina que, pronto, comercializar\u00e1 otros atractivos juegos basados en barajas y cartas.<\/p>\n<p>En los tiempos de la realidad virtual y la inteligencia artificial, da gusto poder desconectar un rato para disfrutar con un juego anal\u00f3gico que fomenta la cultura y la curiosidad, apelando a la inteligencia de las personas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/jugar-al-talentum\/91zbhf29f7l-_sl1500_\/\" rel=\"attachment wp-att-23771\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23771\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91zBHF29F7L._SL1500_-297x300.jpg\" alt=\"\" width=\"297\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91zBHF29F7L._SL1500_-297x300.jpg 297w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91zBHF29F7L._SL1500_-768x775.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91zBHF29F7L._SL1500_-644x650.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/12\/91zBHF29F7L._SL1500_.jpg 1487w\" sizes=\"auto, (max-width: 297px) 100vw, 297px\" \/><\/a><\/p>\n<p>Por cierto que la ontolog\u00eda estudia el ser o la realidad, las ballenas no se hacen los o\u00eddos sordos para luchar contra el estr\u00e9pito, mina se puede convertir en tina y en fina, la descomunal presa de las Tres Gargantas est\u00e1 en China y un viol\u00edn tiene cuatro cuerdas. \u00a1Qui\u00e9n lo dir\u00eda, con lo dif\u00edcil que debe ser tocarlo\u2026 sin amargarle la vida a la pobre ballena!<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23654 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23654 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfSon ustedes jugones? \u00bfHartos de vivir a trav\u00e9s de la pantalla del m\u00f3vil-tablet-ordenador-televisi\u00f3n? \u00bfTienen ganas de volver a mirar a la cara a esos familiares cercanos y amigos de toda la vida a los que solo reconocen por su foto de perfil en las redes sociales? \u00bfLes gusta el Trivial, pero ya est\u00e1n aburridos de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15483,15478,15479,15482,15480,15481,15477],"class_list":["post-23768","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-gamebook","tag-juego-talentum","tag-juegos-de-mesa-talentum","tag-juegos-de-preguntas","tag-juegos-parecidos-tribal","tag-libro-juego","tag-talentum"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23768","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23768"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23768\/revisions"}],"predecessor-version":[{"id":23773,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23768\/revisions\/23773"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23768"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23768"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23768"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}