{"id":23615,"date":"2017-11-14T13:21:47","date_gmt":"2017-11-14T12:21:47","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23615"},"modified":"2017-11-14T13:21:47","modified_gmt":"2017-11-14T12:21:47","slug":"el-costo-hundido","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-costo-hundido\/","title":{"rendered":"El costo hundido"},"content":{"rendered":"<p>Imaginemos que el pr\u00f3ximo viernes hay un concierto muy chulo en cualquier sala de Granada. Lo que no es mucho imaginar, dicho sea de paso, dado que salimos a 40 o 50 bolos musicales en esta ciudad, cada fin de semana.<\/p>\n<figure id=\"attachment_23616\" aria-describedby=\"caption-attachment-23616\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-costo-hundido\/treasure-chest-sinking-in-water-image-shot-2010-exact-date-unknown\/\" rel=\"attachment wp-att-23616\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-23616\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Coste-hundido-300x162.jpg\" alt=\"\" width=\"300\" height=\"162\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Coste-hundido-300x162.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Coste-hundido.jpg 604w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-23616\" class=\"wp-caption-text\">BMHPW6 Treasure chest sinking in water. Image shot 2010. Exact date unknown.<\/figcaption><\/figure>\n<p>Imaginemos que a usted le mola el grupo que toca y le apetece tanto ir a ese concierto que compra la entrada por Internet. Su cuate musical m\u00e1s cercano, con el que comparte gustos musicales, tambi\u00e9n ir\u00e1 al espect\u00e1culo, que esa banda es una de sus favoritas, pero no saca la entrada anticipada y decide esperar al d\u00eda en cuesti\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>Llega el viernes. Mal tiempo. Fr\u00edo. Viento. Cansancio acumulado de la semana. Est\u00e1 usted en casa, a media tarde, vestido con esa ropa taaaaaaaan c\u00f3moda y las alpargatas de pa\u00f1o\u2026 Ve usted la mantita en el sof\u00e1, provoc\u00e1ndole. Y entonces llega ella. La tentaci\u00f3n. La tentaci\u00f3n de no salir y quedarse a ver una pel\u00edcula o leer un buen libro. Pero, de ceder a ella, perder\u00eda el importe que pag\u00f3 por la entrada. \u00bfQu\u00e9 hacer?<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-costo-hundido\/costos-hundidos\/\" rel=\"attachment wp-att-23617\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23617\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costos-hundidos-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costos-hundidos-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costos-hundidos-768x431.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costos-hundidos-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costos-hundidos.jpg 890w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A su socio de correr\u00edas musicales le ha surgido la misma tentaci\u00f3n, por supuesto. Que tambi\u00e9n ha llegado a casa helado y la semana ha sido igualmente dura. Solo que \u00e9l todav\u00eda no se ha gastado ni un euro en el concierto. \u00bfA que podemos anticipar, m\u00e1s o menos, c\u00f3mo ser\u00eda el intercambio de WhatsApp entre ustedes dos? \u00bfQui\u00e9n pondr\u00eda m\u00e1s empe\u00f1o en ir al concierto y qui\u00e9n ser\u00eda m\u00e1s propenso a optar por el plan casero?<\/p>\n<p>&nbsp;<\/p>\n<p>El precio que usted pag\u00f3 por la entrada es lo que se llama un costo hundido: un gasto realizado en el pasado y que no puede ser recuperado. Y precisamente por eso, porque ya est\u00e1n hechos y resultan irrecuperables, los costos hundidos no deber\u00edan resultar relevantes a la hora de tomar decisiones de una forma fr\u00eda, anal\u00edtica y racional. Pero anda que no pesan\u2026<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-costo-hundido\/costo-hundido\/\" rel=\"attachment wp-att-23618\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23618\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Costo-hundido.jpg\" alt=\"\" width=\"262\" height=\"192\" \/><\/a><\/p>\n<p>\u00bfQui\u00e9n no se ha encontrado alguna vez enfrentado a una situaci\u00f3n por el estilo? Lo l\u00f3gico ser\u00eda ceder a la tentaci\u00f3n y pasar del concierto. Y, sin embargo, qu\u00e9 importancia tiene el costo hundido \u2013y un amigo persistente- para obligarnos a hacer cosas que, a priori, no nos apetecen, pero de las que luego nos alegramos sobremanera. \u00a1Viva la irracionalidad en la toma de seg\u00fan qu\u00e9 peque\u00f1as decisiones! Como la de irse de conciertos\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23486 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23486 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Imaginemos que el pr\u00f3ximo viernes hay un concierto muy chulo en cualquier sala de Granada. Lo que no es mucho imaginar, dicho sea de paso, dado que salimos a 40 o 50 bolos musicales en esta ciudad, cada fin de semana. Imaginemos que a usted le mola el grupo que toca y le apetece tanto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15362,15363,15364,2445],"class_list":["post-23615","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-coste-hundido","tag-costos-hundidos","tag-pagar-el-precio","tag-pereza"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23615","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23615"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23615\/revisions"}],"predecessor-version":[{"id":23620,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23615\/revisions\/23620"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23615"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23615"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23615"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}