{"id":23537,"date":"2017-11-02T14:39:58","date_gmt":"2017-11-02T13:39:58","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23537"},"modified":"2017-11-02T14:39:58","modified_gmt":"2017-11-02T13:39:58","slug":"pedos-de-hipopotamo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/pedos-de-hipopotamo\/","title":{"rendered":"Pedos de hipop\u00f3tamo"},"content":{"rendered":"<p>Es importante que tanta gente se haya cre\u00eddo lo del pedo del hipop\u00f3tamo, dando la noticia por cierta y comparti\u00e9ndola en sus redes sociales. Fijo que la han le\u00eddo: en el parque de Cab\u00e1rceno, un hipop\u00f3tamo solt\u00f3 un ventosidad de tal calibre que tres ancianos tuvieron que ser hospitalizados al entrar en contacto con el gas metano emitido por el animal.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pedos-de-hipopotamo\/pedo-de-hipopotamo\/\" rel=\"attachment wp-att-23538\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-23538\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Pedo-de-hipop\u00f3tamo.jpg\" alt=\"\" width=\"286\" height=\"176\" \/><\/a><\/p>\n<p>La noticia era tan chusca que llegaba a decir, como en la canci\u00f3n de Radio Futura, que alguno de los afectados cay\u00f3 fulminado al suelo. \u00bfSe acuerdan? \u201cHan ca\u00eddo los dos, cual soldados fulminados, al suelo. Y ahora est\u00e1n atrapados los dos, en la misma prisi\u00f3n\u2026\u201d.<\/p>\n<p>&nbsp;<\/p>\n<p>Es importante que nos creamos noticias falsas como la del pedo del hipop\u00f3tamo para constatar la facilidad con la que nos tragamos trolas y cuentos chinos; nuestra predisposici\u00f3n a dar por verdaderas historias cuestionables, pat\u00e9ticas y rid\u00edculas.<\/p>\n<p>&nbsp;<\/p>\n<p>Lo parad\u00f3jico es que, al mismo tiempo, nos cuesta creernos informaciones que, pudiendo ser ciertas adem\u00e1s de veros\u00edmiles, ponemos en solfa y en sordina. Por ejemplo, lo del antiguo alcalde de Granada, su secretaria, su hija y las cuentas en Zurich. \u00bfEn serio? \u00bfDe verdad? \u00bfEn Zurich? \u00bfEl tipo aquel de P\u00ed\u00f1ar del que los guays del paraguays se mofaban por cateto, pero que arras\u00f3 en tres elecciones consecutivas, en la muy culta, vanguardista y moderna ciudad de Granada?<\/p>\n<p>&nbsp;<\/p>\n<p>Zygmunt Bauman populariz\u00f3 el t\u00e9rmino de \u201cl\u00edquido\u201d, aplicado a la sociedad, a la cultura y a los tiempos que nos han tocado vivir: es todo tan voluble y cambia a tanta velocidad que los modelos sociales, los valores y las estructuras no tienen tiempo de enraizar y hacerse costumbre o norma para los ciudadanos. Lo que val\u00eda ayer, hoy lo despreciamos y no entendemos c\u00f3mo le pod\u00edamos conceder importancia alguna.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pedos-de-hipopotamo\/modernidad-liquida\/\" rel=\"attachment wp-att-23539\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23539\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Modernidad-l\u00edquida-201x300.jpg\" alt=\"\" width=\"201\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Modernidad-l\u00edquida-201x300.jpg 201w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/Modernidad-l\u00edquida.jpg 288w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n<p>Hablas ahora con cualquiera, le recuerdas que Pepe Torres arrasaba en las urnas una y otra vez; que incluso gan\u00f3 el \u00faltimo c\u00f3nclave electoral, hace un par de a\u00f1os, despu\u00e9s de sufrir un ictus y con la mitad de su partido en contra; y se hace un silencio inc\u00f3modo, como si aquello no hubiera ocurrido nunca.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pedos-de-hipopotamo\/cortina-de-humo-2\/\" rel=\"attachment wp-att-23540\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23540\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/cortina-de-humo-300x69.png\" alt=\"\" width=\"300\" height=\"69\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/cortina-de-humo-300x69.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/11\/cortina-de-humo.png 619w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00bfY si hubi\u00e9ramos evolucionado, pasando de la sociedad l\u00edquida a una gaseosa, repleta de cortinas de humo y pedos de hipop\u00f3tamo que nos aturden, nos confunden y no nos dejan ver la realidad, por mucho que la tengamos delante de los ojos?<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23486 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23486 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Es importante que tanta gente se haya cre\u00eddo lo del pedo del hipop\u00f3tamo, dando la noticia por cierta y comparti\u00e9ndola en sus redes sociales. Fijo que la han le\u00eddo: en el parque de Cab\u00e1rceno, un hipop\u00f3tamo solt\u00f3 un ventosidad de tal calibre que tres ancianos tuvieron que ser hospitalizados al entrar en contacto con el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15321,14413,6072,15320,15322],"class_list":["post-23537","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-bulos","tag-corrupcion-granada","tag-cortina-de-humo","tag-pedo-de-hipopotamo","tag-tragarse-bulos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23537","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23537"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23537\/revisions"}],"predecessor-version":[{"id":23542,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23537\/revisions\/23542"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23537"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23537"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23537"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}