{"id":235,"date":"2008-05-17T12:11:00","date_gmt":"2008-05-17T11:11:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=235"},"modified":"2008-05-17T12:11:00","modified_gmt":"2008-05-17T11:11:00","slug":"stopper","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/stopper\/","title":{"rendered":"STOPPER"},"content":{"rendered":"<table id=\"HB_Mail_Container\" height=\"100%\" cellspacing=\"0\" cellpadding=\"0\" width=\"100%\" border=\"0\" unselectable=\"on\">\n<tbody>\n<tr height=\"100%\" width=\"100%\" unselectable=\"on\">\n<td id=\"HB_Focus_Element\" valign=\"top\" width=\"100%\" background=\"\" height=\"250\" unselectable=\"off\">\n<div align=\"justify\"><span style=\"font-family:times new roman;\"><em><strong>Dedicado a Luis Rubiales, capit\u00e1n del Levante.<br \/>Si hubiera m\u00e1s jugadores como \u00e9l,<br \/>Pasar\u00edan menos cosas como las que se cuentan en este libro.<\/strong><\/em><\/span><\/p>\n<\/div>\n<p align=\"justify\"><\/p>\n<div align=\"justify\">En otras entregas del <a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/02\/un-proyecto-las-relaciones-entre-el.html\"><span style=\"color:#ff0000;\"><strong>Proyecto Florens<\/strong><\/span> <\/a>nos hemos fijado en lo importante que es asumir bien los cambios de ciclo vitales (<a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/02\/fin-de-ciclo-parte-i-pau-gasol.html\"><span style=\"color:#ff0000;\"><strong>ejemplo de Gasol<\/strong><\/span><\/a>) e, incluso, determinar cu\u00e1ndo es la hora de retirarse (<a href=\"http:\/\/pateando-el-mundo.blogspot.com\/2008\/04\/indurain-una-retirada-tiempo.html\"><span style=\"color:#ff0000;\"><strong>caso Indurain<\/strong><\/span><\/a>), poniendo el punto y final a una carrera deportiva o empresarial.<\/div>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5201303644776408130\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/SC6-G3PXpEI\/AAAAAAAAB1U\/RHbd0LUcdIs\/s400\/_017.jpg\" border=\"0\" \/><br \/>En esta ocasi\u00f3n vamos a tocar un tema peliagudo: el de \u201cY despu\u00e9s, \u00bfqu\u00e9?\u201d<\/p>\n<p>Para ello nos vamos a fijar en un modelo extra\u00eddo de la ficci\u00f3n, pero muy basado en la realidad. Porque si en posteriores ocasiones hablaremos de Luis Enrique, Andr\u00e9s Jim\u00e9nez, Guardiola, Laudrup, Schuster, Jalabert o Armstrong, bien conocidos por todos, hoy nos vamos a centrar en la figura de Juli\u00e1n, un jugador de f\u00fatbol al que, a buen seguro, nadie recuerda.<\/p>\n<p>Podr\u00eda ser Julio Alberto, por ejemplo. O el Chava Jim\u00e9nez. O el mism\u00edsimo Maradona, si el \u201cbarrilete c\u00f3smico\u201d no hubiera sido un tipo tan medi\u00e1tico. Pero no. Hablamos, sencillamente, de Juli\u00e1n, un prometedor chaval de la cantera valenciana que lleg\u00f3 a jugar en la selecci\u00f3n espa\u00f1ola de juveniles y que debut\u00f3 en primera divisi\u00f3n muy joven, not\u00e1ndose que iba para figura grande del f\u00fatbol.<\/p>\n<p>Un delantero centro con clase, estiloso, buena planta, r\u00e1pido y con car\u00e1cter. Un buen muchacho que cuid\u00f3 su cuerpo como si fuera un templo y que, sin embargo, cuando mejor se las promet\u00eda, sufri\u00f3 una importante lesi\u00f3n de rodilla. Y ya nunca m\u00e1s volvi\u00f3 a ser el mismo. Se hab\u00eda casado con una guapa ni\u00f1a bien, ten\u00eda una hija, su suegro era un potentado y todo le rodaba a las mil maravillas&#8230; hasta que la rodilla hizo crack. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5201303640481440802\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/SC6-GnPXpCI\/AAAAAAAAB1E\/UbWLa63PpdU\/s400\/_03.bmp\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Porque, aunque los m\u00e9dicos le dijeron que la operaci\u00f3n fue un \u00e9xito, no pudo volver a ser el que era. De hecho, un entrenador con vista y talento le reconvirti\u00f3 en defensa central, dado que su pierna no estaba para excesivas filigranas en el \u00e1rea contraria. A\u00fan as\u00ed, los contratos se desvanecieron en el aire y, de verse rifado por los clubes de Primera, se encontr\u00f3 jugando en los campos de Segunda divisi\u00f3n. Y a\u00fan ten\u00eda que dar las gracias. S\u00f3lo que a su mujer, eso de verse en Extremadura y alrededores no le hizo la menor gracia. Y se march\u00f3, llev\u00e1ndose consigo a las dos ni\u00f1as que ya ten\u00eda el matrimonio.<\/p>\n<p>Juli\u00e1n comenz\u00f3 a deslizarse por una irremisible cuesta abajo que le llev\u00f3 a entrar una espiral descendente de juergas, alcohol, vida nocturna, peleas y jaleos varios. Como tantos otros. Un \u00bfbuen? d\u00eda se encontr\u00f3 con el Rulas, uno de esos empresarios de la construcci\u00f3n con la cara m\u00e1s dura que el cemento armado, casado con una mujer de armas tomar y tanto talento para los negocios como mala mano con la familia. Y Juli\u00e1n se convirti\u00f3 en su guardaespaldas, asistente y hombre para todo. Un resuelveproblemas.<\/p>\n<p>\u201cAlgunos nacen con estrella y otros estrellados. Lo peor de nacer estrellado es que cuando te quieres dar cuenta, la cosa ya no tiene remedio\u201d. <\/p>\n<p><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5201303644776408114\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/SC6-G3PXpDI\/AAAAAAAAB1M\/grqmnz8Wm9Y\/s400\/_016.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">As\u00ed comienza \u201cStopper\u201d, publicada por la <a href=\"http:\/\/www.editorialberenice.com\/\"><span style=\"color:#ff0000;\"><strong>editorial Berenice<\/strong><\/span><\/a>, en la que el escritor alicantino Gast\u00f3n Segura cuenta la historia de Juli\u00e1n, un hombre sin suerte. Y lo hace a trav\u00e9s de una narraci\u00f3n muy especial: es la conciencia de Juli\u00e1n la que, en una narraci\u00f3n continuada de apenas 140 p\u00e1ginas, sin cap\u00edtulos y sin apenas di\u00e1logos, le habla directamente a su due\u00f1o, apelando a sus recuerdos y a su memoria.<\/p>\n<p>A trav\u00e9s de un recurso narrativo tan singular, el autor hace que el protagonista se enfrente a sus fantasmas, lo que sirve para que el lector conozca los entresijos de las modernas mafias, las costumbres de los chavales bakaladeros y, tambi\u00e9n, lo que pasa en los vestuarios de los clubes de f\u00fatbol, de puertas para adentro. C\u00f3mo se hace para echar a un entrenador o a un jugador que no es del agrado de los pesos pesados del equipo o c\u00f3mo se putea a un compa\u00f1ero, tan s\u00f3lo porque parece un tanto amanerado y quiz\u00e1 sea maric\u00f3n, hasta conseguir que se retire del f\u00fatbol. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5201303644776408146\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp2.blogger.com\/_r6VY1mvj3jk\/SC6-G3PXpFI\/AAAAAAAAB1c\/tohCc6_yZes\/s400\/_018.jpg\" border=\"0\" \/> <\/p>\n<p align=\"justify\">Y todo este repaso a su vida lo hace Juli\u00e1n cuando est\u00e1 a punto de enfrentarse a una situaci\u00f3n de la que, posiblemente, no saldr\u00e1 con bien: ha de liberar al marido de su amante, que est\u00e1 secuestrado por unos narcotraficantes colombianos. Y mientras su conciencia le pide que no lo haga, record\u00e1ndole la cantidad de malas decisiones que ha tomado en su vida, Juli\u00e1n se prepara para entrar en acci\u00f3n, una vez m\u00e1s&#8230;<\/p>\n<p>Una novela muy sugerente en la que lo negro y lo deportivo se dan la mano, dejando patente que, en todos los \u00f3rdenes de la vida, la suerte es tanto o m\u00e1s importante que la formaci\u00f3n y el trabajo duro, no en vano, la cualidad que m\u00e1s apreciaba Napole\u00f3n en sus oficiales, la que le llevaba a promocionarles hasta lo m\u00e1s alto del escalaf\u00f3n era, precisamente, que estuvieran tocados por la baraka y los hados de la Diosa Fortuna&#8230; Porque unos nacen con estrella y otros, estrellados.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<p align=\"justify\">Etiquetas: <a href=\"http:\/\/bitacoras.com\/canales\/futbol\" rel=\"tag\">futbol<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/rubiales\" rel=\"tag\">rubiales<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/stopper\" rel=\"tag\">stopper<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/gaston+segura\" rel=\"tag\">gaston segura<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/berenice\" rel=\"tag\">berenice<\/a>, <a href=\"http:\/\/bitacoras.com\/canales\/florens\" rel=\"tag\">florens<\/a><\/p>\n<p align=\"justify\">\n<\/td>\n<\/tr>\n<tr unselectable=\"on\" hb_tag=\"1\">\n<td style=\"FONT-SIZE: 1pt\" height=\"1\" unselectable=\"on\"><\/p>\n<div id=\"hotbar_promo\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>Dedicado a Luis Rubiales, capit\u00e1n del Levante.Si hubiera m\u00e1s jugadores como \u00e9l,Pasar\u00edan menos cosas como las que se cuentan en este libro. En otras entregas del Proyecto Florens nos hemos fijado en lo importante que es asumir bien los cambios de ciclo vitales (ejemplo de Gasol) e, incluso, determinar cu\u00e1ndo es la hora de retirarse [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[13,9,21],"tags":[],"class_list":["post-235","post","type-post","status-publish","format-standard","hentry","category-deporte-vida-empresa","category-literarios","category-negra-y-criminal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=235"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/235\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}