{"id":23375,"date":"2017-10-12T13:44:22","date_gmt":"2017-10-12T12:44:22","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23375"},"modified":"2017-10-12T13:44:22","modified_gmt":"2017-10-12T12:44:22","slug":"la-hora-del-federalismo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-hora-del-federalismo\/","title":{"rendered":"La hora del federalismo"},"content":{"rendered":"<p>La ma\u00f1ana de ayer volvi\u00f3 a ser vertiginosa, informativamente hablando, y tras la comparecencia de Rajoy para se\u00f1alar lo que ustedes saben que se\u00f1al\u00f3, le toc\u00f3 el turno a Pedro S\u00e1nchez. Y su anuncio tambi\u00e9n tuvo miga: apoyaba al presidente del Gobierno en las decisiones que tomara con respecto a la declaraci\u00f3n de Puigdemont y Catalu\u00f1a, pero sobre todo, avanzaba un acuerdo con Rajoy para reformar la Constituci\u00f3n.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-hora-del-federalismo\/grupo-consejo-constitucional-640x363\/\" rel=\"attachment wp-att-23376\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23376\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Grupo-Consejo-Constitucional-640x363-300x170.jpg\" alt=\"\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Grupo-Consejo-Constitucional-640x363-300x170.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Grupo-Consejo-Constitucional-640x363.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Una reforma que, de acuerdo con el calendario previsto, va a ser r\u00e1pida, teniendo en cuenta la trascendencia del tema en cuesti\u00f3n. Y ah\u00ed es donde entran dos de las personas de nuestro entorno que m\u00e1s tienen que decir sobre el asunto: Gregorio C\u00e1mara y Jos\u00e9 Antonio Montilla, catedr\u00e1ticos de Derecho Constitucional de la UGR y federalistas convencidos.<\/p>\n<p>&nbsp;<\/p>\n<p>Gregorio C\u00e1mara es diputado en el Congreso, inteligente decisi\u00f3n del PSOE a la hora de conformar las listas electorales de las \u00faltimas elecciones. Jos\u00e9 Antonio Montilla, por su parte, es el presidente de la asociaci\u00f3n Federalistas de Andaluc\u00eda, cuyo objetivo es difundir por nuestra comunidad el federalismo como modelo para una m\u00e1s adecuada organizaci\u00f3n territorial del Estado, as\u00ed como impulsar una reforma de la Constituci\u00f3n espa\u00f1ola de 1978 en sentido federal.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-hora-del-federalismo\/gregorio-2\/\" rel=\"attachment wp-att-23377\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23377\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Gregorio-2-300x189.jpg\" alt=\"\" width=\"300\" height=\"189\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Gregorio-2-300x189.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Gregorio-2.jpg 570w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es incre\u00edble c\u00f3mo, en muy poco tiempo, el blanco pasa a ser negro y el negro se convierte en blanco. Hasta hace unas semanas, cualquier modificaci\u00f3n de la Constituci\u00f3n era un anatema para amplios sectores de militantes y simpatizantes del PP y Ciudadanos y el uso de un t\u00e9rmino como \u201cFederalismo\u201d provocaba en las conversaciones silencios inc\u00f3modos, muecas de desprecio\u2026 o hasta un escupitajo en un ojo, metaf\u00f3ricamente hablando.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfSobre qu\u00e9 bases se va a plantear la negociaci\u00f3n para la reforma de la Constituci\u00f3n? De momento, no ha trascendido: solo hemos sabido que se activar\u00e1 inmediatamente la comisi\u00f3n para la evaluaci\u00f3n del Estado auton\u00f3mico que ya est\u00e1 registrada en el Parlamento, con una duraci\u00f3n de seis meses. A su conclusi\u00f3n, se abrir\u00e1 el debate de la reforma constitucional en el Congreso.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/la-hora-del-federalismo\/attachment\/000000317065\/\" rel=\"attachment wp-att-23378\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23378\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/000000317065-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/000000317065-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/000000317065-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/000000317065-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/000000317065.jpg 1000w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Los pr\u00f3ximos meses van a ser pr\u00f3digos en debates jur\u00eddicos, fiscales, econ\u00f3micos, territoriales, auton\u00f3micos y constitucionales; por lo que conviene recordar la conocida como Declaraci\u00f3n de Granada, aprobada por el PSOE en julio de 2013. M\u00e1s que nada porque los socialistas son los \u00fanicos que se han tomado en serio esto de reformar la Constituci\u00f3n, con sentido de Estado, en los \u00faltimos tiempos.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23308 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23308 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/09\/1-Twitter-Lens-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La ma\u00f1ana de ayer volvi\u00f3 a ser vertiginosa, informativamente hablando, y tras la comparecencia de Rajoy para se\u00f1alar lo que ustedes saben que se\u00f1al\u00f3, le toc\u00f3 el turno a Pedro S\u00e1nchez. Y su anuncio tambi\u00e9n tuvo miga: apoyaba al presidente del Gobierno en las decisiones que tomara con respecto a la declaraci\u00f3n de Puigdemont y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15214,15213,15212,15215,15216],"class_list":["post-23375","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-gregorio-camara","tag-jose-antonio-montilla","tag-la-hora-del-federalismo","tag-proceso-constituyente","tag-reforma-constitucion-espanola"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23375","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23375"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23375\/revisions"}],"predecessor-version":[{"id":23381,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23375\/revisions\/23381"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23375"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23375"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23375"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}