{"id":23333,"date":"2017-10-04T19:21:39","date_gmt":"2017-10-04T18:21:39","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23333"},"modified":"2017-10-04T19:21:39","modified_gmt":"2017-10-04T18:21:39","slug":"piensa-en-negro","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/piensa-en-negro\/","title":{"rendered":"Piensa en negro"},"content":{"rendered":"<p>Piensa en negro y acertar\u00e1s. Think\u2019Noir. Si\u00e9ntelo. V\u00edvelo. Disfr\u00fatalo. Desde el pasado jueves he pasado en mi casa el tiempo justo para ducharme, cambiarme de ropa, dormir un escaso pu\u00f1ado de horas y salir zumbando. Se me ha enmohecido la comida en el frigor\u00edfico y la adrenalina no deja de fluir por mi cuerpo, las 24 horas del d\u00eda. \u00bfSaben ustedes el gustazo, el subid\u00f3n que es eso?<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/piensa-en-negro\/cartel-granada-noir-3\/\" rel=\"attachment wp-att-23334\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23334\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Cartel-Granada-Noir-214x300.jpg\" alt=\"\" width=\"214\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Cartel-Granada-Noir-214x300.jpg 214w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Cartel-Granada-Noir-768x1079.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Cartel-Granada-Noir-644x905.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Cartel-Granada-Noir.jpg 860w\" sizes=\"auto, (max-width: 214px) 100vw, 214px\" \/><\/a><\/p>\n<p>Estos d\u00edas estamos disfrutando de la presencia en nuestra ciudad de una pl\u00e9yade de creadores que nos est\u00e1n inyectando vitalidad y creatividad, a raudales y en vena. \u00bfQu\u00e9 voy a decir yo, si soy el director de Granada Noir, la locura que puse en marcha hace tres a\u00f1os, de la mano del imprescindible Gustavo G\u00f3mez y sin cuya agencia, Acento Comunicaci\u00f3n, todo esto ser\u00eda imposible?<\/p>\n<p>&nbsp;<\/p>\n<p>No puedo ser objetivo, pero lo veo en la cara de la gente, lo escucho en los corrillos que se forman al terminar los actos, en la expresi\u00f3n de las personas que nos acompa\u00f1an en los Encuentros Cerveza Alhambra Especial, tomando una birra y disfrutando de una rica tapa.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/desolacion-y-rabia\/desolacion\/\" rel=\"attachment wp-att-23327\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23327\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Desolaci\u00f3n-300x167.jpg\" alt=\"\" width=\"300\" height=\"167\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Desolaci\u00f3n-300x167.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Desolaci\u00f3n-768x428.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Desolaci\u00f3n-644x359.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/10\/Desolaci\u00f3n.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Las acaloradas discusiones sobre qu\u00e9 es ser una hero\u00edna hoy y sobre si debe haber mesas literarias con presencia exclusivamente femenina, el disfrute de contemplaci\u00f3n de las ilustraciones del proyecto Hnegra, los cientos de personas que se arremolinaron en torno a la Potato Head Jazz Band en Puerta Real; la emoci\u00f3n de conocer la dram\u00e1tica historia de la Alhambra subterr\u00e1nea, negra y dram\u00e1tica, que convierte a \u201cJuego de tronos\u201d en juego de ni\u00f1os\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>En Granada Noir hemos interrogado, hasta el ensa\u00f1amiento, a uno de los m\u00e1s grandes artistas granadinos de la historia: Juanjo Guarnido, al que damos la enhorabuena por su ingreso en la Academia de Bellas Artes. Hemos sido testigos del encuentro, \u00a1por fin!, entre Federico Garc\u00eda Lorca y Agust\u00edn Pen\u00f3n, gracias al magisterio y a la imaginaci\u00f3n de Enrique Bonet, Juanfran Cabrera, Fernando Mar\u00edas y un Alejandro Pedregosa que, un lunes por la noche, nos deleit\u00f3 con un sentido recital de poes\u00eda sangrante en la que refulge el acero de las navajas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/que-es-ser-una-heroina-hoy\/hnegra6\/\" rel=\"attachment wp-att-23296\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23296\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/09\/Hnegra6-231x300.jpg\" alt=\"\" width=\"231\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/09\/Hnegra6-231x300.jpg 231w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/09\/Hnegra6.jpg 545w\" sizes=\"auto, (max-width: 231px) 100vw, 231px\" \/><\/a><\/p>\n<p>Todav\u00eda nos queda m\u00e1s de la mitad de Granada Noir: pel\u00edculas por ver, cineastas a los que conocer, escritores a los que escuchar, investigadores de los que aprender, libros por compra, m\u00fasica con la que bailar\u2026 \u00bfNos acompa\u00f1an? Porque el aut\u00e9ntico crimen ser\u00eda perd\u00e9rselo\u2026<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-23308 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-23308 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/09\/1-Twitter-Lens-1.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Piensa en negro y acertar\u00e1s. Think\u2019Noir. Si\u00e9ntelo. V\u00edvelo. Disfr\u00fatalo. Desde el pasado jueves he pasado en mi casa el tiempo justo para ducharme, cambiarme de ropa, dormir un escaso pu\u00f1ado de horas y salir zumbando. Se me ha enmohecido la comida en el frigor\u00edfico y la adrenalina no deja de fluir por mi cuerpo, las [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,6],"tags":[11145,15189],"class_list":["post-23333","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-opinion","tag-granada-noir-2","tag-piensa-en-negro"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23333","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23333"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23333\/revisions"}],"predecessor-version":[{"id":23336,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23333\/revisions\/23336"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23333"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23333"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23333"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}