{"id":23089,"date":"2017-08-20T07:20:04","date_gmt":"2017-08-20T06:20:04","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23089"},"modified":"2017-08-18T12:21:36","modified_gmt":"2017-08-18T11:21:36","slug":"des","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/des\/","title":{"rendered":"Des&#8230;"},"content":{"rendered":"<p>D\u00edas de desconexi\u00f3n, desaceleraci\u00f3n, desaparici\u00f3n. Ten\u00eda escrita esta columna desde hace un par de d\u00edas. De hecho, era la que estaba previsto que saliera el pasado viernes. Los acontecimientos de Barcelona la convirtieron, de pronto, en algo fr\u00edvolo, absurdo, casi surrealista.<\/p>\n<p>&nbsp;<\/p>\n<p>\u00bfC\u00f3mo hablar de vacaciones, del cansancio de este plomizo mes de agosto, de lo largo que se est\u00e1 haciendo un verano que empez\u00f3 a fre\u00edrnos y a achicharrarnos a comienzos de mes de junio, y que lleva acumuladas tantas alertas amarillas y naranjas que parece una cesta de c\u00edtricos?<\/p>\n<p>&nbsp;<\/p>\n<p>Jugando con las palabras, les dec\u00eda que no me lo tomaran a mal, pero que iba a tratar de estar muy a gusto el resto de agosto y que, para ello, me evadir\u00eda de todas las responsabilidades posibles. Por ejemplo, la de esta columna. No porque me pese o me canse, sino para relajar a las neuronas, sin forzarlas a buscar tema cada d\u00eda, a plantearse el tono y la forma del art\u00edculo, etc\u00e9tera.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuando ocurre una atrocidad como la de Barcelona, cada persona reacciona de forma distinta. Quienes llevamos el veneno de la literatura en las venas, necesitamos exorcizar nuestros demonios, descomprimir y expulsar el miedo, el asco y la rabia a trav\u00e9s de la escritura.<\/p>\n<p>&nbsp;<\/p>\n<p>Escribir una columna diaria es tanto una gozada, cr\u00e9anme, como una responsabilidad. Publicar todos los d\u00edas en IDEAL, adem\u00e1s de ser un privilegio, es un desaf\u00edo constante a la creatividad que me obliga a estar atento a la realidad, a leer mucho, a hablar m\u00e1s, a preguntar, buscar, estudiar, recordar, consultar, investigar\u2026 Que rellenar de palabras con sentido esta cajetilla, todos los d\u00edas, no es f\u00e1cil.<\/p>\n<p>&nbsp;<\/p>\n<p>Dado que, como ya les cont\u00e9, este a\u00f1o no puedo viajar, hab\u00eda pensado marcarme un Cifuentes y seguir escribiendo esta columna todo el verano, que no hay nada m\u00e1s retador y apasionante. La luctuosa y tr\u00e1gica actualidad, adem\u00e1s, as\u00ed parece exigirlo.<\/p>\n<p>&nbsp;<\/p>\n<p>Sin embargo, a agosto a\u00fan le quedan dos semanas largas y la mente me pide relajo y abandono; descanso y desconexi\u00f3n, entregarse a la molicie y rendirse al tiempo espont\u00e1neo: hacer lo que le d\u00e9 la gana seg\u00fan el momento, sin compromisos ni obligaciones.<\/p>\n<p>&nbsp;<\/p>\n<p>D\u00edas para seguir la actualidad de cerca, pero tambi\u00e9n para mantenerme un poco alejado de todo y para leer mucho, tratando de encontrar respuestas a los desaf\u00edos del futuro inmediato. Nos reecontramos en septiembre. \u00a1Cu\u00eddense!<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-22754 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22754 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>D\u00edas de desconexi\u00f3n, desaceleraci\u00f3n, desaparici\u00f3n. Ten\u00eda escrita esta columna desde hace un par de d\u00edas. De hecho, era la que estaba previsto que saliera el pasado viernes. Los acontecimientos de Barcelona la convirtieron, de pronto, en algo fr\u00edvolo, absurdo, casi surrealista. &nbsp; \u00bfC\u00f3mo hablar de vacaciones, del cansancio de este plomizo mes de agosto, de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15036,9039,15037],"class_list":["post-23089","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-des","tag-desconexion","tag-lens-vacaciones"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23089","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23089"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23089\/revisions"}],"predecessor-version":[{"id":23090,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23089\/revisions\/23090"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23089"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23089"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23089"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}