{"id":23082,"date":"2017-08-18T07:49:10","date_gmt":"2017-08-18T06:49:10","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=23082"},"modified":"2017-08-18T07:49:10","modified_gmt":"2017-08-18T06:49:10","slug":"con-barcelona","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/con-barcelona\/","title":{"rendered":"Con Barcelona"},"content":{"rendered":"<p>Me asomo a las \u00faltimas informaciones sobre el atentado de Barcelona, antes de escribir estas notas, y me invade la n\u00e1usea al leer que ya van trece personas muertas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/con-barcelona\/con-barcelona\/\" rel=\"attachment wp-att-23083\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-23083\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Con-Barcelona-300x153.jpg\" alt=\"\" width=\"300\" height=\"153\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Con-Barcelona-300x153.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Con-Barcelona-768x392.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Con-Barcelona-644x329.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Con-Barcelona.jpg 1632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Pienso en los muchos amigos que tengo en Barcelona y suplico que no haya ninguno afectado. Pienso en las v\u00edctimas, en sus familias, en el terrible dolor provocado por esta animalada.<\/p>\n<p>&nbsp;<\/p>\n<p>Leo que se busca una furgoneta blanca, que los terroristas est\u00e1n atrincherados en una tienda o, quiz\u00e1, en un restaurante turco.<\/p>\n<p>&nbsp;<\/p>\n<p>Y las preguntas. \u00bfC\u00f3mo es posible? \u00bfPor qu\u00e9 ha ocurrido algo as\u00ed? \u00bfQui\u00e9n es capaz de una atrocidad de este calibre? \u00bfQu\u00e9 quieren? \u00bfQu\u00e9 buscan?<\/p>\n<p>&nbsp;<\/p>\n<p>A lo largo de los \u00faltimos a\u00f1os se vienen repitiendo este tipo de atentados con una descorazonadora frecuencia. Y lo que m\u00e1s miedo da es que resultan imprevisibles: un desequilibrado, un coche o una furgoneta y se desata el Apocalipsis.<\/p>\n<figure id=\"attachment_23084\" aria-describedby=\"caption-attachment-23084\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/con-barcelona\/barcelona-frederic-amat\/\" rel=\"attachment wp-att-23084\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-23084\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Barcelona-Frederic-Amat-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Barcelona-Frederic-Amat-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Barcelona-Frederic-Amat-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Barcelona-Frederic-Amat-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Barcelona-Frederic-Amat.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-23084\" class=\"wp-caption-text\">Frederic Amat<\/figcaption><\/figure>\n<p>Sin bombas, sin explosivos, sin armas. Lo de Charlottesville de hace unos d\u00edas es buena prueba de que cualquier enfermo, al volante de un coche, se puede convertir en un arma letal.<\/p>\n<p>&nbsp;<\/p>\n<p>Cuando ocurren barbaridades como \u00e9sta, la vida queda en suspenso. Es dif\u00edcil encontrar las palabras y todas las cosas en las que basamos nuestro d\u00eda a d\u00eda cotidiano dejan de tener sentido.<\/p>\n<p>&nbsp;<\/p>\n<p>Y sin embargo, hay que seguir adelante con nuestra vida. Es la \u00fanica manera posible de desarmar el terrorismo. De combatirlo de ra\u00edz. De vencerlo. Seguir adelante. Seguir creyendo en la democracia y en el Estado de Derecho. Seguir defendiendo nuestras libertades y nuestros derechos. No pensar en tomar atajos.<\/p>\n<p>&nbsp;<\/p>\n<p>Las v\u00edsceras, las tripas piden venganza. En estos momentos de dolor, duelo e indignaci\u00f3n, es f\u00e1cil dejarse llevar por la ira.<\/p>\n<p>&nbsp;<\/p>\n<p>Resulta esencial apelar a la sensatez, a la calma y a la frialdad de todos los poderes p\u00fablicos. Es necesario un frente unido, s\u00f3lido y cerrado en torno al gobierno. Que no se utilice de forma partidista una atrocidad como la de Barcelona.<\/p>\n<p>&nbsp;<\/p>\n<p>Que el atentado de ayer sirva para hacernos m\u00e1s fuertes como ciudadanos y como sociedad. \u00c9se ser\u00eda el mayor fracaso de los terroristas.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-22754 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22754 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me asomo a las \u00faltimas informaciones sobre el atentado de Barcelona, antes de escribir estas notas, y me invade la n\u00e1usea al leer que ya van trece personas muertas. Pienso en los muchos amigos que tengo en Barcelona y suplico que no haya ninguno afectado. Pienso en las v\u00edctimas, en sus familias, en el terrible [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[15032,881,15034,15033],"class_list":["post-23082","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-atentados-barcelona","tag-barcelona","tag-barcelona-vive","tag-con-barcelona"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23082","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=23082"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23082\/revisions"}],"predecessor-version":[{"id":23086,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/23082\/revisions\/23086"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=23082"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=23082"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=23082"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}