{"id":22983,"date":"2017-08-09T09:23:00","date_gmt":"2017-08-09T08:23:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22983"},"modified":"2017-08-09T09:23:00","modified_gmt":"2017-08-09T08:23:00","slug":"violencia-contra-la-mujer-2","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/violencia-contra-la-mujer-2\/","title":{"rendered":"Violencia contra la mujer"},"content":{"rendered":"<p>Voy a terminar mi largo an\u00e1lisis del Bar\u00f3metro del mes de julio del CIS con un dato que me parece tan ilustrativo como preocupante y aterrador: a la pregunta sobre cu\u00e1l es el principal problema que existe actualmente en Espa\u00f1a, solo un 1,4% de los encuestados respondieron \u201cLa violencia contra la mujer\u201d en una de sus tres respuestas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/violencia-contra-la-mujer-2\/violencia-contra-la-mujer-verbal\/\" rel=\"attachment wp-att-22984\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22984\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-verbal-300x225.jpg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-verbal-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-verbal-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-verbal-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-verbal.jpg 1440w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Entiendo que el paro, los problemas econ\u00f3micos y la corrupci\u00f3n son preocupaciones mayoritariamente extendidas en nuestra sociedad, pero \u00bfhabr\u00eda estado la cuesti\u00f3n de la violencia contra la mujer entre las cinco inquietudes de una mayor\u00eda de encuestados? \u00bfY entre las diez primeras? Y si las respuestas se hubieran segregado por g\u00e9nero, \u00bfqu\u00e9 habr\u00edamos respondido los hombres?<\/p>\n<p>&nbsp;<\/p>\n<p>Un dato, espeluznante: treinta y una mujeres asesinadas en Espa\u00f1a en lo que va de a\u00f1o. 31. M\u00e1s cifras: de ellas, solo seis hab\u00edan denunciado anteriormente a su agresor y, sin embargo, diecinueve conviv\u00edan con su verdugo.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/violencia-contra-la-mujer-2\/violencia-contra-la-mujer-huescar\/\" rel=\"attachment wp-att-22985\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22985\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-Hu\u00e9scar-285x300.jpg\" alt=\"\" width=\"285\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-Hu\u00e9scar-285x300.jpg 285w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-Hu\u00e9scar.jpg 617w\" sizes=\"auto, (max-width: 285px) 100vw, 285px\" \/><\/a><\/p>\n<p>Estas cifras demuestran que tenemos un problema, grav\u00edsimo, y que los protocolos no funcionan. Que las mujeres siguen sin denunciar y que no encuentran soporte ni ayuda en las instituciones para romper la cadena del maltrato. Porque el asesinato, nunca lo olvidemos, es el \u00faltimo estadio de la violencia contra la mujer.<\/p>\n<p>&nbsp;<\/p>\n<p>Falla la prevenci\u00f3n, falla la educaci\u00f3n y falla la protecci\u00f3n. Por eso, cada vez que leo o escucho a hombres -y, en ocasiones, a algunas mujeres- hablar de feminazis, de la violencia de las mujeres contra los hombres o de las denuncias falsas por violencia de g\u00e9nero en temas de separaci\u00f3n y divorcio; me pongo malo, se me revuelven las tripas y me dan ganas de vomitar.<\/p>\n<p>&nbsp;<\/p>\n<p>31 mujeres asesinadas. No muertas, no: A-SE-SI-NA-DAS. 31 mujeres asesinadas a manos de hombres. Duele hablar de mujeres asesinadas, pero es una expresi\u00f3n lamentablemente ajustada a la realidad, no como eso de \u201cv\u00edctimas de la violencia de g\u00e9nero\u201d, en abstracto, con ese lenguaje fr\u00edo, neutro y funcionarial que cosifica a las personas.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/violencia-contra-la-mujer-2\/violencia-contra-la-mujer-no\/\" rel=\"attachment wp-att-22986\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22986\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-NO-300x157.jpg\" alt=\"\" width=\"300\" height=\"157\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-NO-300x157.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-NO-768x403.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-NO-644x338.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/08\/Violencia-contra-la-mujer-NO.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>En la cuesti\u00f3n de la violencia contra la mujer no valen simetr\u00edas ni resulta admisible lo pol\u00edticamente correcto: hablamos de una lacra execrable que deber\u00eda avergonzarnos y que exige, a voces, un Pacto de Estado que dote de fondos y de medios a una pol\u00edtica dirigida a revertir esta intolerable situaci\u00f3n. Cada d\u00eda que pasa sin afrontar una cuesti\u00f3n de alarma social, fracasamos un poco m\u00e1s como sociedad.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-22754 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22754 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voy a terminar mi largo an\u00e1lisis del Bar\u00f3metro del mes de julio del CIS con un dato que me parece tan ilustrativo como preocupante y aterrador: a la pregunta sobre cu\u00e1l es el principal problema que existe actualmente en Espa\u00f1a, solo un 1,4% de los encuestados respondieron \u201cLa violencia contra la mujer\u201d en una de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14971,14970,14972,4771],"class_list":["post-22983","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-mujeres-asesinadas-espana","tag-no-mas-violencia-contra-la-mujer","tag-pacto-estado-violencia-contra-la-mujer","tag-violencia-contra-la-mujer"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22983","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22983"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22983\/revisions"}],"predecessor-version":[{"id":22988,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22983\/revisions\/22988"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22983"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22983"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22983"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}