{"id":22856,"date":"2017-07-23T16:57:52","date_gmt":"2017-07-23T15:57:52","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22856"},"modified":"2017-07-23T16:57:52","modified_gmt":"2017-07-23T15:57:52","slug":"parguelas-volantes","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/parguelas-volantes\/","title":{"rendered":"Parguelas volantes"},"content":{"rendered":"<p>Me gustan los diccionarios de sin\u00f3nimos alternativos. Como el que se\u00f1ala que un parguela tambi\u00e9n es un tolai, un pimpinela, un huev\u00f3n y un pichurria. Un pagafantas y un <i>tontolhaba<\/i>, en dos palabras.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/parguelas-volantes\/attachment\/20007307\/\" rel=\"attachment wp-att-22857\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22857\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/20007307-300x300.jpg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/20007307-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/20007307-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/20007307.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Me declaro ser todo eso y m\u00e1s porque yo fui uno de los que estuvieron a punto de ser convencidos de que deber\u00edamos dar por perdido el aeropuerto de Granada y convertir al de M\u00e1laga en la v\u00eda de acceso al turismo <i>a\u00e9reo<\/i> a Andaluc\u00eda.<\/p>\n<p>Y es que, efectivamente, hubo un momento en que, cuanto m\u00e1s largo era el nombre del Aeropuerto Federico Garc\u00eda Lorca de Granada y Ja\u00e9n, menos aviones aterrizaban en sus pistas, pareci\u00e9ndose m\u00e1s a los aer\u00f3dromos fantasma de Ciudad Real o Castell\u00f3n que al flamante Pablo Ruiz Picasso de M\u00e1laga que, para m\u00e1s inri, estrenaba una flamante tercera terminal.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/parguelas-volantes\/a88ae633d15d2ac5815a78e7acee6d4f\/\" rel=\"attachment wp-att-22858\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22858\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/a88ae633d15d2ac5815a78e7acee6d4f-300x225.jpeg\" alt=\"\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/a88ae633d15d2ac5815a78e7acee6d4f-300x225.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/a88ae633d15d2ac5815a78e7acee6d4f-768x577.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/a88ae633d15d2ac5815a78e7acee6d4f-644x484.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/a88ae633d15d2ac5815a78e7acee6d4f.jpeg 980w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Llegados a ese punto, se gener\u00f3 una corriente de opini\u00f3n que defend\u00eda que la puerta natural de entrada del turismo internacional a Andaluc\u00eda pasaba por M\u00e1laga y que, a partir de ah\u00ed, el resto de provincias deber\u00edamos ingeni\u00e1rnoslas para conseguir atraerlos a nuestras ciudades y pueblos.<\/p>\n<p>De la misma manera, y una vez eliminado el ferrocarril de nuestra vida, los granadinos empezamos a hacernos el cuerpo de que la \u00fanica manera de salir de la provincia era por carretera, fuera con destino a Madrid, a Levante\u2026o con destino a M\u00e1laga y a su aeropuerto. Les confieso que yo, en los \u00faltimo a\u00f1os, cada vez que he tenido que volar, no me he molestado ni en consultar las posibilidades que brindaba el Federico Garc\u00eda Lorca.<\/p>\n<p>Menos mal que ha habido en Granada personas menos parguelas que yo con esto del aeropuerto y que, en vez de rendirse, se han empe\u00f1ado en darle vida y en conseguir m\u00e1s y m\u00e1s conexiones, tanto con otras ciudades de Espa\u00f1a como del extranjero. A los habituales vuelos con Madrid y Barcelona hay que ir sumando Mil\u00e1n, Manchester, Londres, Par\u00eds, Bilbao, Santa Cruz de Tenerife o Las Palmas de Gran Canaria.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/parguelas-volantes\/easyjet_xoptimizadax-u10104477540862h-u211895904247t7d-575x323ideal-ideal\/\" rel=\"attachment wp-att-22859\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22859\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/easyjet_xoptimizadax-U10104477540862H-U211895904247T7D-575x323@Ideal-Ideal-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/easyjet_xoptimizadax-U10104477540862H-U211895904247T7D-575x323@Ideal-Ideal-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/easyjet_xoptimizadax-U10104477540862H-U211895904247T7D-575x323@Ideal-Ideal.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Enhorabuena a las instituciones y a las personas que se empe\u00f1aron en ir contra la inercia, el conformismo y el abandono. Una enhorabuena que quiero personificar en Marta Torres, la directora del aeropuerto, y en su equipo.<\/p>\n<p>No seamos parguelas: mucha gente quiere visitar Granada y, pon\u00e9rselo f\u00e1cil y permitirles que vengan de forma directa, resulta ser un buen negocio.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-22754 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-22754 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Me gustan los diccionarios de sin\u00f3nimos alternativos. Como el que se\u00f1ala que un parguela tambi\u00e9n es un tolai, un pimpinela, un huev\u00f3n y un pichurria. Un pagafantas y un tontolhaba, en dos palabras. Me declaro ser todo eso y m\u00e1s porque yo fui uno de los que estuvieron a punto de ser convencidos de que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12016,14880,14881,12018,12017,14882,14883],"class_list":["post-22856","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-aeropuerto-granada","tag-parguela","tag-parguelas","tag-viajar-a-granada","tag-vuelos-a-granada","tag-vuelos-desde-granada","tag-vuelos-directos-granada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22856","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22856"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22856\/revisions"}],"predecessor-version":[{"id":22861,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22856\/revisions\/22861"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22856"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22856"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22856"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}