{"id":22702,"date":"2017-07-03T08:51:13","date_gmt":"2017-07-03T07:51:13","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22702"},"modified":"2017-07-03T08:51:13","modified_gmt":"2017-07-03T07:51:13","slug":"eres-lo-que-compartes","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/eres-lo-que-compartes\/","title":{"rendered":"Eres lo que compartes"},"content":{"rendered":"<p>Andrea, Lucas y Fernando estaban de visita en Granada. Pasaron el d\u00eda recorriendo algunos de los lugares m\u00e1s reconocibles de la capital nazar\u00ed y, para cenar, se hab\u00edan sentado en una terraza de la plaza de La Romanilla.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014Espero que no tarden mucho en traer la cena. Estoy muerto\u2014dijo Lucas.<\/p>\n<p>\u2014Y yo. Hecha polvo\u2014convino Andrea.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/eres-lo-que-compartes\/eres-lo-que-compartes-plaza-romanilla\/\" rel=\"attachment wp-att-22703\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22703\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-Plaza-Romanilla-300x135.jpg\" alt=\"\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-Plaza-Romanilla-300x135.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-Plaza-Romanilla-768x344.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-Plaza-Romanilla-644x289.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-Plaza-Romanilla.jpg 988w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Fernando era el que se mostraba m\u00e1s entero y animoso. A\u00fan as\u00ed, se alegr\u00f3 de que llegaran las tostas con aguacate y se dispon\u00eda a echarle mano a una cuando Lucas y Andrea exclamaron al un\u00edsono:<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014\u00a1Pero a d\u00f3nde vas, ansia viva! \u00bfNo puedes esperar a que hagamos la foto?<\/p>\n<p>&nbsp;<\/p>\n<p>La foto. La dichosa foto. Fernando, de fotos, estaba hasta lugares de su anatom\u00eda que no vamos a repetir. De fotos\u2026 y de selfis, filtros, instagrames, v\u00eddeos y megustas. De posados, robados y, sobre todo, de fingidos.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014Claro. Como eres un dinosaurio para la Red\u2026<\/p>\n<p>\u2014Ser\u00e1 eso. Pero el revuelto de morcilla con pi\u00f1ones se est\u00e1 enfriando.<\/p>\n<p>\u2014Un minuto: comparto la foto y lo pruebo.<\/p>\n<p>\u2014\u00bfPara qu\u00e9? Probarlo, quiero decir. Si ya habr\u00e1s publicado que est\u00e1 de muerte\u2026<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/eres-lo-que-compartes\/eres-lo-que-compartes-escalando\/\" rel=\"attachment wp-att-22704\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22704\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-escalando-300x211.jpg\" alt=\"\" width=\"300\" height=\"211\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-escalando-300x211.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-escalando.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Al d\u00eda siguiente, Lucas y Andrea no llegaron a la cena. Estaban tan cansados, p\u00e1lidos y ojerosos que, por la noche, no salieron del hotel. Eso s\u00ed: la Red les felicit\u00f3 por haber batido otro r\u00e9cord.<\/p>\n<p>&nbsp;<\/p>\n<p>\u2014As\u00ed aprovech\u00e1is para interactuar con vuestros contactos, \u00bfno?\u2014ironiz\u00f3 Fernando.<\/p>\n<p>&nbsp;<\/p>\n<p>Pero es que \u00e9l no lo entend\u00eda. La presi\u00f3n que supone la Red. \u201cEres lo que compartes\u201d, le\u00eda la popular Andrea en la pantalla de su tel\u00e9fono, sempiternamente operativo. \u201cQue sepan lo que se est\u00e1n perdiendo\u201d, era el mantra que su smartphone repet\u00eda a Lucas, a todas horas, muy consciente de su gen egoc\u00e9ntrico y competitivo.<\/p>\n<p>&nbsp;<\/p>\n<p>Y estaban las recompensas diarias que ofrec\u00eda la Red: medallas virtuales y menciones online, siempre que consegu\u00edan hitos como postear 25, 50 o 100 fotos o alcanzar un elevado n\u00famero de likes.<\/p>\n<p>&nbsp;<\/p>\n<p>\u201cT\u00fa energ\u00eda es nuestra fuerza\u201d. Pero Andrea ya no consigui\u00f3 salir del hotel, la\u00a0 tarde siguiente. \u201cContigo, somos m\u00e1s\u201d. Pero Lucas ni siquiera lleg\u00f3 al almuerzo: necesitaban del wifi de sus habitaciones para seguir operando.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/eres-lo-que-compartes\/eres-lo-que-compartes-depredador\/\" rel=\"attachment wp-att-22705\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22705\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-depredador-300x187.jpg\" alt=\"\" width=\"300\" height=\"187\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-depredador-300x187.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-depredador-768x478.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-depredador-644x401.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/07\/Eres-lo-que-compartes-depredador.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u201cYa somos dos mil millones\u201d, proclamaba la Red. Dos mil millones de usuarios en todo el mundo que, libremente, alimentaban la creciente e insaciable sed de c\u00edbersangre que demandaba la Red para nutrir a sus criaturas.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Andrea, Lucas y Fernando estaban de visita en Granada. Pasaron el d\u00eda recorriendo algunos de los lugares m\u00e1s reconocibles de la capital nazar\u00ed y, para cenar, se hab\u00edan sentado en una terraza de la plaza de La Romanilla. &nbsp; \u2014Espero que no tarden mucho en traer la cena. Estoy muerto\u2014dijo Lucas. \u2014Y yo. Hecha polvo\u2014convino [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6,31,13716],"tags":[14770],"class_list":["post-22702","post","type-post","status-publish","format-standard","hentry","category-opinion","category-relatos","category-soy","tag-eres-lo-que-compartes"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22702","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22702"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22702\/revisions"}],"predecessor-version":[{"id":22707,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22702\/revisions\/22707"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22702"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22702"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22702"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}