{"id":22251,"date":"2017-05-08T08:40:55","date_gmt":"2017-05-08T07:40:55","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22251"},"modified":"2017-05-08T09:11:58","modified_gmt":"2017-05-08T08:11:58","slug":"trabajargratis","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/trabajargratis\/","title":{"rendered":"Becas, pr\u00e1cticas y pasant\u00edas"},"content":{"rendered":"<p>Los que tenemos de cuarenta a\u00f1os hacia arriba podemos ser un co\u00f1azo manifiesto, analizando el aqu\u00ed y el ahora desde la perspectiva del pasado siglo. Que s\u00ed. Que est\u00e1 muy bien nuestra experiencia, pero que no podemos seguir anclados en los supuestos buenos viejos tiempos, en plan Abuelo Cebolletas. Por ejemplo, con el tema del trabajo gratis total.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/22251-2\/lens-ideal\/\" rel=\"attachment wp-att-22252\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22252\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Lens-IDEAL-300x138.jpg\" alt=\"\" width=\"300\" height=\"138\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Lens-IDEAL-300x138.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Lens-IDEAL-768x354.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Lens-IDEAL-644x297.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Lens-IDEAL.jpg 1632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Que s\u00ed. Que es cierto que buena parte de la gente de mi generaci\u00f3n -y de otras anteriores- hicimos becas, pasant\u00edas, meritorajes o pr\u00e1cticas poco o nada remuneradas. Pero es que la Espa\u00f1a de antes y la de ahora se parecen muy poco, laboralmente hablando.<\/p>\n<p>&nbsp;<\/p>\n<p>La cosa comenz\u00f3 a cambiar ya antes de la Crisis, en los a\u00f1os de la supuesta bonanza y del crecimiento econ\u00f3mico te\u00f3ricamente ilimitado, cuando los sectores de la construcci\u00f3n y el inmobiliario se convirtieron en man\u00e1 para miles de personas que, con poca o ninguna formaci\u00f3n, ve\u00edan posible ganar mucho y buen dinero. Una \u00e9poca en que ser mileurista era motivo de queja.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/22251-2\/becarios\/\" rel=\"attachment wp-att-22254\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22254\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Becarios-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Becarios-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Becarios.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Antes, sin embargo, la cosa era diferente. Al terminar el instituto, la FP o la universidad, hab\u00eda una especie de pacto t\u00e1cito: t\u00fa, incorp\u00f3rate al mercado laboral o profesional desde abajo, a trav\u00e9s de pr\u00e1cticas, becas o pasant\u00edas y, si te lo curras y le pones ganas, tes\u00f3n, ilusi\u00f3n y esfuerzo, ir\u00e1s hacia arriba. Poco a poco. Despu\u00e9s entraban m\u00faltiples factores en juego para conseguir llegar m\u00e1s o menos lejos. Pero, en general, la cosa funcionaba.<\/p>\n<p>&nbsp;<\/p>\n<p>Ahora, por desgracia, todo eso es historia. En 2017, con millones de parados, una precarizaci\u00f3n laboral absoluta y un mercado de trabajo obscenamente escorado al sector servicios, da lo mismo que seas mejor o peor, que le pongas m\u00e1s o menos ganas: siempre habr\u00e1 gente que har\u00e1 lo mismo que t\u00fa\u2026 por menos dinero.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/22251-2\/contratos\/\" rel=\"attachment wp-att-22253\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22253\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Contratos-300x209.jpg\" alt=\"\" width=\"300\" height=\"209\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Contratos-300x209.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Contratos.jpg 444w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por eso escandaliza tanto y resulta tan indigno lo del trabajo gratis -o a cambio de cama y comida- en restaurantes de superlujo que sirven men\u00fas de 100, 200 y 300 euros en adelante. Antes, en la Edad Viejuna, el meritoraje escasamente remunerado era una f\u00f3rmula para aprender y abrirnos camino que, adem\u00e1s, nos impulsaba en la escala socio-laboral. Sin embargo, en m\u00faltiples profesiones, esa escala ya no existe. Las pol\u00edticas neoliberales la han dinamitado. Y el trabajo gratis fomenta, por tanto, mano de obra barata de la que se abusa en un entorno de precarizaci\u00f3n laboral extremadamente peligroso.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-21978 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21978 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Los que tenemos de cuarenta a\u00f1os hacia arriba podemos ser un co\u00f1azo manifiesto, analizando el aqu\u00ed y el ahora desde la perspectiva del pasado siglo. Que s\u00ed. Que est\u00e1 muy bien nuestra experiencia, pero que no podemos seguir anclados en los supuestos buenos viejos tiempos, en plan Abuelo Cebolletas. Por ejemplo, con el tema del [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14458,14462,14461,14460,14459,14463,14457],"class_list":["post-22251","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-angel-leon-piso-patera","tag-becarios","tag-becas","tag-edad-viejuna","tag-estrellas-michelin-explotacion-laboral","tag-practicas-gratis","tag-trabajo-gratis-total"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22251","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22251"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22251\/revisions"}],"predecessor-version":[{"id":22258,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22251\/revisions\/22258"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22251"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22251"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22251"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}