{"id":22232,"date":"2017-05-04T11:33:46","date_gmt":"2017-05-04T10:33:46","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22232"},"modified":"2017-05-05T11:37:31","modified_gmt":"2017-05-05T10:37:31","slug":"gente-muy-ocupada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/gente-muy-ocupada\/","title":{"rendered":"Gente muy ocupada"},"content":{"rendered":"<p>A comienzos de semana tuve que telefonear a una persona por cuestiones de trabajo. Insisto en el \u201ctuve que\u201d y en que era por asuntos laborales. Nada que ver, pues, con el placer, el gusto, el esparcimiento o el divertimento. Y de ello hablo en IDEAL hoy.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/gente-muy-ocupada\/gente-ocupada\/\" rel=\"attachment wp-att-22233\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22233\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-Ocupada-300x131.jpg\" alt=\"\" width=\"300\" height=\"131\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-Ocupada-300x131.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-Ocupada-768x334.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-Ocupada-644x280.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-Ocupada.jpg 850w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>La persona en cuesti\u00f3n, antes siquiera de escucharme, empez\u00f3 por ponerme en antecedentes de lo muy liada y ocupada que est\u00e1 y del mucho trabajo que tiene. En ese momento, mi primera reacci\u00f3n fue colgar el tel\u00e9fono\u2026 y mandarla a hacer g\u00e1rgaras. O a plantar cebollinos. O a fre\u00edr esp\u00e1rragos, que ya sabemos que hay excedente de esta verdura en el Poniente granadino y que todos debemos comprarlos y consumirlos con fruici\u00f3n.<\/p>\n<p>&nbsp;<\/p>\n<p>En serio: \u00bfqu\u00e9 me aporta a m\u00ed esa informaci\u00f3n? \u00bfEn qu\u00e9 me afecta? \u00bfMe deber\u00eda importar un carajo? O, quiz\u00e1, al hacer \u00e9nfasis en esa enorme carga de trabajo que sobrelleva sobre sus hombros, esa persona me estaba mandando mensajes subliminales del tipo \u201c\u00a1Qu\u00e9 cantidad de trabajo tengo! (No como t\u00fa)\u201d o \u201cTengo mucho l\u00edo (y me est\u00e1s molestando con esta llamada)\u201d.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/gente-muy-ocupada\/gente-ocupada\/\" rel=\"attachment wp-att-22233\"><br \/>\n<\/a> <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/gente-muy-ocupada\/gente-ocupada-ay\/\" rel=\"attachment wp-att-22234\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22234\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-ocupada-ay-300x300.jpeg\" alt=\"\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-ocupada-ay-300x300.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-ocupada-ay-150x150.jpeg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-ocupada-ay.jpeg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>A m\u00ed, antes, me daba igual esa gente que no hace m\u00e1s que decir y proclamar a los cuatro vientos lo muy liada que est\u00e1. -Pues como yo\u2026 y como la mayor parte de la gente que conozco- sol\u00eda pensar, dando por zanjado el asunto. Ahora, ser\u00e1 la malafoll\u00e1 entreverada de viejunismo, esa gente me irrita profundamente. Porque las personas que no se hartan de proclamar su alto nivel de estr\u00e9s, agobio y l\u00edo mental, hacen de menos a los que, sencillamente, cumplimos con nuestro trabajo de la mejor manera posible.<\/p>\n<p>&nbsp;<\/p>\n<p>Pero es que, adem\u00e1s, tengo muy comprobado que la gente que va con el agobio por bandera suele ser, por lo general, de lo m\u00e1s ineficiente. E ineficaz. Por decirlo cort\u00e9smente. La gente que no deja de hacer postureo con el excesivo trabajo que tiene, cada vez me resulta m\u00e1s sospechosa de, en realidad, no tener mucho que hacer: si tan ocupada estuviera, no perder\u00eda el tiempo repiti\u00e9ndolo una y otra vez.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/gente-muy-ocupada\/gente-ocupada-toy-story\/\" rel=\"attachment wp-att-22235\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-22235\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/05\/Gente-ocupada-toy-story.jpg\" alt=\"\" width=\"258\" height=\"196\" \/><\/a><\/p>\n<p>\u00bfNo les ha pasado, llegar a un bar que est\u00e1 hasta los topes y que les atiendan razonablemente r\u00e1pido y bien mientras que hay garitos medio vac\u00edos en los que todo es lentitud, desidia e ineficiencia? Pues, lo m\u00e1s probable, es que el personal m\u00e1s quejoso est\u00e9 en este segundo tipo de establecimiento.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-21978 noopener noreferrer\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21978 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A comienzos de semana tuve que telefonear a una persona por cuestiones de trabajo. Insisto en el \u201ctuve que\u201d y en que era por asuntos laborales. Nada que ver, pues, con el placer, el gusto, el esparcimiento o el divertimento. Y de ello hablo en IDEAL hoy. La persona en cuesti\u00f3n, antes siquiera de escucharme, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14444,14447,14445,14446],"class_list":["post-22232","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-gente-muy-ocupada","tag-no-me-jodas","tag-que-lio-tengo","tag-por-que-me-molestas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22232","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22232"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22232\/revisions"}],"predecessor-version":[{"id":22237,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22232\/revisions\/22237"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22232"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22232"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22232"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}