{"id":22018,"date":"2017-04-09T07:27:54","date_gmt":"2017-04-09T06:27:54","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=22018"},"modified":"2017-04-08T19:37:21","modified_gmt":"2017-04-08T18:37:21","slug":"el-juez-de-la-horca","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-juez-de-la-horca\/","title":{"rendered":"El juez de la horca"},"content":{"rendered":"<p>Yo tambi\u00e9n estoy cansado de todo lo que est\u00e1 ocurriendo en torno al Ayuntamiento de Granada, en una semana nefasta para la pol\u00edtica local.\u00a0Prometo que, desde ma\u00f1ana, en IDEAL, me volcar\u00e9 en aspectos m\u00e1s l\u00fadicos, alegres y festivos de nuestro entorno, pero hoy me siento obligado a volver sobre la situaci\u00f3n de Paco Cuenca, al que dej\u00e1bamos ayer con la soga al cuello <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/comienza-la-cuenta-atras-2\/\" target=\"_blank\">en esta columna<\/a>, tras la comparecencia de Luis Salvador y Sebasti\u00e1n P\u00e9rez ante los medios de comunicaci\u00f3n, haciendo p\u00fablica una entente cordial que veremos d\u00f3nde desemboca. Y sobre ello va mi columna dominical de IDEAL.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=22019\" rel=\"attachment wp-att-22019\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22019\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/59714080_1473013827-224x300.jpg\" alt=\"\" width=\"224\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/59714080_1473013827-224x300.jpg 224w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/59714080_1473013827-644x862.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/59714080_1473013827.jpg 720w\" sizes=\"auto, (max-width: 224px) 100vw, 224px\" \/><\/a><\/p>\n<p>\u00bfQu\u00e9 les ha parecido la actuaci\u00f3n de los susodichos, poniendo al alcalde de Granada en la picota? Lo del PP tiene toda la l\u00f3gica y el sentido: de cara al congreso del mes que viene, Sebasti\u00e1n P\u00e9rez se ha presentado como la \u00fanica opci\u00f3n v\u00e1lida para retomar la alcald\u00eda, dado el ascendiente que Torres Hurtado tiene sobre la candidatura de Garc\u00eda Montero.<\/p>\n<p>Pero, \u00bfy lo de Salvador? Por seguir en la misma clave de western de ayer, \u00bfno tienen la sensaci\u00f3n de que se ha erigido en una especie de Roy Bean, conocido popularmente como el Juez de la Horca? En serio, Ciudadanos se lo tiene que hacer ver. Porque ya cansa su vigilante y exigente actitud\u2026 en contraste con su falta de compromiso y colaboraci\u00f3n a la hora de sacar adelante proyectos de gobierno.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=22020\" rel=\"attachment wp-att-22020\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22020\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/57490286-181x300.jpg\" alt=\"\" width=\"181\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/57490286-181x300.jpg 181w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/57490286.jpg 619w\" sizes=\"auto, (max-width: 181px) 100vw, 181px\" \/><\/a><\/p>\n<p>M\u00e1s all\u00e1 de poner y quitar alcaldes, deshojando la margarita entre la Rosa y la Gaviota, \u00bfqu\u00e9 ha hecho Ciudadanos en el consistorio granadino? Luis Salvador se queja de que Paco Cuenca va por libre, pero \u00bfqu\u00e9 fue antes, el huevo o la gallina? Porque exigir, Salvador exige mucho. Pero, \u00bfy colaborar?<\/p>\n<p>En este punto, Paco Cuenca y su inmensa minor\u00eda tienen una baza a su favor: si Luis Salvador cumple su amenaza y vuelve a cambiar al alcalde de la ciudad, el tercero en poco m\u00e1s de media legislatura, su miop\u00eda a la hora de apostar por las personas a las que brinda su apoyo se convertir\u00e1 en leyenda, hasta el punto de que ser\u00e1 mejor que te mire una legi\u00f3n de tuertos a que lo haga Salvador.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=22021\" rel=\"attachment wp-att-22021\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-22021\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/sebastian-perez-salvador-575x323-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/sebastian-perez-salvador-575x323-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/sebastian-perez-salvador-575x323.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Por contra, si termina indultando a Cuenca, su cr\u00e9dito y su credibilidad habr\u00e1n perdido enteros. Otra vez. Y el sambenito de ser un \u201cQuiero y no puedo\u201d se le adosar\u00e1 a la espalda, como el monigote del D\u00eda de los Inocentes.<\/p>\n<p>&nbsp;<\/p>\n<p>PD.- Podemos tacha de esperpento la comparecencia de Salvador-Sebasti\u00e1n y <a href=\"http:\/\/www.ideal.es\/granada\/201704\/08\/podemos-tacha-esperpento-anuncio-20170408145043.html\" target=\"_blank\">\u00absigue tendiendo la mano al PSOE\u00bb<\/a>. Lo malo es que ha pasado un a\u00f1o y las manos tendidas no parecen haber servido para nada.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-21978\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21978 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/04\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Yo tambi\u00e9n estoy cansado de todo lo que est\u00e1 ocurriendo en torno al Ayuntamiento de Granada, en una semana nefasta para la pol\u00edtica local.\u00a0Prometo que, desde ma\u00f1ana, en IDEAL, me volcar\u00e9 en aspectos m\u00e1s l\u00fadicos, alegres y festivos de nuestro entorno, pero hoy me siento obligado a volver sobre la situaci\u00f3n de Paco Cuenca, al [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14304,14301,14303,14298,14302,14297,14299,14305,14300],"class_list":["post-22018","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alberto-mataran","tag-crisis-ayuntamiento-de-granada","tag-deriva-ciudadanos","tag-el-juez-de-la-horca","tag-granada-crisis","tag-luis-salvador-granada","tag-luis-salvador-juez-horca","tag-manos-tendidas","tag-salvador-sebastian"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22018","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=22018"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22018\/revisions"}],"predecessor-version":[{"id":22024,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/22018\/revisions\/22024"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=22018"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=22018"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=22018"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}