{"id":21608,"date":"2017-02-17T11:57:45","date_gmt":"2017-02-17T10:57:45","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=21608"},"modified":"2017-02-17T11:57:45","modified_gmt":"2017-02-17T10:57:45","slug":"granada-es-un-western","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/granada-es-un-western\/","title":{"rendered":"Granada es un western"},"content":{"rendered":"<p>S\u00ed. Lo es. Un western. Granada. Literalmente hablando. No me refiero al cine, por una vez. No hablo metaf\u00f3ricamente ni barrunto la posibilidad de que las Badlands de Guadix vayan a acoger el rodaje de una nueva pel\u00edcula del Oeste. Lo que digo es que Granada es un western en s\u00ed misma. Y de ello hablo hoy en IDEAL.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/granada-es-un-western\/granada-western\/\" rel=\"attachment wp-att-21610\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21610\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-western-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-western-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-western.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>\u00bfLeyeron ustedes el IDEAL de ayer? Al peri\u00f3dico f\u00edsico, me refiero. Al de papel. Que ya saben que una de mis m\u00e1ximas es que no es lo mismo saber lo que pasa que estar informados. Para saber lo que pasa, basta con picotear por Internet, pinchar algunos enlaces, aceptar unas cookies y dar a unos cuantos Me gusta en las redes sociales.<\/p>\n<p>&nbsp;<\/p>\n<p>Estar informados es otra cosa. Implica leer. Pero leer de verdad. Y escuchar, m\u00e1s all\u00e1 de o\u00edr. Y si ustedes leyeron ayer este peri\u00f3dico tendr\u00e1n que convenir conmigo\u2026 en que Granada es un western.<\/p>\n<p>&nbsp;<\/p>\n<p>Portada y p\u00e1ginas 2 y 3: \u201cDesmantelada una potente multinacional granadina dedicada al narcotr\u00e1fico\u201d. P\u00e1gina 3: \u201cLa guerra contra los enganches ilegales y la marihuana, sin tregua\u201d. P\u00e1gina 4: \u201cDenuncian a dos menores por maltrato animal tras una pelea de gallos\u201d y \u201cPrisi\u00f3n para el atracador que intent\u00f3 robar un bar del barrio de la Plaza de Toros\u201d. P\u00e1gina 5: \u201cLos doce ni\u00f1os que se amotinaron en el \u00c1ngel Ganivet e hirieron a dos polic\u00edas se declaran culpables\u201d.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/granada-es-un-western\/granada-peleas-gallos\/\" rel=\"attachment wp-att-21611\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21611\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-peleas-gallos-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-peleas-gallos-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-peleas-gallos.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Es necesario llegar a la p\u00e1gina 7 para encontrar esos temas que ya nos suenan a conocidos: el retraso en el Metro, el caso Serrallo o la fusi\u00f3n hospitalaria.<\/p>\n<p>&nbsp;<\/p>\n<p>Es importante leer el peri\u00f3dico y estar informados porque, de lo contrario, si solo picoteamos de las noticias que nos interesan, permanecemos ajenos a la realidad de lo que pasa en la calle. Y en la calle hay hach\u00eds y marihuana como para parar un tranv\u00eda, gallos de pelea tuertos, sin cresta ni espolones, despu\u00e9s de enfrentarlos en peleas ilegales; motines en centros de acogida y atracos a mano armada, felizmente frustrado en el caso que nos ocupa.<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/granada-es-un-western\/granada-marihuana\/\" rel=\"attachment wp-att-21612\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21612\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-marihuana-300x169.jpg\" alt=\"\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-marihuana-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/Granada-marihuana.jpg 572w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p>Todo eso es, tambi\u00e9n, la realidad de Granada. Y como bien escrib\u00eda Alejandro Pedregosa en su columna del pasado s\u00e1bado, est\u00e1 directamente relacionado con los paup\u00e9rrimos \u00edndices de riqueza y empleo de la provincia de Granada, con sus bajos niveles de industrializaci\u00f3n y tecnificaci\u00f3n y con las proverbiales carencias mil y una veces denunciadas, pero jam\u00e1s corregidas.<\/p>\n<p>&nbsp;<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-21583\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21583 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/02\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>S\u00ed. Lo es. Un western. Granada. Literalmente hablando. No me refiero al cine, por una vez. No hablo metaf\u00f3ricamente ni barrunto la posibilidad de que las Badlands de Guadix vayan a acoger el rodaje de una nueva pel\u00edcula del Oeste. Lo que digo es que Granada es un western en s\u00ed misma. Y de ello [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[14005,14000,14003,14002,14004,14001],"class_list":["post-21608","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-delincuencia-granada","tag-granada-western","tag-hachis-granada","tag-marihuana-granada","tag-peleas-de-gallos-granada","tag-western-granada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21608","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=21608"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21608\/revisions"}],"predecessor-version":[{"id":21614,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21608\/revisions\/21614"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=21608"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=21608"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=21608"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}