{"id":21423,"date":"2017-01-28T20:40:48","date_gmt":"2017-01-28T19:40:48","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=21423"},"modified":"2017-01-28T20:40:48","modified_gmt":"2017-01-28T19:40:48","slug":"pepe-carvalho-en-las-manos-de-carlos-zanon","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/pepe-carvalho-en-las-manos-de-carlos-zanon\/","title":{"rendered":"Pepe Carvalho, en las manos de Carlos Zan\u00f3n"},"content":{"rendered":"<p>Por fin subimos on line la entrevista que hicimos en IDEAL a Carlos Zan\u00f3n. Y es que hace un par de semanas, un personaje de ficci\u00f3n se convert\u00eda en Trending Topic: Pepe Carvalho. El m\u00edtico detective creado por Manuel V\u00e1zquez Montalb\u00e1n pon\u00eda las redes en ebullici\u00f3n gracias a una noticia tan inesperada como feliz: en 2018, y de la mano del escritor Carlos Zan\u00f3n, habr\u00e1 una nueva novela protagonizada por un tipo c\u00ednico y descre\u00eddo, pero firmemente comprometido con la verdad. Un gourmet que fue agente de la CIA, miembro del Partido Comunista y actualmente\u2026<\/p>\n<p><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pepe-carvalho-en-las-manos-de-carlos-zanon\/xxxv-feria-del-libro-de-granada-2016\/\" rel=\"attachment wp-att-21424\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-21424\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/MG_4003_Carlos_Zanon_Andres_Lopez_Presentacion_jpg.jpg.jpg\" alt=\"\" width=\"350\" height=\"237\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/MG_4003_Carlos_Zanon_Andres_Lopez_Presentacion_jpg.jpg.jpg 350w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/MG_4003_Carlos_Zanon_Andres_Lopez_Presentacion_jpg.jpg-300x203.jpg 300w\" sizes=\"auto, (max-width: 350px) 100vw, 350px\" \/><\/a><\/p>\n<p>Precisamente de eso, de la actualidad de Pepe Carvalho, hablamos con Carlos Zan\u00f3n, elegido por Planeta y por los herederos de Manuel V\u00e1zquez Montalb\u00e1n para continuar con una saga hist\u00f3rica de la literatura negra y criminal.<\/p>\n<p>\u00bfC\u00f3mo se siente usted ante un reto de semejante magnitud?<\/p>\n<p><b>Ilusionado seguro y, a ratos, agobiado y con ganas de que el foco cambie de sitio.<\/b><\/p>\n<p>\u00bfTuvo dudas a la hora de aceptar el desaf\u00edo?<\/p>\n<p><b>S\u00ed, claro. De todo tipo. No s\u00f3lo del proyecto sino tambi\u00e9n de c\u00f3mo iba a afectar a mi trayectoria, de trabajar con otra editorial.\u00a0<\/b><\/p>\n<p>La reacci\u00f3n mayoritaria ante la noticia ha sido favorable y positiva. \u00bfTem\u00eda usted el momento de hacerse p\u00fablico este bombazo?<\/p>\n<p><b>La verdad es que no me hab\u00eda hecho ninguna idea en particular.<\/b><\/p>\n<figure id=\"attachment_21425\" aria-describedby=\"caption-attachment-21425\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pepe-carvalho-en-las-manos-de-carlos-zanon\/carlos-zanon-003_2\/\" rel=\"attachment wp-att-21425\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-21425\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/Carlos-Zanon-003_2-644x411.jpg\" alt=\"\" width=\"644\" height=\"411\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/Carlos-Zanon-003_2-644x411.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/Carlos-Zanon-003_2-300x192.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/Carlos-Zanon-003_2-768x490.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/Carlos-Zanon-003_2.jpg 1250w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><figcaption id=\"caption-attachment-21425\" class=\"wp-caption-text\">Foto: Solo Novela Negra<\/figcaption><\/figure>\n<p>Despedimos a Carvalho en \u201cMilenio\u201d, un tour de force narrativo en el que se marchaba de Espa\u00f1a y se embarcaba en una complicada vuelta al mundo. \u00bfNos reencontraremos con \u00e9l aqu\u00ed y ahora, en la Barcelona de la que es alcaldesa Ada Colau?<\/p>\n<p><b>\u00c9sa es la idea: 2017-2018. Barcelona y quiz\u00e1s otra ciudad.\u00a0<\/b><b>\u00a0<\/b><\/p>\n<p>Usted tambi\u00e9n ha retratado Barcelona en sus novelas. \u00bfSer\u00e1 f\u00e1cil llegar a un punto de encuentro entre ambas perspectivas de la misma ciudad?<\/p>\n<p><b>Mi idea es respetar al escritor y a su mundo y para eso no hay nada mejor, creo yo, que el libro tenga mi manera de escribir y mi ciudad, el aqu\u00ed y el ahora, del modo en que lo retrataba MVM.<\/b><\/p>\n<p>Carvalho naci\u00f3 en 1972, vinculado al asesinato de Kennedy, pero fue en \u201cLa soledad del manager\u201d, publicada en 1977, cuando Manuel V\u00e1zquez Montalb\u00e1n le dio hechuras de protagonista de una saga literaria de largo recorrido. Carvalho ha sido testigo, pues, de cuarenta a\u00f1os de la historia reciente de Espa\u00f1a. \u00bfC\u00f3mo afronta usted el paso del tiempo en un personaje con tanto visto, con tanto vivido?<\/p>\n<p><b>Pienso en un personaje, una mirada y un encargo que ha de resolver.<\/b><\/p>\n<figure id=\"attachment_21426\" aria-describedby=\"caption-attachment-21426\" style=\"width: 644px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/pepe-carvalho-en-las-manos-de-carlos-zanon\/timthumb-php-2\/\" rel=\"attachment wp-att-21426\"><img loading=\"lazy\" decoding=\"async\" class=\"size-large wp-image-21426\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/timthumb.php-2-644x361.jpeg\" alt=\"\" width=\"644\" height=\"361\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/timthumb.php-2-644x361.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/timthumb.php-2-300x168.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/timthumb.php-2-768x430.jpeg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/timthumb.php-2.jpeg 1250w\" sizes=\"auto, (max-width: 644px) 100vw, 644px\" \/><\/a><figcaption id=\"caption-attachment-21426\" class=\"wp-caption-text\">Foto. Solo Novela Negra<\/figcaption><\/figure>\n<p>Los lectores de MVM esperamos encontrarnos con algunos de los rasgos distintivos de la saga de Carvalho, \u00bfseguir\u00e1 quemando libros, por ejemplo?<\/p>\n<p><b>S\u00ed, \u00e9sa es una tentaci\u00f3n que no he podido ni he querido evitar.<\/b><\/p>\n<p>\u00bfC\u00f3mo se habr\u00e1 adaptado Carvalho a la era de Internet? \u00bfNos puede usted asegurar que NO se ha abierto cuenta en Instagram para poner fotos de esos exquisitos platos a los que es tan aficionado?<\/p>\n<p><b>Te lo aseguro.<\/b><\/p>\n<p>Ha dicho usted que Carvalho ser\u00e1 m\u00e1s rockero en esta nueva entrega. \u00bfSe anima usted a pinchar en Granada Noir la banda sonora de su vida, a ver qu\u00e9 tal suena?<\/p>\n<p><b>Eso est\u00e1 hecho, amigo.<\/b><\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-21248\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-21248 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2017\/01\/1-Twitter-Lens.jpg\" alt=\"\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Por fin subimos on line la entrevista que hicimos en IDEAL a Carlos Zan\u00f3n. Y es que hace un par de semanas, un personaje de ficci\u00f3n se convert\u00eda en Trending Topic: Pepe Carvalho. El m\u00edtico detective creado por Manuel V\u00e1zquez Montalb\u00e1n pon\u00eda las redes en ebullici\u00f3n gracias a una noticia tan inesperada como feliz: en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":true,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,21],"tags":[13864,12012,13862,13863,13865,12372],"class_list":["post-21423","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-negra-y-criminal","tag-carlos-zanon-carvalho","tag-carlos-zanon-granada","tag-carlos-zanon-granada-noir","tag-carlos-zanon-granada-noir-3","tag-carvalho-zanon","tag-manuel-vazquez-montalban"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21423","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=21423"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21423\/revisions"}],"predecessor-version":[{"id":21428,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21423\/revisions\/21428"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=21423"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=21423"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=21423"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}