{"id":21030,"date":"2016-12-11T19:03:18","date_gmt":"2016-12-11T18:03:18","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=21030"},"modified":"2016-12-11T19:03:18","modified_gmt":"2016-12-11T18:03:18","slug":"en-el-pabellon-cubierto","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-pabellon-cubierto\/","title":{"rendered":"En el pabell\u00f3n cubierto"},"content":{"rendered":"<p style=\"text-align: justify;\">Hasta ayer no ca\u00ed en la cuenta de la enorme importancia que tienen las palabras \u201cpabell\u00f3n cubierto\u201d en nuestras vidas. \u00a1Con qu\u00e9 naturalidad las usamos en nuestro lenguaje cotidiano! Y con qu\u00e9 sencillez los hemos incorporado a nuestra agenda. A ellos. Los pabellones.<\/p>\n<p style=\"text-align: justify;\">Cuando mi querido Alberto Tarifa me dijo que el s\u00e1bado hab\u00eda un Tres x Tres de baloncesto, no dud\u00e9 en apuntarme, junto a Sergio y Owen. A lo que no prest\u00e9 mucha atenci\u00f3n era al motivo del torneo: la inauguraci\u00f3n del nuevo pabell\u00f3n cubierto del colegio Mulhac\u00e9n. Y de un asunto aparentemente banal hablo hoy en IDEAL.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-pabellon-cubierto\/fullsizerender-2-4\/\" rel=\"attachment wp-att-21031\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21031\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2-300x225.jpg\" alt=\"Pe\u00f1a baloncesto Jes\u00fas Lens\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2-1024x768.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2-644x483.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/FullSizeRender-2.jpg 1632w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y all\u00ed nos plantamos, ayer por la ma\u00f1ana, junto a varias decenas m\u00e1s de jugadores, la mayor\u00eda de ellos mucho m\u00e1s j\u00f3venes que nosotros; dispuestos a compartir un pu\u00f1ado de horas de deporte y confraternizaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">A mitad de torneo, se hizo la inauguraci\u00f3n oficial del pabell\u00f3n y uno de los participantes en el acto record\u00f3 la cantidad de veces que hemos ido a hacer deporte y nos hemos encontrado con los partidos suspendidos por la lluvia o las inclemencias meteorol\u00f3gicas. En ese preciso instante me vino una cascada de recuerdos: la asignatura de gimnasia en el colegio, las competiciones escolares, las pe\u00f1as de baloncesto, los partidos del Patronato, los Intercajas y los meses de entrenamiento\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-pabellon-cubierto\/nunez-blanca-575x323\/\" rel=\"attachment wp-att-21032\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21032\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/nunez-blanca-575x323-300x169.jpg\" alt=\"Pabell\u00f3n N\u00fa\u00f1ez Blanca\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/nunez-blanca-575x323-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/nunez-blanca-575x323.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Hoy domingo, miles de granadinos disfrutar\u00e1n de cientos de actividades deportivas que se celebrar\u00e1n en los muchos pabellones deportivos de nuestras ciudades y pueblos. \u00bfSomos conscientes del logro y el avance que supone no depender del tiempo para practicar deporte? \u00a1Cu\u00e1ntos equipos y pe\u00f1as no han surgido al calor de unas instalaciones que, en cientos de barrios y municipios, le han cambiado la vida a la gente!<\/p>\n<p style=\"text-align: justify;\">Me encant\u00f3 participar en un acto tan sencillo, pero a la vez tan sentido y emocionante como el de ayer. Un acto que me sirvi\u00f3 para darle valor a algo que viene formando parte de mi vida desde hace a\u00f1os y a\u00f1os: practicar deporte en las mejores condiciones posibles.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-pabellon-cubierto\/img_6031\/\" rel=\"attachment wp-att-21033\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-21033\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/IMG_6031-300x225.jpg\" alt=\"Pabellones Cubiertos Granada\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/IMG_6031-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/IMG_6031-768x576.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/IMG_6031-1024x768.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/12\/IMG_6031-644x483.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Un lunar empa\u00f1\u00f3 la jornada: mi querido tocayo Jes\u00fas, tan buen deportista como mejor persona, sufri\u00f3 una grave lesi\u00f3n de rodilla en una entrada a canasta. Ayer mismo fue operado y, conociendo su tes\u00f3n y su fortaleza, s\u00e9 que no tardar\u00e1 en volver a nadar, correr y montar en bicicleta, participando en sus Triatlones. Sirva esta columna como homenaje a un tipo extraordinario y vitalista que jam\u00e1s pierde la sonrisa.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-20775\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20775 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/1-Twitter-Lens.jpg\" alt=\"1 Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hasta ayer no ca\u00ed en la cuenta de la enorme importancia que tienen las palabras \u201cpabell\u00f3n cubierto\u201d en nuestras vidas. \u00a1Con qu\u00e9 naturalidad las usamos en nuestro lenguaje cotidiano! Y con qu\u00e9 sencillez los hemos incorporado a nuestra agenda. A ellos. Los pabellones. Cuando mi querido Alberto Tarifa me dijo que el s\u00e1bado hab\u00eda un [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[13599,13601,10177,13600,13203,13598],"class_list":["post-21030","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alberto-tarifa","tag-alumni-atendis","tag-jesus-rodriguez","tag-owen-bombero","tag-owen-garcia","tag-pabellones-cubiertos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21030","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=21030"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21030\/revisions"}],"predecessor-version":[{"id":21035,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/21030\/revisions\/21035"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=21030"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=21030"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=21030"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}