{"id":20989,"date":"2016-12-04T18:28:19","date_gmt":"2016-12-04T17:28:19","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20989"},"modified":"2016-12-04T18:28:19","modified_gmt":"2016-12-04T17:28:19","slug":"granadinos-a-acelerar-tocamos","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/granadinos-a-acelerar-tocamos\/","title":{"rendered":"\u00a1Granadinos! \u00a1A acelerar tocamos!"},"content":{"rendered":"<p style=\"text-align: justify;\">Ha llegado la hora. El momento decisivo. Estamos en ese punto en que toca dejar de calentar y entrar al partido, con los m\u00fasculos en tensi\u00f3n y plena concentraci\u00f3n, dispuestos a dar el 100% de nosotros mismos. Se acab\u00f3 la espera. Toca quitarse la sudadera, apretar los dientes y demostrar, por una vez, que s\u00ed se puede.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/un-acelerador-en-granada\/acelerador-cern\/\" rel=\"attachment wp-att-19586\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19586\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-CERN-300x169.jpg\" alt=\"Acelerador CERN\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-CERN-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-CERN-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-CERN.jpg 770w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Porque Granada se juega su futuro en los pr\u00f3ximos meses, una vez presentada la candidatura para albergar el famoso IFMIF-Dones, el Acelerador de Part\u00edculas que meter\u00eda a nuestra provincia, de lleno, en el siglo XXI.<\/p>\n<p style=\"text-align: justify;\">En esta cuesti\u00f3n no caben titubeos ni medias tintas. El compromiso debe ser total y absoluto. De momento, parece que todas las administraciones est\u00e1n remando en la misma direcci\u00f3n, dando igual el color de cada una. Y es que en esta largu\u00edsima carrera de fondo, cuya meta parece vislumbrarse a final de 2017, da lo mismo que seamos rojos, azules, verdes o violetas: estamos en el mismo barco. El barco de progreso cient\u00edfico y tecnol\u00f3gico que, por una vez, hemos tomado a tiempo.<\/p>\n<p style=\"text-align: justify;\">Con el proyecto del IFMIF-Dones se est\u00e1n haciendo las cosas bien. Se est\u00e1 trabajando de forma consensuada y discreta en un ejemplo de colaboraci\u00f3n p\u00fablico-privada que, de momento, cuenta con 230 millones de financiaci\u00f3n comprometidos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/un-acelerador-en-granada\/seven-solutions\/\" rel=\"attachment wp-att-19585\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19585\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Seven-Solutions-200x300.jpg\" alt=\"Seven Solutions\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Seven-Solutions-200x300.jpg 200w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Seven-Solutions.jpg 487w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pero falta m\u00e1s dinero. Porque la otra gran competidora para albergar el acelerador de part\u00edculas, Croacia, dispone de un presupuesto de 400 millones de euros. La parte t\u00e9cnica de la candidatura espa\u00f1ola supera a la croata y a la polaca, que parece haber perdido opciones en esta carrera, por lo que la decisi\u00f3n final depender\u00e1 de un pu\u00f1ado de millones de euros.<\/p>\n<p style=\"text-align: justify;\">La diferencia es, ahora, de 170 millones de euros. Una cantidad muy importante y respetable, pero en absoluto imposible de conseguir. Sobre todo porque, aunque no se alcancen los 400 kilos, la candidatura granadina est\u00e1 muy bien valorada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/un-acelerador-en-granada\/acelerador\/\" rel=\"attachment wp-att-19584\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19584\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-300x181.jpg\" alt=\"Acelerador\" width=\"300\" height=\"181\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador-300x181.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Acelerador.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Da igual que seamos del centro o de la periferia. De pueblo o de ciudad. Del Madrid o del Bar\u00e7a. Del Metro soterrado o de superficie. De la estaci\u00f3n de Moneo o de un sencillo apeadero. En el tema del Acelerador de Part\u00edculas, Granada solo puede ser una y, cada uno en nuestro \u00e1mbito de actuaci\u00f3n, hemos de trabajar duro para conseguir su llegada.<\/p>\n<p style=\"text-align: justify;\">Form\u00e9monos e inform\u00e9monos. Aprendamos. Escribamos, pidamos, clamemos y exijamos. Todos unidos y en sinton\u00eda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfQue por qu\u00e9 es tan importante? Por una parte, por la cuesti\u00f3n literaria y parad\u00f3jica, como escrib\u00ed <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/un-acelerador-en-granada\/\" target=\"_blank\">aqu\u00ed d\u00eda en IDEAL<\/a>, en clave ir\u00f3nica. Y, por otra parte, por lo econ\u00f3mico, social y por el empuje en las infraestructuras que puede tener para Granada, como igualmente escrib\u00ed en IDEAL, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/potencial-potencia-cientifica\/\" target=\"_blank\">en este otro art\u00edculo<\/a>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Si est\u00e1n de acuerdo, compartan, difundan distribuyan&#8230; \u00a1Es nuestro futuro!<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-20775\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20775 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/1-Twitter-Lens.jpg\" alt=\"1 Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ha llegado la hora. El momento decisivo. Estamos en ese punto en que toca dejar de calentar y entrar al partido, con los m\u00fasculos en tensi\u00f3n y plena concentraci\u00f3n, dispuestos a dar el 100% de nosotros mismos. Se acab\u00f3 la espera. Toca quitarse la sudadera, apretar los dientes y demostrar, por una vez, que s\u00ed [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12596,13567,12635,10644,7541,12633,12632,12127,13566,564],"class_list":["post-20989","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-acelerador-de-particulas","tag-biotecnologia","tag-francisco-benitez","tag-granada-2020","tag-granada-futuro","tag-ifmif","tag-ifmif-dones","tag-pts-granada","tag-santiago-carbo","tag-viajes-en-el-tiempo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20989","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20989"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20989\/revisions"}],"predecessor-version":[{"id":20990,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20989\/revisions\/20990"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20989"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20989"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20989"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}