{"id":20957,"date":"2016-11-30T11:17:35","date_gmt":"2016-11-30T10:17:35","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20957"},"modified":"2016-11-30T11:17:36","modified_gmt":"2016-11-30T10:17:36","slug":"el-noir-que-viajo-en-un-ballenero","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/","title":{"rendered":"El Noir que viaj\u00f3 en un ballenero"},"content":{"rendered":"<p style=\"text-align: justify;\">Uno escribe \u201cballena\u201d y el lector piensa autom\u00e1ticamente en \u201cMoby Dick\u201d. Adem\u00e1s, el barco ballenero por excelencia es el Pequod, comandado por el capit\u00e1n Ahab. Eso es un hecho. Como tambi\u00e9n lo es que Ahab es Gregory Peck. Y punto.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/moby-dick\/\" rel=\"attachment wp-att-20958\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20958\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-300x300.jpg\" alt=\"moby dick\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-768x768.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-644x644.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Partiendo de esas premisas, es muy complejo para cualquier autor o cineasta abordar una historia que transcurra en un ballenero: lector y espectador tienen inevitablemente a comparar con la novela de Melville o con la pel\u00edcula de Huston.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">De ah\u00ed que me gustara tanto la atrevida propuesta de Ron Howard, al filmar \u201cEn el coraz\u00f3n del mar\u201d: un escritor que pasa por un bloqueo creativo le paga a un antiguo marinero una fuerte suma de dinero para que le cuente su historia. Una historia terrible, que aconteci\u00f3 muchos a\u00f1os ha. Y de la que nunca ha hablado. Una historia brutal que ha tratado de olvidar por todos los medios. Sin conseguirlo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/en-el-corazon-del-mar\/\" rel=\"attachment wp-att-20959\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20959\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar-300x169.jpg\" alt=\"En el coraz\u00f3n del mar\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar-1024x576.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/En-el-coraz\u00f3n-del-mar.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Una historia que transcurre a comienzos del siglo XIX, en el Essex, un ballenero que, mal comandado por un capit\u00e1n clasista y soberbio, se ve sometido a mil y una desventuras en alta mar. La pel\u00edcula, interpretada por Chris Hemsworth, es un brillante ejercicio de espectacular cine de aventuras que gustar\u00e1 a los aficionados al subg\u00e9nero.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Porque dentro del g\u00e9nero de aventuras hay todo un subg\u00e9nero protagonizado por los grandes barcos de vela que surcan los oc\u00e9anos y por el que siento especial predilecci\u00f3n. De ah\u00ed que, en cuanto tuve conocimiento de la publicaci\u00f3n de la novela \u201cLa sangre helada\u201d, publicada por Roca Editorial, me lanzara como un poseso sobre ella. A sabiendas de que era un ejercicio arriesgado, por supuesto.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/moby-dick-ahab\/\" rel=\"attachment wp-att-20960\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20960\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab-300x200.jpg\" alt=\"moby dick Ahab\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab-768x513.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab-1024x684.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab-644x430.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/moby-dick-Ahab.jpg 1050w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y es que la novela de Ian McGuire introduce el Noir en un ballenero que se dirige al \u00c1rtico, en busca de las \u00faltimas ballenas. Porque \u201cLa sangre helada\u201d transcurre en las postrimer\u00edas del siglo XIX, cuando los barcos de vapor empezaron a dejar obsoletos a los veleros y la caza de la ballena tocaba a su fin. En primer lugar, porque hab\u00edan sido tan diezmadas que, para encontrarlas, hab\u00eda que viajar al C\u00edrculo Polar. Y, en segundo lugar, porque la grasa de ballena cotizaba a la baja, tras el descubrimiento de productos qu\u00edmicos que pod\u00edan sustituirla.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/la-sangre-helada\/\" rel=\"attachment wp-att-20961\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20961\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-196x300.jpg\" alt=\"La sangre helada\" width=\"196\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-196x300.jpg 196w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada.jpg 500w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Efectivamente, el Volunteer navega hacia el \u00c1rtico, comandado por el capit\u00e1n\u00a0 Brownlee. A bordo, entre otros miembros de la tripulaci\u00f3n, Henry Drax, un arponero extremadamente violento al que descubriremos al principio de la narraci\u00f3n tirando de navaja y llev\u00e1ndose por delante a un pobre desdichado que tuvo la mala fortuna de toparse con \u00e9l.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Patrick Summer, el m\u00e9dico del Volunteer, tiene otro car\u00e1cter completamente distinto, aunque tambi\u00e9n arrastra una complicada historia a sus espaldas. Y es que, como tantas veces hemos encontrado en la historia de la gran literatura, embarcarse en una larga traves\u00eda de futuro incierto es la mejor f\u00f3rmula para tratar de olvidar a los fantasmas del pasado. Y, si no, que le pregunten a Joseph Conrad.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/la-sangre-helada-detalle\/\" rel=\"attachment wp-att-20962\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20962\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-detalle-300x206.jpg\" alt=\"La sangre helada detalle\" width=\"300\" height=\"206\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-detalle-300x206.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-detalle-644x443.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/La-sangre-helada-detalle.jpg 650w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De repente, un asesinato a bordo. Un asesinato particularmente brutal, cometido con la sa\u00f1a y la crueldad propias de un asesino en serie. \u00bfC\u00f3mo? \u00bfAsesinos en serie? \u00bfEn un ballenero? \u00bfEn el siglo XIX? \u00bfNo se nos estar\u00e1 yendo de las manos, esto del Noir?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">No. Tranquilos. \u201cLa sangre helada\u201d es un perfecto c\u00f3ctel que, desde la primera p\u00e1gina, mezcla a la perfecci\u00f3n los elementos de la mejor narraci\u00f3n negra y criminal con la aventura pura y dura, d\u00e1ndose la mano la caza de las focas y las ballenas con la caza del asesino.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Una novela, adem\u00e1s, que salta inteligentemente en el tiempo y en el espacio para transportar al lector a la India colonial, d\u00e1ndole a la narraci\u00f3n un toque extra de exotismo\u2026 y violencia. Porque lo mejor de \u201cLa sangre helada\u201d es que est\u00e1 trufada del hedor de la podredumbre y del sabor de la sangre: como sostiene Ian McGuire, la propia industria ballenera en el siglo XIX era violenta y sangrienta, de forma que su libro es una narraci\u00f3n muy realista de la compleja y turbulenta vida de aquellos a\u00f1os.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-que-viajo-en-un-ballenero\/ian-mcguire\/\" rel=\"attachment wp-att-20963\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20963\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/Ian-Mcguire-300x220.jpg\" alt=\"Ian Mcguire\" width=\"300\" height=\"220\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/Ian-Mcguire-300x220.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/Ian-Mcguire.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Una novela, tambi\u00e9n, en la que hay osos. Osos polares. Osos cuya presencia es m\u00e1s l\u00f3gica en \u201cLa sangre helada\u201d que en la isla de \u201cPerdidos\u201d, pero que tambi\u00e9n resultan amenazadores. Osos, en fin, que desempe\u00f1an un papel muy parecido al del (otro) protagonista de \u201cEl renacido\u201d, la pel\u00edcula que depar\u00f3 su primer Oscar a Leonardo DiCaprio, actor que estar\u00eda fant\u00e1stico en la piel de Summer. Que no ser\u00e1 extra\u00f1o que veamos, pronto, una pel\u00edcula basada en esta novela.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfCuadra ahora la mezcla entre la novela cl\u00e1sica de aventuras y el thriller m\u00e1s adictivo? Lean, lean \u201cLa sangre helada\u201d. Pero h\u00e1ganlo al calor del hogar, bien tapados con una manta, no sea que la sangre cuajada sea la suya\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-20775\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-20775 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/11\/1-Twitter-Lens.jpg\" alt=\"1 Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno escribe \u201cballena\u201d y el lector piensa autom\u00e1ticamente en \u201cMoby Dick\u201d. Adem\u00e1s, el barco ballenero por excelencia es el Pequod, comandado por el capit\u00e1n Ahab. Eso es un hecho. Como tambi\u00e9n lo es que Ahab es Gregory Peck. Y punto. Partiendo de esas premisas, es muy complejo para cualquier autor o cineasta abordar una historia [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,11774],"tags":[],"class_list":["post-20957","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-rincon-oscuro"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20957","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20957"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20957\/revisions"}],"predecessor-version":[{"id":20965,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20957\/revisions\/20965"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20957"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20957"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20957"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}