{"id":20677,"date":"2016-10-28T09:28:06","date_gmt":"2016-10-28T08:28:06","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20677"},"modified":"2016-10-28T09:28:07","modified_gmt":"2016-10-28T08:28:07","slug":"las-revalidas-invalidas","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/las-revalidas-invalidas\/","title":{"rendered":"Las rev\u00e1lidas inv\u00e1lidas"},"content":{"rendered":"<p style=\"text-align: justify;\">Contrastan las caras de alegr\u00eda, ilusi\u00f3n, expectativas, nervios e incertidumbre de los alumnos que han participado en las Jornadas de Recepci\u00f3n de Estudiantes de la UGR con los rostros, decididos e indignados, de los manifestantes en las concentraciones en contra de la LOMCE y las rev\u00e1lidas. Y de ello hablo en IDEAL.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-revalidas-invalidas\/manifestacion-lomce\/\" rel=\"attachment wp-att-20678\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20678\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Manifestaci\u00f3n-LOMCE-300x185.jpg\" alt=\"Manifestaci\u00f3n LOMCE\" width=\"300\" height=\"185\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Manifestaci\u00f3n-LOMCE-300x185.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Manifestaci\u00f3n-LOMCE-644x398.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Manifestaci\u00f3n-LOMCE.jpg 647w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Las dos caras de una misma moneda. De hecho, algunos de los estudiantes participaron de ambas convocatorias, que la ilusi\u00f3n no es incompatible con la indignaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Abro la web de IDEAL y me encuentro con que Rajoy, en pleno proceso de investidura, cede a las cr\u00edticas y presiones de la comunidad educativa, de forma que \u201cque las rev\u00e1lidas de cuarto de la ESO y Bachiller que implantar\u00e1 este curso carecer\u00e1n de todo valor acad\u00e9mico durante todo el tiempo que sea necesario para tratar de cerrar un pacto nacional por la educaci\u00f3n\u201d. \u00a1Toma ya!<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_20680\" aria-describedby=\"caption-attachment-20680\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-revalidas-invalidas\/universitarios-recepcion\/\" rel=\"attachment wp-att-20680\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20680\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Universitarios-recepci\u00f3n-300x200.jpg\" alt=\"Foto: Cristian G\u00e1lvez\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Universitarios-recepci\u00f3n-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Universitarios-recepci\u00f3n-768x511.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Universitarios-recepci\u00f3n-1024x682.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Universitarios-recepci\u00f3n-644x429.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-20680\" class=\"wp-caption-text\">Foto: Cristian G\u00e1lvez<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Sin duda, es una buena noticia. Pero una buena noticia que no debe hacernos olvidar el esc\u00e1ndalo que supone haber tratado de hacer comulgar con ruedas de molino a alumnos y docentes, a lo largo de estos a\u00f1os. \u00bfD\u00f3nde quedan ahora las soflamas sobre la educaci\u00f3n de calidad y la excelencia que han estado repitiendo los corifeos del PP, desde que se anunci\u00f3 el desprop\u00f3sito de la LOMCE, una norma criticada de forma un\u00e1nime por todas las fuerzas pol\u00edticas\u2026 excepci\u00f3n hecha del PP?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">S\u00ed. Ahora toca hablar de Pacto Nacional por la Educaci\u00f3n. As\u00ed, con may\u00fasculas. Y de otros grandes Pactos, como el de las Pensiones. Lo que sea, para justificar la abstenci\u00f3n del PSOE y el apoyo de Cs al gobierno de Rajoy. L\u00e1stima que, durante su mandato con mayor\u00eda absoluta, el PP no haya querido consensuar nada de nada.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A ver si hay suerte y en este marem\u00e1gnum de cesiones y negociaciones se cuela de rond\u00f3n el ignominioso 21% del IVA cultural, que tanto da\u00f1o ha hecho y sigue haciendo a los sectores creativos de nuestro pa\u00eds. Ya sabemos que la Cultura no le interesa a ning\u00fan estadista (recordemos que, en los debates presidenciales de las dos \u00faltimas campa\u00f1as electorales, nadie la nombr\u00f3 ni por error), pero lo mismo y de casualidad, alguien plantea el tema.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-revalidas-invalidas\/iva-cultural\/\" rel=\"attachment wp-att-20681\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-20681\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/IVA-cultural.jpg\" alt=\"IVA cultural\" width=\"223\" height=\"226\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfQuiz\u00e1 los descolocados chavales de Unidos Podemos, pillados en fuera de juego tras su frustrado y est\u00e9ril ejercicio de tacticismo? Adem\u00e1s de enfurru\u00f1arse y decir que NO a todo, alguna cruzada tendr\u00e1n que hacer suya\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Contrastan las caras de alegr\u00eda, ilusi\u00f3n, expectativas, nervios e incertidumbre de los alumnos que han participado en las Jornadas de Recepci\u00f3n de Estudiantes de la UGR con los rostros, decididos e indignados, de los manifestantes en las concentraciones en contra de la LOMCE y las rev\u00e1lidas. Y de ello hablo en IDEAL. Las dos caras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[7125,13351,13352,13350,13348,13349,13347,13346],"class_list":["post-20677","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-7125","tag-iva-21","tag-iva-cultural","tag-ley-de-educacion","tag-lomce","tag-no-a-rajoy","tag-revalida-invalida","tag-revalidas-invalidas"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20677","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20677"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20677\/revisions"}],"predecessor-version":[{"id":20683,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20677\/revisions\/20683"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20677"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20677"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20677"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}