{"id":20553,"date":"2016-10-05T09:22:51","date_gmt":"2016-10-05T08:22:51","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20553"},"modified":"2016-10-13T09:34:44","modified_gmt":"2016-10-13T08:34:44","slug":"las-mil-caras-de-la-ira","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/","title":{"rendered":"Las mil caras de la ira"},"content":{"rendered":"<p style=\"text-align: justify;\">Coinciden en cartelera dos pel\u00edculas extraordinarias, polic\u00edacas, espa\u00f1olas y m\u00e1s negras que el carb\u00f3n. Dos pel\u00edculas que han conquistado al p\u00fablico y a la cr\u00edtica en los exigentes y prestigiosos Festivales de Venecia y San Sebasti\u00e1n. Dos pel\u00edculas que acreditan el extraordinario momento que atraviesa el cine Noir en nuestro pa\u00eds y de las que hablo hoy en El Rinc\u00f3n Oscuro de IDEAL.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/el-hombre-de-las-mil-caras-3\/\" rel=\"attachment wp-att-20554\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20554\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-210x300.jpg\" alt=\"El hombre de las mil caras\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-210x300.jpg 210w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-768x1097.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-717x1024.jpg 717w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-644x920.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras.jpg 840w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Son dos pel\u00edculas, adem\u00e1s, de factura y tem\u00e1ticamente radicalmente distintas. Por un lado, \u201cEl hombre de las mil caras\u201d, de Alberto Rodr\u00edguez, art\u00edfice de la memorable \u201cLa isla m\u00ednima\u201d y en cuya producci\u00f3n tambi\u00e9n ha participado Jos\u00e9 S\u00e1nchez-Montes y la granadina Sacromonte Films. <a href=\"http:\/\/spainmediaradio.es\/radio\/calor-la-noche-hombre-las-mil-caras\/\" target=\"_blank\">Escuchen aqu\u00ed<\/a>, por cierto, el programa de radio que hicimos sobre Alberto Rodr\u00edguez Javier M\u00e1rquez, Juan Ram\u00f3n Biedma y un servidor. No es por nada, pero nos ha quedado la mar de bien&#8230;<\/p>\n<p style=\"text-align: justify;\">Por otro, \u201cTarde para la ira\u201d, el inesperado y sorprendente debut tras las c\u00e1maras de un Raul Ar\u00e9valo que, adem\u00e1s de ser un excelente actor, apunta maneras para convertirse en un cineasta total y al que auguramos una exitosa carrera, tambi\u00e9n, detr\u00e1s de las c\u00e1maras.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/tarde-para-la-ira-2\/\" rel=\"attachment wp-att-20555\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20555\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-210x300.jpg\" alt=\"Tarde para la ira\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-210x300.jpg 210w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira.jpg 450w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cEl hombre de las mil caras\u201d es una pel\u00edcula para ver con calma, sosiego y detenimiento. Se trata de una cinta de esp\u00edas al estilo cl\u00e1sico en la que apenas se ve una pistola, un mal gesto o una sacudida de violencia. Un filme en que los seguimientos y las persecuciones nada tienen que ver con el cine de acci\u00f3n norteamericano al que estamos acostumbrados.<\/p>\n<p style=\"text-align: justify;\">Una pel\u00edcula con un dise\u00f1o de producci\u00f3n exquisito en que Madrid, Par\u00eds, Singapur o Suiza lucen en pantalla con un esplendor y una minuciosidad en los detalles a los que no estamos acostumbrados en el cine espa\u00f1ol. \u201cEl hombre de las mil caras\u201d cuenta la historia de un personaje que, si no hubiera existido en la realidad, habr\u00eda que creado: Francisco Paesa. Un Francisco Paesa que, vivito y coleando, aprovech\u00f3 el estreno de la pel\u00edcula para conceder una de sus maravillosas y enigm\u00e1ticas entrevistas. La vida de Paesa es tan desaforada que Alberto Rodr\u00edguez se ha centrado, exclusivamente, en el c\u00e9lebre episodio de la huida, paso a la clandestinidad y entrega de Rold\u00e1n, un personaje que hubiera encajado como un guante en los tebeos de Ib\u00e1\u00f1ez y que, sin embargo, fue director de la Guardia Civil y casi, casi Ministro del Interior del gobierno socialista.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/el-hombre-de-las-mil-caras-fotograma\/\" rel=\"attachment wp-att-20556\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20556\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Fotograma-300x170.jpg\" alt=\"El hombre de las mil caras Fotograma\" width=\"300\" height=\"170\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Fotograma-300x170.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Fotograma-644x365.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Fotograma.jpg 660w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cEl hombre de las mil caras\u201d es una lecci\u00f3n de cine, desde el primer fotograma hasta el \u00faltimo. Y un recital interpretativo de un Eduard Fern\u00e1ndez llamado a ganar todos los premios del a\u00f1o por su medida y memorable interpretaci\u00f3n, perfectamente secundado por Carlos Santos y por un Jos\u00e9 Coronado que, por fin, cambia de registro. Sin dejar de ser \u00e9l mismo, por supuesto\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/el-hombre-de-las-mil-caras-alberto-rodriguez\/\" rel=\"attachment wp-att-20557\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20557\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Alberto-Rodr\u00edguez-300x163.jpg\" alt=\"El hombre de las mil caras Alberto Rodr\u00edguez\" width=\"300\" height=\"163\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Alberto-Rodr\u00edguez-300x163.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Alberto-Rodr\u00edguez-644x350.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/El-hombre-de-las-mil-caras-Alberto-Rodr\u00edguez.jpg 735w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y tambi\u00e9n hay que ir al cine a ver \u201cTarde para la ira\u201d, por supuesto. Una pel\u00edcula seca y \u00e1spera como la lija. Una pel\u00edcula que te golpea como un zurdazo de Muhammad Ali, dej\u00e1ndote noqueado en la butaca del cine.<\/p>\n<p style=\"text-align: justify;\">Un atraco frustrado a una joyer\u00eda. Huyen los ladrones. El conductor que esperaba fuera tiene un accidente y es detenido por la polic\u00eda. Pasa el tiempo. Cambio de escenario. Un bar de barrio. Un cliente serio, callado y taciturno. Los due\u00f1os, una pareja joven y optimista cuya hija va a hacer la comuni\u00f3n. Y la camarera, familia suya. Una camarera seca, consumida y hastiada por la vida que, cuando termina su turno tras la barra y sirviendo la terraza, va a la c\u00e1rcel a visitar a su marido, en el bis a bis.<\/p>\n<p style=\"text-align: justify;\">Con esos mimbres, que Ar\u00e9valo cuenta en los cinco primeros impresionantes minutos de la pel\u00edcula, est\u00e1n presentados todos los personajes y algunos de los escenarios en los que transcurrir\u00e1 \u201cTarde para la ira\u201d. A partir de ah\u00ed, una dur\u00edsima historia de venganza y redenci\u00f3n en la que las explosiones de violencia, secas y absolutamente carentes de cualquier pirotecnia, dejan boquiabierto al espectador.<\/p>\n<p style=\"text-align: justify;\">Interpretada por un austero y contenido Antonio de la Torre, la \u00f3pera prima de Ra\u00fal Ar\u00e9valo oscila entre el Noir urbano contempor\u00e1neo y un cine negro rural que recuerda, por momentos, a la violencia mostrada por Saura en \u201cLa caza\u201d o, posteriormente, en \u201cEl s\u00e9ptimo d\u00eda\u201d, en que recrea la matanza de Puerto Hurraco.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/las-mil-caras-de-la-ira\/tarde-para-la-ira-de-la-torre\/\" rel=\"attachment wp-att-20558\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20558\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-de-la-torre-300x200.jpg\" alt=\"Tarde para la ira de la torre\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-de-la-torre-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-de-la-torre-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/10\/Tarde-para-la-ira-de-la-torre.jpg 750w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cEl hombre de las mil caras\u201d y \u201cTarde para la ira\u201d, dos pel\u00edculas excelentes y de una factura t\u00e9cnica impecable. Dos ejemplos de las m\u00faltiples facetas que puede mostrar el Noir, con personajes, tramas, paisajes y situaciones radicalmente diferentes, pero que sirven para completar el mosaico del mejor cine espa\u00f1ol contempor\u00e1neo.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Coinciden en cartelera dos pel\u00edculas extraordinarias, polic\u00edacas, espa\u00f1olas y m\u00e1s negras que el carb\u00f3n. Dos pel\u00edculas que han conquistado al p\u00fablico y a la cr\u00edtica en los exigentes y prestigiosos Festivales de Venecia y San Sebasti\u00e1n. Dos pel\u00edculas que acreditan el extraordinario momento que atraviesa el cine Noir en nuestro pa\u00eds y de las que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10,21,11774],"tags":[7772,13121,11776,13269,11145,13119],"class_list":["post-20553","post","type-post","status-publish","format-standard","hentry","category-cine","category-negra-y-criminal","category-rincon-oscuro","tag-eduard-fernandez","tag-el-hombre-de-las-mil-caras","tag-el-rincon-oscuro","tag-en-el-calor-de-la-noche","tag-granada-noir-2","tag-tarde-para-la-ira"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20553","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20553"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20553\/revisions"}],"predecessor-version":[{"id":20562,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20553\/revisions\/20562"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20553"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20553"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20553"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}