{"id":20492,"date":"2016-10-01T13:21:45","date_gmt":"2016-10-01T12:21:45","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20492"},"modified":"2016-10-02T13:25:13","modified_gmt":"2016-10-02T12:25:13","slug":"festival-independiente-de-la-chana","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/festival-independiente-de-la-chana\/","title":{"rendered":"Festival Independiente de la Chana"},"content":{"rendered":"<p>Hoy s\u00e1bado, que deber\u00eda haber amanecido bueno y soleado, an\u00edmense a acercarse a La Chana, al Parque de las Alquer\u00edas, para disfrutar de las m\u00faltiples propuestas del FICH, un Festival voluntariosa y brillantemente organizado por los vecinos del inquieto, participativo y activo barrio granadino.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Me gustan propuestas como el FICH, multidisciplinares y abiertas a todos los p\u00fablicos, con espacios para disfrutar de actividades de lo m\u00e1s diverso, desde el Ecoespacio y el Espacio Solidario al Act\u00edvate o al muy provocador Expr\u00e9sate, para fomentar la libre difusi\u00f3n de ideas. Y est\u00e1n, por supuesto, los escenarios para la m\u00fasica, a la ca\u00edda de la tarde.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Me gusta la filosof\u00eda de un festival que busca fomentar la convivencia entre culturas, el respeto entre generaciones, la participaci\u00f3n ciudadana, la ecolog\u00eda, la solidaridad y el cuidado y buen uso de los espacios p\u00fablicos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero, \u00bfsaben lo mejor de todo? Que esos buenos prop\u00f3sitos se convierten en realidades palpables y tangibles. S\u00e9 de lo que hablo, que el a\u00f1o pasado, los organizadores tuvieron el detalle de invitarme a participar en una charla sobre deporte en la naturaleza y tuvimos ocasi\u00f3n de compartir una hora de agradable e instructiva conversaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Vayan, vayan hoy s\u00e1bado a ese Parque de las Alquer\u00edas con sus peque\u00f1uelos, si fuera el caso, que hay espacios y actividades para los ni\u00f1os. Y d\u00e9jense envolver por la sensaci\u00f3n de compartir un espacio p\u00fablico que, en ocasiones como \u00e9sta, demuestra su aut\u00e9ntica y real utilidad y el sentido que deber\u00eda tener.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Desde que el a\u00f1o pasado conoc\u00ed a ese pu\u00f1ado de j\u00f3venes que tiran del carro del FICH, he ido siguiendo la cantidad de actividades en que participan y las muchas cosas que hacen y organizan, empezando por su grupo de m\u00fasica.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Los \u00c1lex Pereira y compa\u00f1\u00eda son esa otra juventud que tambi\u00e9n existe y que, como en el caso de Teruel, merece tener m\u00e1s visibilidad y reconocimiento. Una juventud activa y participativa, preocupada por las cuestiones pol\u00edticas y sociales del momento, involucrada en movimientos ciudadanos y cultural e intelectualmente muy preparada.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Vayan hoy al Parque de las Alquer\u00edas a disfrutar de los talleres y mesas redondas previstas (una sobre la problem\u00e1tica del AVE); de las exposiciones de fotos antiguas del barrio y de pintura de los vecinos y de un largo etc\u00e9tera de actividades. Incluida una paella popular a mediod\u00eda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Hoy s\u00e1bado, que deber\u00eda haber amanecido bueno y soleado, an\u00edmense a acercarse a La Chana, al Parque de las Alquer\u00edas, para disfrutar de las m\u00faltiples propuestas del FICH, un Festival voluntariosa y brillantemente organizado por los vecinos del inquieto, participativo y activo barrio granadino. Me gustan propuestas como el FICH, multidisciplinares y abiertas a todos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[13236,11602,11600,11601],"class_list":["post-20492","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-alex-pereira","tag-festival-independiente-de-la-chana","tag-fich","tag-fich-chana"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20492","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20492"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20492\/revisions"}],"predecessor-version":[{"id":20493,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20492\/revisions\/20493"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20492"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20492"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20492"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}