{"id":2038,"date":"2009-04-14T13:57:06","date_gmt":"2009-04-14T12:57:06","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=2038"},"modified":"2009-04-14T13:57:06","modified_gmt":"2009-04-14T12:57:06","slug":"cuando-el-rojo-es-negro","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/cuando-el-rojo-es-negro\/","title":{"rendered":"CUANDO EL ROJO ES NEGRO"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Hace unas semanas anunci\u00e1bamos <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=1967\">la salida de la revista .38<\/a>, en que se inclu\u00eda la rese\u00f1a que os dejo a continuanci\u00f3n, entre otras muchas exquisiteces que os recomiend\u00e9 leer vivamente. \u00bfLo hicist\u00e9is? \ud83d\ude09<\/em>\u00a0<\/p>\n<p style=\"text-align: justify;\">La tercera de las novelas que Almuzara publica en espa\u00f1ol de Qiu Xiaolong supon\u00eda, para m\u00ed, un reto muy importante ya que si el debut del autor chino con \u00abMuerte de una hero\u00edna roja\u00bb me deslumbr\u00f3, la continuaci\u00f3n de las aventuras del inspector Chen, \u00abVisado para Shanghai\u00bb, me dej\u00f3 m\u00e1s bien fr\u00edo.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_00011.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2041 aligncenter\" title=\"Cuando el rojo es negro\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_00011.gif\" alt=\"\" width=\"315\" height=\"445\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_00011.gif 315w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_00011-212x300.gif 212w\" sizes=\"auto, (max-width: 315px) 100vw, 315px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y me dio rabia ya que, con Qiu Xiaolong se inici\u00f3 mi fascinaci\u00f3n por ese Crimen Globalizado que nos lleva a leer tramas negras y polic\u00edacas que se desarrollan en escenarios tan distintos a los habituales del g\u00e9nero, de Suecia e Islandia a Tailandia, Camboya o, como en este caso, China.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Una China sumida en cambios tan vertiginosos como inasibles para buena parte de la poblaci\u00f3n. Entre ellos, el de la vivienda y la construcci\u00f3n. Con lo que hemos o\u00eddo hablar sobre la famosa burbuja inmobiliaria, la especulaci\u00f3n urban\u00edstica y la grosera invasi\u00f3n de demenciales centros comerciales que se ha producido en nuestras ciudades, ha tenido que ser un autor chino, residente en EE.UU., el que ponga el dedo en la supurante llaga de uno de los asuntos m\u00e1s candentes de la actualidad del siglo XXI.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_86.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2042 aligncenter\" title=\"Shanghai\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_86.jpg\" alt=\"\" width=\"478\" height=\"308\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_86.jpg 478w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_86-300x193.jpg 300w\" sizes=\"auto, (max-width: 478px) 100vw, 478px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La novela comienza con el inspector Chen tom\u00e1ndose unas vacaciones. Como sus seguidores m\u00e1s ac\u00e9rrimos ya sabemos, para completar el magro sueldo que cobra uno de los mejores polic\u00edas de Shanghai por el ejercicio de su cargo y gracias a su vocaci\u00f3n literaria, ha de hacer traducciones del ingl\u00e9s al chino, sobre todo, de novelas polic\u00edacas. Y precisamente por ello, por conocer los entresijos de una sociedad como la yanqui, el todopoderoso se\u00f1or Gu le pide que le ayude con un trabajo muy especial: la traducci\u00f3n del proyecto Nuevo Mundo, un futuro centro comercial vanguardista que se construir\u00e1 en el coraz\u00f3n de la ciudad y que ser\u00e1 una recreaci\u00f3n de la cosmopolita y chispeante Shanghai de los a\u00f1os treinta; un proyecto a caballo entre lo cultural y lo comercial que&#8230; bueno. Ya se ver\u00e1 en qu\u00e9 acaba desembocando.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_322.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2043 aligncenter\" title=\"Qiu Xiaolong\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_322.jpg\" alt=\"\" width=\"337\" height=\"450\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_322.jpg 337w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_322-224x300.jpg 224w\" sizes=\"auto, (max-width: 337px) 100vw, 337px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y mientras, en un <em>Shikumen<\/em>, una aut\u00e9ntica casa antigua y tradicional de Shanghai, una de esas casas enormes que se han ido parcelando y cuarteando para albergar a decenas de inquilinos, aparece muerta una mujer muy especial, famosa por haber escrito una pol\u00e9mica novela bastante cr\u00edtica con el sistema y conocida por una antigua historia de amor con un intelectual purgado en la Revoluci\u00f3n Cultural. \u00a0<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_292.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2039 aligncenter\" title=\"Shanghai\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_292.jpg\" alt=\"\" width=\"500\" height=\"328\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_292.jpg 599w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_292-300x196.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De la resoluci\u00f3n de este caso se encargar\u00e1 el detective Yu, ayudante de Chen, que tendr\u00e1 una inmejorable oportunidad de demostrar que es un gran polic\u00eda y que sabe volar solo.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Lo mejor de la novela, adem\u00e1s de esas continuas referencias a los cl\u00e1sicos de la poes\u00eda china (<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=1839\">unos cuaversos le dedicamos<\/a>)\u00a0que pespuntean la acci\u00f3n, que a muchos irritan y a m\u00ed me encantan; es la doble dimensi\u00f3n de la historia de la China que nos plantea Xiaolong, como espejos que se miran, enfrentados, mostrando los sue\u00f1os de un tiempo, devenidos en pesadilla a\u00f1os despu\u00e9s.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_0343.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-2040 aligncenter\" title=\"poes\u00eda china\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_0343.jpg\" alt=\"\" width=\"392\" height=\"600\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_0343.jpg 392w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/04\/_0343-196x300.jpg 196w\" sizes=\"auto, (max-width: 392px) 100vw, 392px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, sin embargo, toda la novela transmite un cierto optimismo y esperanza en un futuro en que lo individual termina teniendo preeminencia sobre un sue\u00f1o colectivista que se ha demostrado tan imposible como catastr\u00f3fico.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00abCuando el rojo es negro\u00bb nos reconcilia con un Qiu Xiaolong anal\u00edtico de la actualidad de un pa\u00eds que es todo un universo en s\u00ed mismo, atractivo, fascinante, contradictorio&#8230; Una gran novela.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hace unas semanas anunci\u00e1bamos la salida de la revista .38, en que se inclu\u00eda la rese\u00f1a que os dejo a continuanci\u00f3n, entre otras muchas exquisiteces que os recomiend\u00e9 leer vivamente. \u00bfLo hicist\u00e9is? \ud83d\ude09\u00a0 La tercera de las novelas que Almuzara publica en espa\u00f1ol de Qiu Xiaolong supon\u00eda, para m\u00ed, un reto muy importante ya que [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[48,548,875,49,67,21,552],"class_list":["post-2038","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-almuzara","tag-cuando-el-rojo-es-negro","tag-leer","tag-libros","tag-literatura","tag-negra-y-criminal","tag-qiu-xiaolong"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/2038","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=2038"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/2038\/revisions"}],"predecessor-version":[{"id":2044,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/2038\/revisions\/2044"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=2038"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=2038"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=2038"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}