{"id":20346,"date":"2016-09-14T14:56:45","date_gmt":"2016-09-14T13:56:45","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20346"},"modified":"2016-09-14T14:56:45","modified_gmt":"2016-09-14T13:56:45","slug":"50-anos-de-a-sangre-fria","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/","title":{"rendered":"50 a\u00f1os de \u00abA sangre fr\u00eda\u00bb"},"content":{"rendered":"<p>El primer cap\u00edtulo de \u201cA sangre fr\u00eda\u201d se titula \u201cLos \u00faltimos que los vieron vivos\u201d y nunca podr\u00e9 olvidar cu\u00e1ndo y d\u00f3nde empec\u00e9 a leerlo, dado que aqu\u00e9l se convirti\u00f3 en uno de mis momentos fundacionales como lector.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/a-sangre-fria-anagrama\/\" rel=\"attachment wp-att-20347\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20347\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Anagrama-189x300.jpg\" alt=\"A sangre fr\u00eda Anagrama\" width=\"189\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Anagrama-189x300.jpg 189w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Anagrama.jpg 540w\" sizes=\"auto, (max-width: 189px) 100vw, 189px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Publicada en 1966, tras siete a\u00f1os de intenso trabajo, \u201cA sangre fr\u00eda\u201d se convirti\u00f3 en un cl\u00e1sico inmediato, consagrando a Truman Capote entre los m\u00e1s grandes creadores de la historia de la literatura norteamericana y dando lugar al nacimiento de un nuevo g\u00e9nero literario: la novela de no ficci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A estas alturas est\u00e1 un\u00e1nimemente admitido que, en realidad, esta modalidad narrativa, basada en el periodismo de investigaci\u00f3n que utiliza las herramientas de la ficci\u00f3n para contar una historia real, no fue inventada por Capote. En 1957, por ejemplo, el argentino Rodolfo Walsh publicaba su imprescindible \u201cOperaci\u00f3n Masacre\u201d, empleando una t\u00e9cnica parecida a la de Capote. Pero ya sabemos c\u00f3mo son los norteamericanos con esto de sentirse pioneros y con el marketing\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El New York Times del 16 de noviembre de 1959 tra\u00eda una noticia fechada el d\u00eda anterior, en Holcomb, Kansas, que arrancaba as\u00ed: \u201cUn honrado granjero, su mujer y sus dos j\u00f3venes hijos aparecieron asesinados por arma de fuego en su casa\u2026 No hab\u00eda se\u00f1ales de lucha y ning\u00fan objeto hab\u00eda sido robado\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/a-sangre-fria-periodicos\/\" rel=\"attachment wp-att-20348\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20348\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-periodicos-300x186.jpg\" alt=\"A sangre fr\u00eda periodicos\" width=\"300\" height=\"186\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-periodicos-300x186.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-periodicos.jpg 420w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Las trescientas palabras del art\u00edculo despertaron tal curiosidad en Capote que decidi\u00f3 irse a Kansas, sobre la marcha, para interesarse por el cu\u00e1druple asesinato de la familia Clutter, del que nada se sab\u00eda y que parec\u00eda carecer de cualquier l\u00f3gica o sentido. Adem\u00e1s, y para que le facilitara las relaciones con los habitantes del peque\u00f1o pueblo de Holcomb; el cosmopolita, refinado y siempre excesivo Truman le pidi\u00f3 ayuda a su amiga Harper Lee. La misma Harper Lee que, a\u00f1os despu\u00e9s, ganar\u00eda el Pulitzer por su memorable \u201cMatar a un ruise\u00f1or\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Capote encaj\u00f3 en Holcomb con la misma naturalidad con la que un marciano verde encajar\u00eda en el sal\u00f3n de nuestra casa y su relaci\u00f3n con los habitantes del pueblo fue tan tensa que, a los cuatro d\u00edas de estar all\u00ed, quer\u00eda abandonar su proyecto de investigaci\u00f3n y volver a la m\u00e1s acogedora Nueva York. Pero Harper Lee le convenci\u00f3 de que perseverara, anim\u00e1ndole en los peores momentos y relajando el ambiente enrarecido que generaba la presencia del sofisticado y caprichoso Capote en un pueblo agr\u00edcola, eminentemente tradicional y conservador.<\/p>\n<figure id=\"attachment_20349\" aria-describedby=\"caption-attachment-20349\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/truman-capote-and-harper-lee\/\" rel=\"attachment wp-att-20349\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20349\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote-y-Harper-Lee-300x198.jpg\" alt=\"1966, Holcomb, Kansas --- Truman Capote signing copies of his book  with Harper Lee.  Capote and Lee are in Kansas during  the making of the film of the same name.   --- Image by \u00a9 Steve Schapiro\/Corbis\" width=\"300\" height=\"198\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote-y-Harper-Lee-300x198.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote-y-Harper-Lee.jpg 525w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-20349\" class=\"wp-caption-text\">1966, Holcomb, Kansas &#8212; Truman Capote signing copies of his book with Harper Lee. Capote and Lee are in Kansas during the making of the film of the same name. &#8212; Image by \u00a9 Steve Schapiro\/Corbis<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Durante el d\u00eda, Capote y Lee hablaban con todo el mundo, especialmente con el sheriff encargado de la investigaci\u00f3n. Lo hac\u00edan de forma espont\u00e1nea, sin tomar notas que pudieran condicionar las conversaciones con la gente. Por la noche, en el hotel, escrib\u00edan los resultados del trabajo del d\u00eda con la mayor exactitud posible. Un trabajo tan descomunal que lleg\u00f3 a sumar, al final de la investigaci\u00f3n de Capote, m\u00e1s de 8.000 p\u00e1ginas de valioso material.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El 30 de diciembre de 1959, Dick Hickok y Perry Smith fueron detenidos como sospechosos del asesinato de los Clutter. Capote pudo ser testigo, en primera persona, de los interrogatorios a los que fueron sometidos, pudo entrevistarse con ellos y con sus abogados mientras segu\u00edan sosteniendo su inocencia y tambi\u00e9n posteriormente, cuando confesaron sus cr\u00edmenes.<\/p>\n<figure id=\"attachment_20350\" aria-describedby=\"caption-attachment-20350\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/a-sangre-fria-holcomb\/\" rel=\"attachment wp-att-20350\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20350\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Holcomb-300x193.jpg\" alt=\"Actual aspecto de la granja en que los Clutter fueron asesinados\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Holcomb-300x193.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Holcomb-644x413.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/A-sangre-fr\u00eda-Holcomb.jpg 720w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-20350\" class=\"wp-caption-text\">Actual aspecto de la granja en que los Clutter fueron asesinados<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">El escritor asisti\u00f3 a todas y cada una de las sesiones del juicio en que fueron declarados culpables y, una vez terminado el mismo, el 26 de abril de 1960, desembarc\u00f3 en Palam\u00f3s, en la Costa Brava, acompa\u00f1ado de su compa\u00f1ero sentimental, Jack Dunphy, de un par de perros, una gata\u2026 y un descomunal equipaje.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Dieciocho meses repartidos en tres veranos pas\u00f3 Capote en Palam\u00f3s, poniendo en orden sus notas y escribiendo minuciosamente todas y cada una de las palabras que componen las 343 precisas y preciosas p\u00e1ginas de \u201cA sangre fr\u00eda\u201d.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/truman-capote\/\" rel=\"attachment wp-att-20351\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20351\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote-300x296.png\" alt=\"Truman Capote\" width=\"300\" height=\"296\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote-300x296.png 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Truman-Capote.png 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">A lo largo de esos a\u00f1os, Capote mantuvo el contacto con Perry Smith: adem\u00e1s de un fluido intercambio de cartas, lo visit\u00f3 en prisi\u00f3n varias veces. Hasta llegar al 14 de abril de 1965, cuando fue testigo de su ejecuci\u00f3n por ahorcamiento, sentencia impuesta a los asesinos, convictos y confesos, por el Tribunal de Kansas. Lo hizo invitado por el propio Perry, con el que Capote hab\u00eda desarrollado una relaci\u00f3n tan \u00edntima y personal que algunos llegaron incluso a calificar de amorosa.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Finalmente, el 25 de septiembre de 1965, la revista The New Yorker public\u00f3 la primera entrega de una obra que, dividida en cuatro partes, caus\u00f3 sensaci\u00f3n desde el primer momento, aclamada por la cr\u00edtica y un p\u00fablico \u00e1vido de seguir leyendo \u201cA sangre fr\u00eda\u201d. En Kansas, por ejemplo, la revista se agotaba nada m\u00e1s ponerse a la venta en los quioscos de todo el estado. Y, por fin, en enero de 1966, la obra maestra de Truman Capote vio la luz en forma de libro, publicado por Random House.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Al poco tiempo de ser publicado, \u201cA sangre fr\u00eda\u201d comenz\u00f3 a recibir cr\u00edticas acerca de las libertades creativas y las licencias que se hab\u00eda tomado el autor, sobre todo a la hora de recrear ciertos di\u00e1logos. Que le hab\u00eda echado mucha literatura a la novela, en pocas palabras. Lo que es muy posible. Pero, llegados a este punto, \u00bfqu\u00e9 m\u00e1s da?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/50-anos-de-a-sangre-fria\/holcomb-kansas\/\" rel=\"attachment wp-att-20352\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20352\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas-300x169.jpg\" alt=\"Holcomb Kansas\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas-768x432.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas-1024x575.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/09\/Holcomb-Kansas.jpg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Cincuenta a\u00f1os despu\u00e9s, \u201cA sangre fr\u00eda\u201d sigue siendo una obra referencial en el mundo de la literatura y del periodismo, una pieza maestra de un nuevo e incipiente g\u00e9nero que, a partir de entonces, empez\u00f3 a ser frecuentado por narradores de todos los pa\u00edses, culturas, idiomas y extracciones. Una novela b\u00e1sica, tambi\u00e9n, para los amantes del g\u00e9nero negro y criminal que el Festival Granada Noir homenajear\u00e1 dentro de unas semanas con motivo de tan singular efem\u00e9ride.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El primer cap\u00edtulo de \u201cA sangre fr\u00eda\u201d se titula \u201cLos \u00faltimos que los vieron vivos\u201d y nunca podr\u00e9 olvidar cu\u00e1ndo y d\u00f3nde empec\u00e9 a leerlo, dado que aqu\u00e9l se convirti\u00f3 en uno de mis momentos fundacionales como lector. Publicada en 1966, tras siete a\u00f1os de intenso trabajo, \u201cA sangre fr\u00eda\u201d se convirti\u00f3 en un cl\u00e1sico [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,21,11774],"tags":[13162,13161,3686,11145,13160,13163,13159],"class_list":["post-20346","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-negra-y-criminal","category-rincon-oscuro","tag-50-anos-a-sangre-fria","tag-a-sangre-fria","tag-aulacine-cajagranada","tag-granada-noir-2","tag-granada-noir-a-sangre-fria","tag-in-cold-blood","tag-truman-capote"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20346","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20346"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20346\/revisions"}],"predecessor-version":[{"id":20354,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20346\/revisions\/20354"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20346"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20346"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20346"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}