{"id":20167,"date":"2016-08-24T08:03:52","date_gmt":"2016-08-24T07:03:52","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=20167"},"modified":"2016-08-24T08:03:53","modified_gmt":"2016-08-24T07:03:53","slug":"literatos-granadinos-premiados","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/literatos-granadinos-premiados\/","title":{"rendered":"Literatos granadinos premiados"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a1Buenas noticias! Antes de que llegue la rentr\u00e9 de septiembre con sus novedades literarias y con los estrenos cinematogr\u00e1ficos de los Festivales de Venecia y Donosti, recibimos la buena nueva de que nuestro paisano Rafael Ruiz Pleguezuelos se ha hecho acreedor del II Premio de Teatro Breve Francisco Nieva.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/literatos-granadinos-premiados\/rafael-ruiz-pleguezuelos\/\" rel=\"attachment wp-att-20168\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20168\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Rafael-Ruiz-Pleguezuelos-300x169.jpg\" alt=\"Rafael Ruiz Pleguezuelos\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Rafael-Ruiz-Pleguezuelos-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Rafael-Ruiz-Pleguezuelos.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Una buena nueva que se une a la consecuci\u00f3n por parte del tambi\u00e9n granadino Jos\u00e9 Mar\u00eda Espinar del XX Premio de Novela Negra de Getafe, noticia que conocimos a finales del pasado mes de julio. Un verano fruct\u00edfero, pues, para nuestros escritores, que el editor Miguel \u00c1ngel C\u00e1liz tambi\u00e9n gan\u00f3 otro premio nacional, convocado por Turpial. Pero ya hablaremos de estos libros cuando los leamos. Que hoy, mi columna de IDEAL se centra en Rafael Ruiz.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Hace unos meses tuve la suerte de presentar \u201cLa botella de Bukowski\u201d, la primera novela de Rafael Ruiz Pleguezuelos, en la inquieta y activa librer\u00eda Agapea de la calle Puentezuelas. No conoc\u00ed a Rafael hasta un par de horas antes de la presentaci\u00f3n. Hab\u00edamos quedado para ponernos de acuerdo en nuestras respectivas intervenciones\u2026 y para charlar de literatura.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/literatos-granadinos-premiados\/la-botella-de-bukowski-2\/\" rel=\"attachment wp-att-20169\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-20169\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/La-botella-de-Bukowski-194x300.jpg\" alt=\"La botella de Bukowski\" width=\"194\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/La-botella-de-Bukowski-194x300.jpg 194w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/La-botella-de-Bukowski.jpg 400w\" sizes=\"auto, (max-width: 194px) 100vw, 194px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Confieso que acud\u00ed un tanto abrumado a la cita, que Rafael es doctor en Filolog\u00eda Inglesa y licenciado en Filolog\u00eda Hisp\u00e1nica y Teor\u00eda de la Literatura. Pero todas las prevenciones se vinieron felizmente abajo en cuanto cruzamos dos palabras y le vi sonre\u00edr. Una sonrisa franca y abierta, seguida de una conversaci\u00f3n l\u00facida y apasionada, alejada de cualquier asomo de pedanter\u00eda.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">No s\u00e9 qu\u00e9 les parecer\u00eda a los asistentes, pero aquella presentaci\u00f3n nos sali\u00f3 de maravilla, aunque est\u00e9 feo que yo lo diga. Estuvimos hablando un mont\u00f3n de tiempo, nos quitamos -educadamente- la palabra, nos pisamos el uno al otro -con el m\u00e1ximo de los respetos- y, creo, conseguimos interesar y entretener al p\u00fablico presente.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u201cLa botella de Bukowski\u201d es una de las novelas m\u00e1s literarias que he le\u00eddo en los \u00faltimos tiempos. Una novela que habla sobre la necesidad compulsiva de escribir. Y de crear. Y que nos cuenta la historia de un joven letraherido que, en la Francia posterior a Mayo del 68, emprende un viaje inici\u00e1tico con el fin de conocer al alcoh\u00f3lico escritor norteamericano cuya inolvidable aparici\u00f3n en el m\u00edtico programa de televisi\u00f3n de Bernard Pivot provoc\u00f3 toda una conmoci\u00f3n.<\/p>\n<figure id=\"attachment_20170\" aria-describedby=\"caption-attachment-20170\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/literatos-granadinos-premiados\/presentacion-lens-pleguezuelos\/\" rel=\"attachment wp-att-20170\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-20170\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Presentaci\u00f3n-Lens-Pleguezuelos-300x225.jpg\" alt=\"Presentaci\u00f3n en Agapea\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Presentaci\u00f3n-Lens-Pleguezuelos-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/08\/Presentaci\u00f3n-Lens-Pleguezuelos.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-20170\" class=\"wp-caption-text\">Presentaci\u00f3n en Agapea<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">La novela de Rafael Ruiz Pleguezuelas es un encendido, rendido y hermoso canto a la pulsi\u00f3n creativa, que es tanto como decir un canto a la vida y el premio a su m\u00e1s reciente obra de teatro le confirma como uno de los m\u00e1s interesantes escritores granadinos contempor\u00e1neos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Buenas noticias! Antes de que llegue la rentr\u00e9 de septiembre con sus novedades literarias y con los estrenos cinematogr\u00e1ficos de los Festivales de Venecia y Donosti, recibimos la buena nueva de que nuestro paisano Rafael Ruiz Pleguezuelos se ha hecho acreedor del II Premio de Teatro Breve Francisco Nieva. Una buena nueva que se une [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,6],"tags":[13019,13018,12212,13017,13016,12239],"class_list":["post-20167","post","type-post","status-publish","format-standard","hentry","category-literarios","category-opinion","tag-autores-granadinos","tag-jose-maria-espinar","tag-la-botella-de-bukowski","tag-miguel-angel-caliz","tag-premio-francisco-nieva-teatro","tag-rafael-ruiz-pleguezuelos"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20167","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=20167"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20167\/revisions"}],"predecessor-version":[{"id":20172,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/20167\/revisions\/20172"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=20167"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=20167"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=20167"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}