{"id":19935,"date":"2016-07-06T10:17:10","date_gmt":"2016-07-06T09:17:10","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=19935"},"modified":"2016-07-06T10:17:11","modified_gmt":"2016-07-06T09:17:11","slug":"elogio-noir-de-los-hombres-de-verde","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/","title":{"rendered":"Elogio Noir de los hombres de verde"},"content":{"rendered":"<p style=\"text-align: justify;\">A estas alturas, les supongo bien informados sobre la operaci\u00f3n T\u00e9rmyca: la Guardia Civil desat\u00f3 ayer una macrooperaci\u00f3n contra la corrupci\u00f3n en diversos ayuntamientos de toda Espa\u00f1a. Las detenciones practicadas alcanzaron a representantes de las administraciones p\u00fablicas, de empresas privadas y despachos de abogados y a ciudadanos particulares a los que trincaron en sus propios domicilios.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/termyca\/\" rel=\"attachment wp-att-19936\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19936\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Termyca-300x169.jpg\" alt=\"Termyca\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Termyca-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Termyca-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Termyca.jpg 678w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Sin extenderme mucho: se ha desmantelado una presunta trama orquestada para ama\u00f1ar concursos p\u00fablicos en diversos ayuntamientos a favor de empresarios afines, a cambio de regalos, d\u00e1divas y cuchipandas varias por parte de los constructores y empresarios implicados. Entre los delitos imputados a los diferentes detenidos: malversaci\u00f3n y blanqueo de capitales, fraude a la hacienda p\u00fablica, etc\u00e9tera.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Hasta aqu\u00ed, la noticia. Pero volvamos al principio de este art\u00edculo y deteng\u00e1monos un momento en los actores principales: la Guardia Civil. Porque ha querido la casualidad que la operaci\u00f3n T\u00e9rmyca se haya desencadenado justo cuando acabo de leer \u201cLos cuerpos extra\u00f1os\u201d, de Lorenzo Silva.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/los-cuerpos-extranos\/\" rel=\"attachment wp-att-19937\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19937\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Los-cuerpos-extra\u00f1os-177x300.jpg\" alt=\"Los cuerpos extra\u00f1os\" width=\"177\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Los-cuerpos-extra\u00f1os-177x300.jpg 177w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Los-cuerpos-extra\u00f1os.jpg 300w\" sizes=\"auto, (max-width: 177px) 100vw, 177px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cLos cuerpo extra\u00f1os\u201d, publicada en Destino, es la pen\u00faltima novela negra protagonizada por dos de los personajes de referencia en el Noir espa\u00f1ol: los guardias civiles Rub\u00e9n Bevilacqua y Virginia Chamorro, cuya \u00faltima aventura, \u201cDonde los escorpiones\u201d, acaba de ver la luz hace unas semanas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero antes de llevarse a sus personajes de referencia a Afganist\u00e1n, Lorenzo Silva les puso a investigar la muerte de la alcaldesa de un pueblo del Levante espa\u00f1ol. Una investigaci\u00f3n que, por supuesto, sac\u00f3 a la luz un caso de corrupci\u00f3n muy, pero que muy parecido a los que ha destapado la operaci\u00f3n T\u00e9rmyca.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En la novela negra espa\u00f1ola hemos tenido a todo tipo de protagonistas. Al principio, eran detectives privados, cobradores de morosos o periodistas. Durante la Transici\u00f3n y los primeros a\u00f1os de la democracia era imposible que un autor de g\u00e9nero polic\u00edaco que quisiera ser respetado eligiera como personaje principal de sus obras a un polic\u00eda. En aquellos a\u00f1os, eran los representantes de un estado fascista, coercitivo y represor. \u00a1Y no digamos ya a un guardia civil!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Poco a poco y con la consolidaci\u00f3n del r\u00e9gimen democr\u00e1tico, las cosas fueron cambiando y empez\u00f3 a ser posible que el p\u00fablico aceptara a los inspectores de polic\u00eda como protagonistas, en positivo, de las historias negras y criminales. As\u00ed, al detective Pepe Carvalho de Manuel V\u00e1zquez Montalb\u00e1n y al antiguo boxeador Toni Carpintero de Juan Madrid, se fueron a\u00f1adiendo el Gitano Flores de \u201cBrigada Central\u201d, del propio Juan Madrid o la inspectora Petra Delicado, de Alicia Gim\u00e9nez Bartlett.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/pepe-carvalho\/\" rel=\"attachment wp-att-19938\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19938\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/pepe-carvalho-300x215.jpg\" alt=\"pepe carvalho\" width=\"300\" height=\"215\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/pepe-carvalho-300x215.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/pepe-carvalho.jpg 620w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, entonces, la sorpresa. Porque, en 1998, el abogado y novelista Lorenzo Silva gan\u00f3 el Premio Ojo Cr\u00edtico con una novela polic\u00edaca protagonizada por dos guardias civiles: \u201cEl lejano pa\u00eds de los estanques\u201d. Y dos a\u00f1os despu\u00e9s, con \u201cEl alquimista impaciente\u201d, esos mismos guardias, Bevilacqua y Chamorro, le permit\u00edan a Silva consagrarse entre los m\u00e1s grandes, al ganar el prestigioso Premio Nadal.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">A\u00fan recuerdo la controversia que levant\u00f3, en su momento, la elecci\u00f3n de dos guardias civiles como protagonistas de una serie literaria que, hasta la fecha, ya suma nueve t\u00edtulos y cientos de miles de copias vendidas. Hoy, Bevilacqua y Chamorro son dos de los personajes imprescindibles del g\u00e9nero negro y Lorenzo Silva se ha convertido en uno de los grandes referentes del Noir espa\u00f1ol. De hecho, pocos autores son capaces de construir novelas procedimentales tan perfectas como las de Silva.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/el-lejano-pais-de-los-estanques\/\" rel=\"attachment wp-att-19939\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19939\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/El-lejano-pa\u00eds-de-los-estanques-176x300.jpg\" alt=\"El lejano pa\u00eds de los estanques\" width=\"176\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/El-lejano-pa\u00eds-de-los-estanques-176x300.jpg 176w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/El-lejano-pa\u00eds-de-los-estanques.jpg 600w\" sizes=\"auto, (max-width: 176px) 100vw, 176px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfCu\u00e1nto han hecho Bevilacqua y Chamorro por la normalizaci\u00f3n de la imagen de la Guardia Civil en el imaginario colectivo espa\u00f1ol? Las conversaciones entre Vila y Virgi, su relaci\u00f3n personal y laboral, su forma de tratar con jefes y subalternos, su manera de afrontar las investigaciones, sus pies de plomo y su mano izquierda; han conseguido dejar atr\u00e1s el imaginario lorquiano de una Guardia Civil \u00e1grafa, insensible y violenta.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/elogio-noir-de-los-hombres-de-verde\/guardia-civil\/\" rel=\"attachment wp-att-19940\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19940\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil-251x300.jpg\" alt=\"Guardia Civil\" width=\"251\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil-251x300.jpg 251w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil-768x918.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil-857x1024.jpg 857w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil-644x770.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Guardia-Civil.jpg 1339w\" sizes=\"auto, (max-width: 251px) 100vw, 251px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Lean, lean ustedes cualquiera de las novelas de Lorenzo Silva protagonizadas por sus guardias civiles. Novelas en las que el factor humano va m\u00e1s all\u00e1 de la investigaci\u00f3n en curso, no en vano, Bevilacqua es psic\u00f3logo de formaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Adem\u00e1s, hoy es un d\u00eda inmejorable para que ataquen \u201cLos cuerpos extra\u00f1os\u201d con la que Lorenzo Silva cerraba su particular Trilog\u00eda sobre la Corrupci\u00f3n, que empez\u00f3 con \u201cEl alquimista impaciente\u201d y una investigaci\u00f3n sobre los asuntos sucios de la Costa del Sol y sigui\u00f3 con \u201cLa marca del meridiano\u201d, en la que los protagonistas se enfrentan a un caso de corrupci\u00f3n dentro del propio cuerpo de la Guardia Civil.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lean \u201cLos cuerpos extra\u00f1os\u201d. Porque, durante la investigaci\u00f3n de la muerte de la alcaldesa levantina, Vila y Chamorro se las ver\u00e1n con concejales de urbanismo corruptos relacionados con el crimen organizado, con tramas de blanqueo de dinero negro y con siniestras presiones para conseguir la concesi\u00f3n de licencias para negocios turbios como un prost\u00edbulo\u2026 y hasta un casino.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-noir-tras-el-totalitarismo\/rincon-oscuro-lorenzo-silva\/\" rel=\"attachment wp-att-19468\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19468\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Rinc\u00f3n-Oscuro-Lorenzo-Silva-201x300.jpg\" alt=\"Rinc\u00f3n Oscuro Lorenzo Silva\" width=\"201\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Rinc\u00f3n-Oscuro-Lorenzo-Silva-201x300.jpg 201w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Rinc\u00f3n-Oscuro-Lorenzo-Silva.jpg 642w\" sizes=\"auto, (max-width: 201px) 100vw, 201px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y es que hoy d\u00eda, como la operaci\u00f3n T\u00e9rmyca acaba de poner de manifiesto, la Guardia Civil desempe\u00f1a un papel de trascendental importancia en la lucha contra la corrupci\u00f3n que asola Espa\u00f1a.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19473\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19473 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/05\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A estas alturas, les supongo bien informados sobre la operaci\u00f3n T\u00e9rmyca: la Guardia Civil desat\u00f3 ayer una macrooperaci\u00f3n contra la corrupci\u00f3n en diversos ayuntamientos de toda Espa\u00f1a. Las detenciones practicadas alcanzaron a representantes de las administraciones p\u00fablicas, de empresas privadas y despachos de abogados y a ciudadanos particulares a los que trincaron en sus propios [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774],"tags":[12846,146,11776,11145,2726,12843,12844,12845,10716],"class_list":["post-19935","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","tag-bevilacqua-y-chamorro","tag-editorial-destino","tag-el-rincon-oscuro","tag-granada-noir-2","tag-lorenzo-silva","tag-los-cuerpos-extranos","tag-oeracion-termyca-noir","tag-operacion-termyca","tag-trilogia-de-la-crisis"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19935","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=19935"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19935\/revisions"}],"predecessor-version":[{"id":19942,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19935\/revisions\/19942"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=19935"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=19935"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=19935"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}