{"id":19886,"date":"2016-07-01T08:53:33","date_gmt":"2016-07-01T07:53:33","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=19886"},"modified":"2016-07-01T08:53:34","modified_gmt":"2016-07-01T07:53:34","slug":"lo-que-en-realidad-importa","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lo-que-en-realidad-importa\/","title":{"rendered":"Lo que en realidad importa"},"content":{"rendered":"<p style=\"text-align: justify;\">Nada mejor que la aver\u00eda del frigor\u00edfico, en plena can\u00edcula veraniega, para hacerte reflexionar sobre las cosas que realmente importan en la vida. Andaba yo entre autocr\u00edticas y pucherazos, combinando la asunci\u00f3n de responsabilidades con la pr\u00e1ctica de mi mejor sonrisa, cuando fui a beber agua y la encontr\u00e9 templaducha. Ech\u00e9 mano a otra botella, y lo mismo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lo-que-en-realidad-importa\/frigorifico-garfield\/\" rel=\"attachment wp-att-19887\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19887\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Frigor\u00edfico-Garfield-300x203.gif\" alt=\"Frigor\u00edfico Garfield\" width=\"300\" height=\"203\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Les ahorro los detalles t\u00e9cnicos y me voy al momento en que me confirman que tengo que comprar otro frigor\u00edfico. D\u00edas de dudas, visitas del t\u00e9cnico, los congelados amenazando con echarse a perder y una tortilla en la basura, no sea que me agarre una salmonelosis. Y, lo peor: el agua caliente. Y sobre estas cuitas dom\u00e9sticas hablo hoy en mi columna de IDEAL.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Yo soy poco caprichoso y de f\u00e1cil conformar, acostumbrado a comer yogures tan caducados que ser\u00eda la envidia de Arias Ca\u00f1ete. Pero con el agua\u2026 \u00a1con el agua soy un sibarita! Tiene que estar fr\u00eda. No helada. Pero tampoco templada. Fr\u00eda. Que escucho \u201cagua del tiempo\u201d y se me revuelven las tripas. Agua del grifo, s\u00ed. Pero inodora, incolora e ins\u00edpida: el menor sabor a pl\u00e1stico, por ejemplo, me arruina ese placer tan sencillo, pero tan b\u00e1sico: beber un trago de agua fresca.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lo-que-en-realidad-importa\/agua-fresca\/\" rel=\"attachment wp-att-19888\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-19888\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Agua-fresca.jpg\" alt=\"Agua fresca\" width=\"182\" height=\"277\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Cuando se te estropea el frigor\u00edfico te das cuenta de la importancia de un electrodom\u00e9stico b\u00e1sico, sin cuya existencia, la vida se te altera y alborota mucho m\u00e1s de lo que cabr\u00eda esperar. Y, llegados a ese punto, los pactos postelectorales o la llegada del AVE pasan a un segundo plano. De hecho, la cabeza empieza a jugarte malas pasadas y te recuerda que, hace unos meses, tambi\u00e9n se te estrope\u00f3 el microondas. Y la cafetera de c\u00e1psulas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El tiempo, que va pasando. Y la caducidad de los chismes, esa obsolescencia programada que, a modo de <em>memento mori<\/em> tecnol\u00f3gico, te conduce a otras reflexiones: \u00bfCu\u00e1nto tardar\u00e1 en empezar a fallarme el cuerpo? \u00bfSe va acercando la fecha de caducidad de unos tendones demasiado machados, de unas rodillas muy baqueteadas? Y caes en la cuenta de que la espalda te viene avisando, con insistencia, tras cada partido de baloncesto.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/lo-que-en-realidad-importa\/obsolescencia-programada\/\" rel=\"attachment wp-att-19889\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19889\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Obsolescencia-programada-300x200.jpg\" alt=\"Obsolescencia programada\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Obsolescencia-programada-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/07\/Obsolescencia-programada.jpg 500w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ya he encargado otro frigor\u00edfico. En un par de d\u00edas, tendr\u00e9 cubitos de hielo y la tortilla no ser\u00e1 una amenaza para mi salud. Entonces, Rajoy volver\u00e1 a ser una preocupaci\u00f3n. Pero, hoy, lo \u00fanico que me importa es d\u00f3nde pegar un trago de agua fresca.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Nada mejor que la aver\u00eda del frigor\u00edfico, en plena can\u00edcula veraniega, para hacerte reflexionar sobre las cosas que realmente importan en la vida. Andaba yo entre autocr\u00edticas y pucherazos, combinando la asunci\u00f3n de responsabilidades con la pr\u00e1ctica de mi mejor sonrisa, cuando fui a beber agua y la encontr\u00e9 templaducha. Ech\u00e9 mano a otra botella, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12816,12817,12815,12814,12813],"class_list":["post-19886","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-agua-fresca","tag-agua-fria","tag-electrodomesticos","tag-frigorifico-roto","tag-obsolescencia-programada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19886","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=19886"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19886\/revisions"}],"predecessor-version":[{"id":19891,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19886\/revisions\/19891"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=19886"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=19886"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=19886"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}