{"id":19860,"date":"2016-06-28T07:00:32","date_gmt":"2016-06-28T06:00:32","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=19860"},"modified":"2016-06-27T13:58:30","modified_gmt":"2016-06-27T12:58:30","slug":"el-infierno-son-los-otros","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-infierno-son-los-otros\/","title":{"rendered":"El infierno \u00bfson los otros?"},"content":{"rendered":"<p style=\"text-align: justify;\">Ayer fue un d\u00eda dedicado al an\u00e1lisis y a la reflexi\u00f3n en torno al 26-J. Deber\u00eda haber sido, tambi\u00e9n, una jornada de autocr\u00edtica. Pero eso no se estila por estos lares, de forma que la mayor\u00eda de los comentarios <em>progresistas<\/em> que pod\u00edamos escuchar y leer oscilaban entre la estupefacci\u00f3n y el menosprecio a los otros, esos otros que, ignorantes y descerebrados, vagos y acomodaticios; no han votado lo mismo que ellos. Porque ellos, por supuesto, tienen la raz\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=19861\" rel=\"attachment wp-att-19861\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19861\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma-213x300.jpg\" alt=\"El infierno son los otros Pacma\" width=\"213\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma-213x300.jpg 213w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma-768x1080.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma-728x1024.jpg 728w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma-644x905.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Pacma.jpg 1138w\" sizes=\"auto, (max-width: 213px) 100vw, 213px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u00bfY los otros? Los otros son el infierno de Sartre. Los otros son los que votan a los azules o a los naranjas. Los otros son los que votan en blanco. Los otros, en fin, podr\u00edan ser hasta los 184.000 votantes que apoyaron a PACMA, en vez de hacerlo al hipot\u00e9tico gobierno del cambio.<\/p>\n<p style=\"text-align: justify;\">Lo f\u00e1cil, a la hora de analizar los resultados del 26-J, es echarse las manos a la cabeza y despotricar contra los dem\u00e1s. Por ejemplo, contra los abstencionistas. Que han sido muchos menos de lo que parec\u00eda. Al final, un 30%. \u00a1Analicen por qu\u00e9 no son capaces de llevarles a las urnas, en vez de tacharles de poco comprometidos! \u00bfY qu\u00e9 me dicen de los 225.000 votos nulos? \u00bfY de los 178.000 votos en blanco?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=19862\" rel=\"attachment wp-att-19862\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19862\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Manos-cabeza-219x300.jpg\" alt=\"El infierno son los otros Manos cabeza\" width=\"219\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Manos-cabeza-219x300.jpg 219w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-Manos-cabeza.jpg 500w\" sizes=\"auto, (max-width: 219px) 100vw, 219px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y luego est\u00e1n los t\u00f3picos, tan da\u00f1inos. Porque favorecen que la gente se eche a dormir. \u00bfQui\u00e9n se iba a imaginar que el PP ganar\u00eda en Andaluc\u00eda, el feudo de una Susana D\u00edaz convertida en una de las grandes perdedoras del domingo? \u00bfSe fiaron demasiado, los socialistas granadinos, del efecto arrastre de Paco Cuenca y de la Operaci\u00f3n Nazar\u00ed?<\/p>\n<p style=\"text-align: justify;\">Y luego est\u00e1, por supuesto, el fiasco protagonizado por un Pablo Iglesias que, tan aficionado como es a \u201cJuego de Tronos\u201d, deber\u00eda repasar c\u00f3mo terminaba \u201cLa Boda Roja\u201d. Y es que no creo que la HBO le admitiera como guionista, a la vista de un tactismo err\u00f3neo y fallido y de una estrategia m\u00e1s basada en la autocomplacencia y en el \u201ccuanto peor, mejor\u201d que en la capacidad de generar ilusi\u00f3n en la gente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/?attachment_id=19863\" rel=\"attachment wp-att-19863\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19863\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-La-boda-roja-300x225.jpg\" alt=\"El infierno son los otros La boda roja\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-La-boda-roja-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/El-infierno-son-los-otros-La-boda-roja.jpg 480w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pero la culpa nunca es nuestra. Es de los otros. Que no nos entienden. Que son unos ignorantes. Y unos vagos. Por eso, cada vez que o\u00eda lo de \u201c\u00bfC\u00f3mo es posible que\u2026?\u201d me acordaba de Hemingway: \u201cNunca preguntes por qui\u00e9n doblan las campanas, doblan por ti\u201d.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-19740\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-19740 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ayer fue un d\u00eda dedicado al an\u00e1lisis y a la reflexi\u00f3n en torno al 26-J. Deber\u00eda haber sido, tambi\u00e9n, una jornada de autocr\u00edtica. Pero eso no se estila por estos lares, de forma que la mayor\u00eda de los comentarios progresistas que pod\u00edamos escuchar y leer oscilaban entre la estupefacci\u00f3n y el menosprecio a los otros, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12797,12796],"class_list":["post-19860","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-autocritica","tag-manos-a-la-cabeza"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19860","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=19860"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19860\/revisions"}],"predecessor-version":[{"id":19865,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19860\/revisions\/19865"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=19860"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=19860"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=19860"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}