{"id":1944,"date":"2009-03-30T07:30:40","date_gmt":"2009-03-30T06:30:40","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=1944"},"modified":"2009-03-30T08:03:47","modified_gmt":"2009-03-30T07:03:47","slug":"media-maraton-de-segovia-intercajas-cochinillo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/media-maraton-de-segovia-intercajas-cochinillo\/","title":{"rendered":"MEDIA MARAT\u00d3N DE SEGOVIA. INTERCAJAS &#038; COCHINILLO"},"content":{"rendered":"<p style=\"text-align: justify;\">Cuando Fernando Arco\u00a0me dijo que el Intercajas de Atletismo de este a\u00f1o se celebrar\u00eda junto\u00a0 a la Media Marat\u00f3n de Segovia, se me pusieron los ojos de bolilla.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04315.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1947 aligncenter\" title=\"Media marat\u00f3n segovia\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04315.jpg\" alt=\"\" width=\"500\" height=\"384\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04315.jpg 800w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04315-300x230.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Segovia.<\/p>\n<p>\u00a0<\/p>\n<p>Uno de los sitios m\u00e1s fascinantes en los que nunca estuve.<\/p>\n<p>\u00a0<\/p>\n<p>Porque hab\u00eda estado con el colegio de la Caja, en octavo. Pero ya no volv\u00ed. Ni siquiera para disputar uno de los m\u00e1s afamados y reverenciados Intercajas de Baloncesto de los \u00faltimos a\u00f1os, a partir del cu\u00e1l, palabras como cochinillo, judiones de La Granja, ponche segoviano, Jos\u00e9 Mar\u00eda o C\u00e1ndido han estado presentes, habitualmente, en las conversaciones de mis amigos.<\/p>\n<p>\u00a0<\/p>\n<p>As\u00ed que, este fin de semana, Roc\u00edo y yo nos fuimos a correr esa extraordinaria Media Marat\u00f3n de Segovia con Fernando, Christian, Maria Jos\u00e9 y Mari Eu.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04510.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1949 aligncenter\" title=\"Media Marat\u00f3n Segovia\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04510.jpg\" alt=\"\" width=\"500\" height=\"375\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04510.jpg 640w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_04510-300x225.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p>Y triunfamos.<\/p>\n<p>\u00a0<\/p>\n<p style=\"text-align: justify;\">Personalmente, hice mi mejor Media Marat\u00f3n de nunca, o de siempre, con un tiempo de una hora y treinta y ocho minutos, en un terreno totalmente quebrado. Roc\u00edo D\u00edez\u00a0debut\u00f3 triunfalmente en la distancia, consiguiendo culminar uno de los recorridos m\u00e1s duros, pero m\u00e1s bonitos que existen y Mar\u00eda Jos\u00e9 Charneco se trajo la medalla de plata de la categor\u00eda femenina.<\/p>\n<p style=\"text-align: center;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_2912.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-1948 aligncenter\" title=\"Media Marat\u00f3n Segovia\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_2912.jpg\" alt=\"\" width=\"500\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_2912.jpg 800w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2009\/03\/_2912-300x180.jpg 300w\" sizes=\"auto, (max-width: 500px) 100vw, 500px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Como resumen, antes de un desarrollo m\u00e1s completo de la prueba, diremos que en Segovia, CajaGRANADA termin\u00f3 s\u00e9ptima, por equipos, la mejor clasificaci\u00f3n de su historia, precisamente en el recorrido m\u00e1s duro y exigente que imaginarse pueda, con unos Fernando Arco y Christian Castillo Bueno absolutamente imperiales, bajando ambos de la hora y media.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">\u00bfY ahora?<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Pues ahora toca recuperar este <a href=\"http:\/\/lasverdesgranada.blogspot.com\/2009\/03\/elogio-de-las-agujetas.html\">Elogio a las Agujetas<\/a>, despu\u00e9s de apenas haber dormido en una noche de carretera, autob\u00fas, lectura e insomnio.<\/p>\n<p style=\"text-align: justify;\">\u00a0<\/p>\n<p style=\"text-align: justify;\">Pronto m\u00e1s.<\/p>\n<p>\u00a0<\/p>\n<p>Mucho m\u00e1s.<\/p>\n<p>\u00a0<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Cuando Fernando Arco\u00a0me dijo que el Intercajas de Atletismo de este a\u00f1o se celebrar\u00eda junto\u00a0 a la Media Marat\u00f3n de Segovia, se me pusieron los ojos de bolilla. \u00a0 Segovia. \u00a0 Uno de los sitios m\u00e1s fascinantes en los que nunca estuve. \u00a0 Porque hab\u00eda estado con el colegio de la Caja, en octavo. Pero [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34],"tags":[857,856,862,34,859,855,54,861,854,853,860],"class_list":["post-1944","post","type-post","status-publish","format-standard","hentry","category-correr","tag-acueducto","tag-cajasegovia","tag-christian-castillo","tag-correr","tag-fernando-arco","tag-intercajas-media-maraton","tag-las-verdes","tag-maria-jose-charneco","tag-media-maraton","tag-media-maraton-segovia","tag-rocio-diez"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/1944","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=1944"}],"version-history":[{"count":4,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/1944\/revisions"}],"predecessor-version":[{"id":1946,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/1944\/revisions\/1946"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=1944"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=1944"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=1944"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}