{"id":19234,"date":"2016-04-03T13:34:23","date_gmt":"2016-04-03T12:34:23","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=19234"},"modified":"2016-04-03T13:34:23","modified_gmt":"2016-04-03T12:34:23","slug":"la-subasta-malaya","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/la-subasta-malaya\/","title":{"rendered":"La Subasta Malaya"},"content":{"rendered":"<p style=\"text-align: justify;\">Escribo estas l\u00edneas bien temprano, el s\u00e1bado por la ma\u00f1ana. He quedado para salir a correr por la monta\u00f1a, dentro de un rato, con mis colegas de las Cabras Locas. Seg\u00fan ellos, vamos a estirar las piernas. En realidad, s\u00e9 que acabar\u00e9 estirando la pata, as\u00ed que prefiero dejar los deberes hechos y enviar cuanto antes esta columna para el IDEAL de hoy domingo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19235\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709-169x300.jpg\" alt=\"Las Cabras Locas\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709-169x300.jpg 169w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709-576x1024.jpg 576w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709-644x1145.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/IMG_3709.jpg 900w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Les cuento esto porque a m\u00ed me gusta escribir mis art\u00edculos bien entrada la tarde, que a primera hora de la ma\u00f1ana me resulta muy complicado tener ninguna opini\u00f3n, sea fundada o por fundar. Necesito leer la prensa y escuchar los an\u00e1lisis de los especialistas, palpar el ambiente de las calles y charlar con conocidos, amigos y colegas. Hoy, por ejemplo, habr\u00eda sido un gran d\u00eda para pasar por la pescader\u00eda, a ver qu\u00e9 se cuentan\u2026<\/p>\n<p style=\"text-align: justify;\">Decido, pues, asomarme a esa otra ventana a la realidad que es Internet. Y, tras una procelosa navegaci\u00f3n, acabo recalando en un puerto de resonancias m\u00edticas: la subasta malaya.<\/p>\n<p style=\"text-align: justify;\">Les aconsejo que visiten ese puerto. \u00a1Qu\u00e9 maravilla! Impresionante, el portal de subastas que liquidar\u00e1 el patrimonio acumulado por Juan Antonio Roca, valorado en 75 millones de euros. Comienzo por la pesta\u00f1a de \u201cInmuebles\u201d, pero como no tengo cash para pujar por los 27 kilos de la Finca La Loma, y los \u00e1ticos de Marbella o las casas de Ibiza no me llaman, me paso a la secci\u00f3n de \u201cAtraques\u201d, que me gusta c\u00f3mo suena. Sin embargo, gastarme 800.000 euros en el Puesto de Atraque 101 de Puerto Ban\u00fas tampoco me encaja. M\u00e1s que nada, porque los impuestos no est\u00e1n incluidos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1_5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19236\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1_5-300x168.jpg\" alt=\"Subasta Malaya\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1_5-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1_5-644x361.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1_5.jpg 980w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Me voy, por tanto, a \u201cOtros bienes\u201d. Armas, caballos, carruajes, l\u00e1tigos, monturas\u2026 \u00a1el para\u00edso para un amante del western! Pero no. No es eso lo que busco. Porque, imbuido por el esp\u00edritu de los \u201c47 Ronin\u00bb y las aventuras de Usagi Yojimbo de Stan Sakai, protagonista del Sal\u00f3n del C\u00f3mic de Granada de este a\u00f1o, <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/comics-en-puerta-real\/\" target=\"_blank\">tal y como dec\u00edamos ayer<\/a>; lo que yo ans\u00edo tener en mi casa es la armadura japonesa completa de Juan Antonio Roca.<\/p>\n<p style=\"text-align: justify;\">\u00a1Una maravillosa armadura de samurai, de comienzos del siglo XX! Desde que he sabido de su existencia, no puedo conciliar el sue\u00f1o.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1459513120_424040_1459515833_noticia_fotograma.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-19237\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1459513120_424040_1459515833_noticia_fotograma-300x169.jpg\" alt=\"Armadura Japonesa siglo XX\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1459513120_424040_1459515833_noticia_fotograma-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1459513120_424040_1459515833_noticia_fotograma-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/04\/1459513120_424040_1459515833_noticia_fotograma.jpg 980w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De hecho, ya no concibo mi vida sin ella. Me dan igual los relojes, los cuadros o las esculturas. Paso hasta de la selecci\u00f3n de vinos, tasada en 280.000\u20ac. \u00a1La armadura, la armadura! \u00a1Yo me pido la armadura!<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18919 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Escribo estas l\u00edneas bien temprano, el s\u00e1bado por la ma\u00f1ana. He quedado para salir a correr por la monta\u00f1a, dentro de un rato, con mis colegas de las Cabras Locas. Seg\u00fan ellos, vamos a estirar las piernas. En realidad, s\u00e9 que acabar\u00e9 estirando la pata, as\u00ed que prefiero dejar los deberes hechos y enviar cuanto [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34,6],"tags":[12289,12290,12291,12288,12292],"class_list":["post-19234","post","type-post","status-publish","format-standard","hentry","category-correr","category-opinion","tag-armadura-japonesa","tag-cabras-locas","tag-correr-como-cabras-locas","tag-subasta-malaya","tag-subasta-patrimonio-roca"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19234","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=19234"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19234\/revisions"}],"predecessor-version":[{"id":19238,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/19234\/revisions\/19238"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=19234"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=19234"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=19234"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}