{"id":18934,"date":"2016-02-21T12:33:02","date_gmt":"2016-02-21T11:33:02","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18934"},"modified":"2016-02-22T12:37:44","modified_gmt":"2016-02-22T11:37:44","slug":"eco-en-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/eco-en-granada\/","title":{"rendered":"Eco en Granada"},"content":{"rendered":"<p style=\"text-align: justify;\">Tiro de hemeroteca para recordar con exactitud c\u00f3mo transcurrieron las dos \u00fanicas ediciones del Hay Festival que se celebraron en Granada, unos a\u00f1os atr\u00e1s. Es la \u00fanica vez, que yo recuerde, en que se ha cobrado la entrada para escuchar hablar a los escritores. Algo in\u00e9dito y sorprendente.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Alhambra.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18935\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Alhambra-300x212.jpg\" alt=\"Hay Festival Alhambra\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Alhambra-300x212.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Alhambra-644x455.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Alhambra.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Un Hay Festival que trajo a Orham Pamuk, a Juan Goytisolo, a Francisco Ayala y a diferentes autores de Oriente. Y a Umberto Eco, que disert\u00f3 en nuestra ciudad sobre \u201cEl mundo de los signos: lo feo y lo falso\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Me resulta muy curioso leer una de las cosas que Eco dijo en la rueda de prensa previa a su intervenci\u00f3n: la memoria medi\u00e1tica es muy breve, lo que me consuela mucho, ya que hoy puedes decir cosas horribles que ma\u00f1ana aparecen en los peri\u00f3dicos, pero un d\u00eda despu\u00e9s todos lo han olvidado. Es terrible pero es un modo tambi\u00e9n de salvarse, conclu\u00eda Eco.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Umberto-Eco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18936\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Umberto-Eco-300x200.jpg\" alt=\"Hay Festival Umberto Eco\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Umberto-Eco-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Umberto-Eco-644x430.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Umberto-Eco.jpg 657w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En esto, el tiempo no le ha dado la raz\u00f3n. Ahora, la memoria medi\u00e1tica es elefanti\u00e1sica y es tan importante tener capturas de pantalla comprometedoras como seguir confeccionando aquellos famosos dossieres de los servicios secretos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Tambi\u00e9n recuerdo que el primer Hay Festival fue muy criticado por una parte de la intelligentsia granadina, que lo tach\u00f3 de elitista y de no contar con los autores locales en las diferentes mesas, conferencias, encuentros y presentaciones. A m\u00ed, aquello me sorprendi\u00f3 mucho. Emocionado como estaba de poder escuchar a escritores que rara vez hab\u00edamos tenido en Granada, no entend\u00eda aquel lamento.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La realidad, tozuda, termin\u00f3 imponi\u00e9ndose un a\u00f1o despu\u00e9s, cuando el patrocinador principal del Hay Festival granadino se ape\u00f3 del carro y no hubo voluntad institucional ni m\u00fasculo financiero para sostener un proyecto literariamente muy excitante. Desde entonces, pocas oportunidades hemos tenido para escuchar a algunas de las grandes luminarias de la palabra y el pensamiento mundiales en nuestra tierra.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Sin embargo, para seguir vi\u00e9ndonos y escuch\u00e1ndonos los de siempre, siempre ha habido momento y ocasi\u00f3n. La visita de Eco queda en el recuerdo como otra oportunidad que Granada dej\u00f3 escapar para incorporarse al circuito internacional de grandes citas culturales. Primero fue el m\u00edtico Esp\u00e1rrago Rock. Despu\u00e9s, el maravilloso Womad. Finalmente, el Hay Festival.<\/p>\n<figure id=\"attachment_18937\" aria-describedby=\"caption-attachment-18937\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Womad.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-18937\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Womad-300x169.jpg\" alt=\"Womad C\u00e1ceres\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Womad-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Hay-Festival-Womad.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-18937\" class=\"wp-caption-text\">Womad C\u00e1ceres<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Menos mal que nos quedan los Festivales de Jazz y el de M\u00fasica y Danza, que nos siguen trayendo a grandes estrellas internacionales.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18928 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Twitter-Lens1.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tiro de hemeroteca para recordar con exactitud c\u00f3mo transcurrieron las dos \u00fanicas ediciones del Hay Festival que se celebraron en Granada, unos a\u00f1os atr\u00e1s. Es la \u00fanica vez, que yo recuerde, en que se ha cobrado la entrada para escuchar hablar a los escritores. Algo in\u00e9dito y sorprendente. Un Hay Festival que trajo a Orham [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[12060,12059,12065,12066,12062,12063,12061,12064],"class_list":["post-18934","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-eco-de-granada","tag-eco-en-granada","tag-festival-caceres","tag-granada-sola","tag-hay-festival","tag-hay-festival-granada","tag-muerte-umberto-eco","tag-womad"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18934","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18934"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18934\/revisions"}],"predecessor-version":[{"id":18938,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18934\/revisions\/18938"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18934"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18934"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18934"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}