{"id":18893,"date":"2016-02-14T14:07:03","date_gmt":"2016-02-14T13:07:03","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18893"},"modified":"2016-02-15T14:07:16","modified_gmt":"2016-02-15T13:07:16","slug":"el-camino-de-solea","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/el-camino-de-solea\/","title":{"rendered":"El camino de Sole\u00e1"},"content":{"rendered":"<p style=\"text-align: justify;\">El disco se titula \u201cTendr\u00e1 que haber un camino\u201d y est\u00e1 comenzando su andadura on the road. En la carretera. \u00a1Qu\u00e9 bien lo pasamos en la sala \u201cBoom, Boom, Boom\u201d, el pasado jueves, en el concierto de presentaci\u00f3n del primer trabajo discogr\u00e1fico de Sole\u00e1 Morente, entre Milnos y decibelios! Y as\u00ed lo cont\u00e9 en IDEAL.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18894\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva-300x164.jpg\" alt=\"Sole\u00e1 Morente Club Alhambra Reserva\" width=\"300\" height=\"164\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva-300x164.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva-1024x560.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva-644x352.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-Club-Alhambra-Reserva.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Porque la m\u00fasica son\u00f3 muy alto. Como a m\u00ed me gusta. Y Sole\u00e1 se elev\u00f3 sobre el escenario, pero sin levitar. Sin despegar los pies del suelo. Que se la vio a gusto, dominando la situaci\u00f3n y controlando el tempo de todo lo mucho, y bueno, que ocurri\u00f3 en una velada para el recuerdo.<\/p>\n<p style=\"text-align: justify;\">Tendr\u00e1 que haber un camino. No se me va de la cabeza el t\u00edtulo del disco. Porque, si ning\u00fan t\u00edtulo es casual, en el caso de Sole\u00e1, licenciada en filolog\u00eda hisp\u00e1nica, menos todav\u00eda.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-camino.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18895\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-camino-300x300.jpg\" alt=\"Sole\u00e1 Morente camino\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-camino-300x300.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-camino-150x150.jpg 150w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-camino.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Camino es una palabra que, f\u00edsica y metaf\u00edsicamente, ha alumbrado infinidad de conceptos, tesis y filosof\u00edas. Una antolog\u00eda de los caminos m\u00e1s importantes de la historia de la literatura, el arte o la m\u00fasica dar\u00eda para completar un volumen de cientos de p\u00e1ginas. Sin embargo, y por trillado que pueda estar el sustantivo, un camino me sigue despertando curiosidad y excitando sobremanera.<\/p>\n<p style=\"text-align: justify;\">Tendr\u00e1 que haber un camino. Tendr\u00e1. \u00a1Qu\u00e9 futuro tan especial! \u00a1Qu\u00e9 sonoridad tan expresiva! Tendr\u00e1. Me encantar\u00eda poder hablar con mi madre -que fue exigente profesora de lengua y encendida amante de la sintaxis- acerca de ese tendr\u00e1, al que sigue un haber que lo convierte en imperativo.<\/p>\n<p style=\"text-align: justify;\">Que no hubiera un camino no parece ser una opci\u00f3n para Sole\u00e1. Es posible que est\u00e9 escondido o que sea dif\u00edcil de encontrar a primera vista. Estar\u00e1 cubierto con zarzas o ser\u00e1 de complicado acceso. Pero est\u00e1 ah\u00ed. Tiene que estarlo. Y a cada uno le corresponde alcanzarlo. Para seguir andando.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-directo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18896\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-directo-300x169.jpg\" alt=\"Sole\u00e1 Morente directo\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-directo-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Sole\u00e1-Morente-directo.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Este disco, siendo el primero de Sole\u00e1, es la culminaci\u00f3n de un largo viaje que ha discurrido por caminos repletos de curvas y meandros, de exigentes cuestas arriba y vertiginosos descensos. Un disco que no admite etiquetas, desborda los l\u00edmites de las clasificaciones al uso y trasciende los g\u00e9neros habituales.<\/p>\n<p style=\"text-align: justify;\">Un disco fundacional que es un golpe de autoafirmaci\u00f3n, adem\u00e1s de una declaraci\u00f3n de principios. Sole\u00e1 no ha elegido el camino f\u00e1cil, c\u00f3modo ni previsible. Sole\u00e1 sab\u00eda que tendr\u00e1 que haber un camino. El suyo propio. Y no ha parado hasta encontrarlo. \u00a1Enhorabuena!<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18076 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>El disco se titula \u201cTendr\u00e1 que haber un camino\u201d y est\u00e1 comenzando su andadura on the road. En la carretera. \u00a1Qu\u00e9 bien lo pasamos en la sala \u201cBoom, Boom, Boom\u201d, el pasado jueves, en el concierto de presentaci\u00f3n del primer trabajo discogr\u00e1fico de Sole\u00e1 Morente, entre Milnos y decibelios! Y as\u00ed lo cont\u00e9 en IDEAL. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17,6],"tags":[5824,12028,12027,12029,12025,12026],"class_list":["post-18893","post","type-post","status-publish","format-standard","hentry","category-musica","category-opinion","tag-alhambra-1925","tag-alhrma-especial","tag-camino-solea","tag-milnoh","tag-solea-morente","tag-tendra-que-haber-un-camino"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18893","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18893"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18893\/revisions"}],"predecessor-version":[{"id":18898,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18893\/revisions\/18898"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18893"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18893"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18893"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}