{"id":18883,"date":"2016-02-15T11:46:25","date_gmt":"2016-02-15T10:46:25","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18883"},"modified":"2016-02-15T11:46:25","modified_gmt":"2016-02-15T10:46:25","slug":"carlos-zanon-premio-hammett-del-2015-presenta-sus-libros-en-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/carlos-zanon-premio-hammett-del-2015-presenta-sus-libros-en-granada\/","title":{"rendered":"Carlos Zan\u00f3n, premio Hammett del 2015, presenta sus libros en Granada"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>El martes, las 19 horas, en el Centro de Exposiciones CAJAGRANADA Puerta Real, el festival Granada Noir presenta a <em><span style=\"color: #ff00ff;\"><a href=\"http:\/\/www.carloszanon.com\/es\/fauna-zanon\/que-te-echen-zanon-por-jesus-lens\" target=\"_blank\">Carlos Zan\u00f3n, uno de los maestros del g\u00e9nero negro contempor\u00e1neo<\/a><\/span><\/em><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Carlos Zan\u00f3n y Jes\u00fas Lens, director de Granada Noir, presentar\u00e1n <span style=\"color: #ff00ff;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/yo-fui-johnny-thunders\/\" target=\"_blank\">\u201cYo fui Johnny Thunders\u201d<\/a><\/span> y <span style=\"color: #ff00ff;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/que-te-echen-zanon\/\" target=\"_blank\">\u201cMarley estaba muerto\u201d<\/a><\/span>, las obras m\u00e1s recientes del escritor barcelon\u00e9s<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Carlos-Zan\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18884\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Carlos-Zan\u00f3n-200x300.jpg\" alt=\"Carlos Zan\u00f3n\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Carlos-Zan\u00f3n-200x300.jpg 200w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2016\/02\/Carlos-Zan\u00f3n.jpg 639w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>El acto cuenta con la colaboraci\u00f3n de CAJAGRANADA Fundaci\u00f3n y de la Fundaci\u00f3n Tres Culturas<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El festival Granada Noir presenta en Granada al polifac\u00e9tico escritor Carlos Zan\u00f3n: poeta, novelista, guionista, articulista y cr\u00edtico literario. Ser\u00e1 el martes 16 de febrero, a las 19 horas, en el Centro de Exposiciones de CAJAGRANADA en Puerta Real.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La conversaci\u00f3n ser\u00e1 conducida por Jes\u00fas Lens, director de Granada Noir, y servir\u00e1 de presentaci\u00f3n de las dos obras m\u00e1s recientes del premiado autor barcelon\u00e9s: \u201cYo fui Johnny Thunders\u201d y \u201cMarley estaba muerto\u201d, publicadas en la Serie Negra de RBA.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Marley-estaba-muerto-portada.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18663\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Marley-estaba-muerto-portada-300x225.jpg\" alt=\"Marley estaba muerto portada\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Marley-estaba-muerto-portada-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Marley-estaba-muerto-portada.jpg 400w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La consecuci\u00f3n del Premio Hammett de Semana Negra por su obra \u201cYo fui Johnny Thunders\u201d, confirm\u00f3 que Carlos Zan\u00f3n es uno de los grandes maestros del g\u00e9nero negro contempor\u00e1neo, habiendo dado la raz\u00f3n a quienes consideran que es el leg\u00edtimo heredero de Manuel V\u00e1zquez Montalb\u00e1n. As\u00ed, el premio m\u00e1s importante de los concedidos a la literatura polic\u00edaca escrita en espa\u00f1ol reconoci\u00f3 el a\u00f1o pasado que estamos ante uno de los grandes talentos de la narrativa actual. Porque Zan\u00f3n es un autor que desborda los l\u00edmites y deja peque\u00f1as las etiquetas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">S\u00ed. Su obra es negra. Pero tambi\u00e9n se la ha descrito como gris asfalto. Y las conexiones que tiene con la movida de los a\u00f1os 80 y la escena musical barcelonesa, la conecta con esa tradici\u00f3n de literatura que suena a m\u00fasica. A rock. Y a polvo de estrellas. Y est\u00e1 el barrio, uno de los grandes protagonistas en la obra de Zan\u00f3n. Porque la obra de Carlos es urbana. Y, a la vez, rezuma poes\u00eda y musicalidad en cada p\u00e1rrafo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Carlos-Zan\u00f3n-rock.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18664\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Carlos-Zan\u00f3n-rock-300x120.jpg\" alt=\"Carlos Zan\u00f3n rock\" width=\"300\" height=\"120\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Carlos-Zan\u00f3n-rock-300x120.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Carlos-Zan\u00f3n-rock.jpg 630w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El g\u00e9nero negro de Zan\u00f3n no exige polic\u00eda cient\u00edfica, CSI ni pruebas de ADN. Porque lo suyo es el alma. Y los sue\u00f1os. Rotos, tant\u00edsimas veces. Y la esperanza. Aunque haya que trabajar muy duro por encontrarla\u2026 y mantener encendida su llama.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Su libro m\u00e1s reciente, \u201cMarley estaba muerto\u201d, es una colecci\u00f3n de cuentos, todos ellos sutilmente conectados entre s\u00ed. La ciudad, el barrio y la familia son los protagonistas. Y los vecinos. Y los descampados y callejones. Y las tapias. Y el bar de la esquina. Y el t\u00edo que solo viene de vez en cuando, pero que transforma cualquier estaci\u00f3n del a\u00f1o en Navidad, gracias a su locura.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En las novelas de Carlos Zan\u00f3n, los hermanos han de compartir la habitaci\u00f3n, los padres no salen al balc\u00f3n a fumar y el rellano de las escaleras de la casa huele a potaje. En la tele nunca se podr\u00e1 ver el partido del Plus, pero siempre sonar\u00e1 la m\u00fasica. De Elvis, por supuesto. Pero tambi\u00e9n de Loquillo.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/07\/Yo-fui-Johnny-Thunders.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18167\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/07\/Yo-fui-Johnny-Thunders-197x300.jpg\" alt=\"Yo fui Johnny Thunders\" width=\"197\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/07\/Yo-fui-Johnny-Thunders-197x300.jpg 197w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/07\/Yo-fui-Johnny-Thunders.jpg 450w\" sizes=\"auto, (max-width: 197px) 100vw, 197px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Carlos Zan\u00f3n es, en fin, uno de los grandes escritores contempor\u00e1neos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El acto de presentaci\u00f3n en Granada de Carlos Zan\u00f3n est\u00e1 organizado por el Festival Granada Noir, Fundaci\u00f3n Tres Culturas y CajaGRANADA Fundaci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>Informaci\u00f3n pr\u00e1ctica:<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lugar: Centro de Exposiciones CajaGRANADA-Puerta Real Acera del Casino, 7. Granada Telf.: 958 227 791<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fecha: 16\/2\/2016<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Hora: 19 horas<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El martes, las 19 horas, en el Centro de Exposiciones CAJAGRANADA Puerta Real, el festival Granada Noir presenta a Carlos Zan\u00f3n, uno de los maestros del g\u00e9nero negro contempor\u00e1neo \u00a0 Carlos Zan\u00f3n y Jes\u00fas Lens, director de Granada Noir, presentar\u00e1n \u201cYo fui Johnny Thunders\u201d y \u201cMarley estaba muerto\u201d, las obras m\u00e1s recientes del escritor barcelon\u00e9s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144,21],"tags":[10664,11449,12012,12013,11593,12014,11448],"class_list":["post-18883","post","type-post","status-publish","format-standard","hentry","category-granada-noir","category-negra-y-criminal","tag-cajagranada-fundacion","tag-carlos-zanon","tag-carlos-zanon-granada","tag-fundacion-tres-culturas","tag-marley-estaba-muerto","tag-que-te-echen-zanon","tag-yo-fui-johnny-thunders"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18883","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18883"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18883\/revisions"}],"predecessor-version":[{"id":18885,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18883\/revisions\/18885"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18883"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18883"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18883"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}