{"id":18603,"date":"2015-12-16T18:00:12","date_gmt":"2015-12-16T17:00:12","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18603"},"modified":"2015-12-16T10:55:06","modified_gmt":"2015-12-16T09:55:06","slug":"glenn","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/glenn\/","title":{"rendered":"Glenn"},"content":{"rendered":"<p style=\"text-align: justify;\">Vaya por delante mi supina ignorancia sobre el personaje que protagoniza \u201cGlenn\u201d, la novela con la que el autor malague\u00f1o Alejandro Gastroguer ha ganado la trig\u00e9simo primera edici\u00f3n de los Premios Literarios Ja\u00e9n, convocados por CAJAGRANADA Fundaci\u00f3n y reci\u00e9n publicada por la editorial Almuzara.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Premios-Literarios-Ja\u00e9n-Premiados-frente.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18604\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Premios-Literarios-Ja\u00e9n-Premiados-frente-300x200.jpg\" alt=\"Premios Literarios Ja\u00e9n Premiados frente\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Premios-Literarios-Ja\u00e9n-Premiados-frente-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Premios-Literarios-Ja\u00e9n-Premiados-frente-1024x681.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Premios-Literarios-Ja\u00e9n-Premiados-frente-644x429.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Gould.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Glenn Gould.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Sab\u00eda tan poco de ese Gould que la primera vez que escuch\u00e9 su nombre, durante las deliberaciones del jurado que concedi\u00f3 el premio Ja\u00e9n (*), pens\u00e9 en ese otro Gould. Elliot. El Elliot Gould protagonista de una de las mejores adaptaciones de Chandler: \u201cEl largo adi\u00f3s\u201d y recientemente recuperado para el cine por la serie \u201cRay Donovan\u201d.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Supina ignorancia, ya digo. Porque Glenn Gould fue un pianista sublime, como he tenido ocasi\u00f3n de comprobar (y escuchar) Un pianista que se hizo famoso por su interpretaci\u00f3n de las Variaciones Goldberg de Bach. Por su doble interpretaci\u00f3n de las mismas, para ser m\u00e1s precisos.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18605\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-300x202.jpg\" alt=\"Glenn Gould\" width=\"300\" height=\"202\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-300x202.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-644x433.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Porque Glenn Gould las grab\u00f3 por primera vez cuando era joven, a mitad de los a\u00f1os 50 del pasado siglo. Y despu\u00e9s, a comienzos de los 80, volvi\u00f3 a registrarlas, aunque de forma totalmente distinta.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Atesorador de una personalidad compleja, que algunos podr\u00edan describir como disfuncional, su vida fue, en realidad, parte de su obra. Una vida diferente, a contracorriente, alejada de los est\u00e1ndares convencionales. Una vida que Alejandro Castroguer ha investigado para construir una biograf\u00eda del m\u00fasico tan especial como su personalidad.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18606\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-300x199.jpg\" alt=\"Glenn\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-300x199.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn.jpg 318w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Una biograf\u00eda escrita a partir de momentos, objetos, conversaciones, decisiones, espant\u00e1s, diagn\u00f3sticos, grabaciones, interpretaciones y silencios. Una novela en la que la forma es tan importante como el fondo. Una novela que es como un puzzle en el que cada ficha termina encajando en su sitio, un mosaico cuyas teselas acaban ofreciendo un ilustrativo fresco de un m\u00fasico que fue m\u00e1s, mucho m\u00e1s que un m\u00fasico, como Alejandro Castroguer se encarga de demostrar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Enamorado de la radio y escritor, Glenn Gould dej\u00f3 de tocar en p\u00fablico en 1964, cuando estaba en lo m\u00e1s alto de su carrera. \u00bfPor qu\u00e9? \u201cGlenn\u201d lo cuenta. Lo narra. O, mejor dicho, da pistas. Porque \u201cGlenn\u201d no es una tesis doctoral, sino una novela. Basada en hechos reales, cierto, pero una novela. Una narraci\u00f3n imponente, dotada de un poderoso armaz\u00f3n, invisible para un lector, que bucea en la vida de Gould y conduce al lector como si estuviera sumergido es un thriller atrapador. Una novela que comienza. Y que termina. O no.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18608\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer-196x300.jpg\" alt=\"Glenn Castroguer\" width=\"196\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer-196x300.jpg 196w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer-669x1024.jpg 669w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer-644x985.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Castroguer.jpg 1046w\" sizes=\"auto, (max-width: 196px) 100vw, 196px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Cuando la lean, ya me entender\u00e1n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Las relaciones de pareja de Glenn, sus padres, aquel viaje a la Uni\u00f3n Sovi\u00e9tica, sus contratos discogr\u00e1ficos, sus visitas a las f\u00e1bricas de pianos, sus horarios imposibles, su pasi\u00f3n por la soledad creativa\u2026 y la banqueta, un objeto sencillo que, sin embargo, tanto significado tiene, atesorando toda una historia.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-silla.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18607\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-silla-300x292.jpg\" alt=\"Glenn Gould silla\" width=\"300\" height=\"292\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-silla-300x292.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Glenn-Gould-silla.jpg 478w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ah\u00ed radica lo mejor de la novela de Castroguer: en los significados que el autor otorga a un sinf\u00edn de datos ciertos y contrastados, construyendo la Historia de Gould a trav\u00e9s de decenas de peque\u00f1as historias, esas historias que nos permiten conocer al personaje. Y tratar de comprenderle. Y amarle, por supuesto.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18076 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">(*) En este jurado, ejerc\u00ed como secretario del jurado, con voz pero sin voto, no habiendo le\u00eddo las novelas finalistas y no teniendo ni idea, pues, de qu\u00e9 iba cada una cuando comenzaron las deliberaciones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Vaya por delante mi supina ignorancia sobre el personaje que protagoniza \u201cGlenn\u201d, la novela con la que el autor malague\u00f1o Alejandro Gastroguer ha ganado la trig\u00e9simo primera edici\u00f3n de los Premios Literarios Ja\u00e9n, convocados por CAJAGRANADA Fundaci\u00f3n y reci\u00e9n publicada por la editorial Almuzara. Gould. Glenn Gould. Sab\u00eda tan poco de ese Gould que la [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[4,9],"tags":[11825,48,11538,11823,11822,11824,5843],"class_list":["post-18603","post","type-post","status-publish","format-standard","hentry","category-libros-bellos","category-literarios","tag-alejandro-castroguer","tag-almuzara","tag-glenn","tag-glenn-castroguer","tag-glenn-gould","tag-premios-jaen-novela","tag-premios-literarios-cajagranada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18603","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18603"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18603\/revisions"}],"predecessor-version":[{"id":18609,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18603\/revisions\/18609"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18603"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18603"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18603"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}