{"id":18548,"date":"2015-12-02T14:29:43","date_gmt":"2015-12-02T13:29:43","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18548"},"modified":"2015-12-02T14:29:43","modified_gmt":"2015-12-02T13:29:43","slug":"homeland-en-el-rincon-oscuro","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/homeland-en-el-rincon-oscuro\/","title":{"rendered":"Homeland en El Rinc\u00f3n Oscuro"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>En nuestro Rinc\u00f3n Oscuro de los mi\u00e9rcoles, en IDEAL, hablamos de una serie que ha vuelto a volar alto.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El d\u00eda de su estreno, uno de los episodios de la quinta temporada de la serie \u201cHomeland\u201d inclu\u00eda un mensaje en que se advert\u00eda a los espectadores de que determinadas im\u00e1genes pod\u00edan herir su sensibilidad, tras los atentados de Par\u00eds.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-5.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18549\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-5-300x225.jpg\" alt=\"Homeland 5\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-5-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-5.jpg 580w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y es que, efectivamente, el personaje de un radical islamista animaba a sus compa\u00f1eros de c\u00e9lula a llevar la yihad, la muerte, el dolor, el caos y la destrucci\u00f3n al coraz\u00f3n de las capitales europeas, en vez de irse a luchar a Siria.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Esta quinta temporada de \u201cHomeland\u201d est\u00e1 tan sorprendentemente apegada a la realidad que, por momentos, da miedo. Por ejemplo, el an\u00e1lisis que Quinn, uno de los agentes de la CIA que ha pasado dos a\u00f1os en Siria, hace sobre el avispero en que se ha convertido la regi\u00f3n.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-quinn.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18550\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-quinn-300x206.jpg\" alt=\"Homeland quinn\" width=\"300\" height=\"206\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-quinn-300x206.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-quinn-1024x703.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-quinn-644x442.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Cuando uno de sus superiores le pregunta si la estrategia que est\u00e1 siguiendo el gobierno de los Estados Unidos es adecuada, \u00e9l pregunta: <em><strong>\u201c\u00bfQu\u00e9 estrategia? D\u00edgame la estrategia y yo le dir\u00e9 si est\u00e1 funcionando\u201d<\/strong><\/em>. Se hace un ominoso silencio en sala y Quinn contin\u00faa: <em><strong>\u201cVer\u00e1n, ese es el problema. Porque ellos s\u00ed tienen una estrategia. Se est\u00e1n agrupando en Raqqa por millares, camuflados entre la poblaci\u00f3n civil y est\u00e1n afilando sus armas. \u00bfY saben para qu\u00e9? Lo llaman El Final de los Tiempos\u2026\u00a0 Est\u00e1n all\u00ed por una sola raz\u00f3n: morir por el Califato y conseguir un mundo sin infieles. Esa es su estrategia y la ha sido desde el siglo XVII\u201d<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">An\u00e1lisis semejantes al de Quinn los hemos podido leer en la prensa de estas dos \u00faltimas semanas por decenas. Y no digamos ya en las Redes Sociales, sorpresiva e inusitadamente repletas de reci\u00e9n nacidos expertos en Oriente Medio y en geopol\u00edtica internacional.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El caso es que empiezas a ver esta temporada de \u201cHomeland\u201d y, si no sabes qui\u00e9nes son Carrie Mathison o Saul Berenson, hay momentos en que puedes pensar que est\u00e1s frente a un noticiario o un documental protagonizado por ISIS, Putin, Al Assad, Charlie Hebdo\u2026 e incluso Snowden. Porque la filtraci\u00f3n de secretos protegidos y el papel de los hackers y los medios de comunicaci\u00f3n tambi\u00e9n est\u00e1n en el meollo argumental de la serie.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-Saul.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18551\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-Saul-225x300.jpg\" alt=\"Homeland Saul\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-Saul-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-Saul.jpg 458w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pero no. Por muy pegada que est\u00e9 a la realidad, \u201cHomeland\u201d no es documental. Es una serie dram\u00e1tica y de acci\u00f3n que utiliza todos los recursos de la ficci\u00f3n televisiva para enganchar a los espectadores, incluidos algunos golpes tan bajos como que un personaje escuche la conversaci\u00f3n de dos jefazos de la CIA\u2026 pegando el o\u00eddo a la puerta de la habitaci\u00f3n en que est\u00e1n encerrados.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero a \u201cHomeland\u201d hay que perdonarle esos bajonazos, sobre todo, porque es una serie que, tras la desaparici\u00f3n de Brody -su personaje m\u00e1s interesante y pieza clave en las dos primeras temporadas- estaba muerta. Muerta y casi enterrada; tanto por parte del p\u00fablico como de la cr\u00edtica especializada. Sin embargo, los productores y los guionistas han sabido c\u00f3mo reinventarla y hacerla cambiar de rumbo para terminar alz\u00e1ndose, triunfante, en esta vertiginosa quinta temporada.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-brody.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18552\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-brody-300x164.jpg\" alt=\"Homeland brody\" width=\"300\" height=\"164\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-brody-300x164.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-brody.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y es que la nueva versi\u00f3n de \u201cHomeland\u201d, tan de 2015, est\u00e1 trufada del esp\u00edritu de Jack Bauer y la m\u00edtica serie \u201c24\u201d, con personajes, traidores y taimados, que son capaces de comprometer incluso a uno de los capitostes de la mism\u00edsima CIA. Y hay explosiones, v\u00e9rtigo y acci\u00f3n. Mucha acci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En esta temporada, la trama transcurre en Berl\u00edn, el mejor escenario posible para una historia de esp\u00edas, como siempre ha defendido Woody Allen. Pero con incursiones en el L\u00edbano de Hezbollah, por ejemplo. Y con planes para derrocar a Al Assad y situar a un l\u00edder democr\u00e1tico y reformista en Damasco.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y todo ello, dejando bastante de lado el trastorno bipolar de la protagonista y los conflictos personales y familiares que la aquejaban en las primeras temporadas de la serie. Los guionistas han considerado que la vertiente m\u00e1s psicol\u00f3gica de los personajes estaba amortizada y que ahora toca enfrentarlos a la tiran\u00eda del No-hay-tiempo. Y al m\u00e1s dif\u00edcil todav\u00eda.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18553\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-300x120.jpg\" alt=\"Homeland\" width=\"300\" height=\"120\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-300x120.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland-644x258.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/12\/Homeland.jpg 770w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Todas estas consideraciones est\u00e1n realizadas sobre la base de los primeros cap\u00edtulos de una quinta temporada de \u201cHomeland\u201d que, a buen seguro, a\u00fan nos tiene bastantes sorpresas guardadas en la rec\u00e1mara.<\/p>\n<p>Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18076 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>En nuestro Rinc\u00f3n Oscuro de los mi\u00e9rcoles, en IDEAL, hablamos de una serie que ha vuelto a volar alto. El d\u00eda de su estreno, uno de los episodios de la quinta temporada de la serie \u201cHomeland\u201d inclu\u00eda un mensaje en que se advert\u00eda a los espectadores de que determinadas im\u00e1genes pod\u00edan herir su sensibilidad, tras [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,11774,12],"tags":[6487],"class_list":["post-18548","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-rincon-oscuro","category-television","tag-homeland"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18548","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18548"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18548\/revisions"}],"predecessor-version":[{"id":18554,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18548\/revisions\/18554"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18548"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18548"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18548"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}