{"id":18486,"date":"2015-11-13T18:04:41","date_gmt":"2015-11-13T17:04:41","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18486"},"modified":"2015-11-13T18:04:59","modified_gmt":"2015-11-13T17:04:59","slug":"dhepaan","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/dhepaan\/","title":{"rendered":"Dheepan"},"content":{"rendered":"<p style=\"text-align: justify;\">Quiz\u00e1 no sea tan redonda como \u201cUn profeta\u201d y \u201cDe \u00f3xido y hueso\u201d, sus anteriores pel\u00edculas, pero la nueva cinta de Jacques Audiard es poderosa, tiene momentos memorables y conmovedores y secuencias tan duras como necesarias.<\/p>\n<p style=\"text-align: justify;\">Y una vez hecha la conclusi\u00f3n y el resumen final, vamos a empezar la rese\u00f1a de \u201cDheepan\u201d, por si tienes inter\u00e9s en profundizar algo m\u00e1s. Que deber\u00edas, no en vano, hablamos de la m\u00e1s reciente Palma de Oro del Festival de Cannes.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18487\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel-300x229.jpg\" alt=\"Dheepan cartel\" width=\"300\" height=\"229\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel-300x229.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel-1024x781.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel-644x491.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-cartel.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Una pena, eso s\u00ed, que a Granada haya llegado \u00fanicamente la versi\u00f3n doblada. Que si el doblaje empieza a ser una atrocidad sistem\u00e1tica que masacra las pel\u00edculas, en este caso alcanza cumbres de aberraci\u00f3n sin l\u00edmite, al doblar a los personajes cuando hablan en su idioma materno, pero dejando sus voces originales cuando mascullan en franc\u00e9s. \u00bfNos hemos vuelto locos?<\/p>\n<p style=\"text-align: justify;\">No me cansar\u00e9 de agradecer al Madrigal que siga manteniendo abierta esta necesaria e imprescindible ventana al cine de autor, pero ya pod\u00edan hacer la gracia completa y traer alguna copia en VOS y proyectarla en alguna de sus sesiones. Porque lo de \u201cDheepan\u201d y su doblaje es de juzgado de guardia.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18488\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola-300x200.jpg\" alt=\"Dheepan pistola\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola-1024x684.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola-644x430.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-pistola.jpg 1200w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pero vayamos a la pel\u00edcula. Todo comienza en Sri Lanka, con un soldado que quema su uniforme y trata de huir a Francia, con papeles falsos, tras fingir que una mujer y una ni\u00f1a a las que acaba de conocer son su familia. Gracias a unos papeles falsos, consiguen llegar al pa\u00eds galo y los servicios sociales los alojan en un barrio marginal, a la vez que son contratados como porteros del edificio en que van a vivir.<\/p>\n<p style=\"text-align: justify;\">No lo tendr\u00e1n f\u00e1cil, ni el protagonista, Dhepaan, ni su familia postiza. No solo han de adaptarse a una cultura, a una lengua y a unas costumbres que no son las suyas y que desconocen por completo, sino que tendr\u00e1n que aprender a convivir entre ellos, dado que ninguno de los tres se conoc\u00eda previamente con anterioridad.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18489\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro-300x169.jpg\" alt=\"Dheepan Palma de Oro\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro-1024x577.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro-644x363.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-Palma-de-Oro.jpg 1280w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y todo ello, en un contexto de marginalidad y violencia en el que el tr\u00e1fico de drogas y las guerras entre bandas con la constante de uno de esos barrios depauperados que no parecen tener esperanza.<\/p>\n<p style=\"text-align: justify;\">As\u00ed las cosas, la pel\u00edcula es uno de esos dramas existencialistas que culminan en una cat\u00e1rtica secuencia y, al final, con un ep\u00edlogo que podr\u00e1 gustar m\u00e1s o menos al espectador, pero que es necesario.<\/p>\n<p style=\"text-align: justify;\">Una pel\u00edcula que habla de y sobre la violencia, de las secuelas que deja en las personas y de las escasas posibilidades que hay de escapar de ella. Una pel\u00edcula con secuencias poderosas, como dec\u00edamos al comienzo de esta rese\u00f1a. Con im\u00e1genes y estampas fantasmag\u00f3ricas, como la primera subida de la protagonista al piso del hombre al que habr\u00e1 de cuidar. Y es que la capacidad visual de Audiard, sin necesidad de efectos especiales o digitales, es proteica y extraordinaria.<\/p>\n<p style=\"text-align: justify;\">Una pel\u00edcula, tambi\u00e9n, con momentos de ternura y hasta de humor, sin los cuales ser\u00eda dif\u00edcilmente digerible la historia de Dhepaan y su familia. Una historia tremenda, compleja y contradictoria; pero tratada con un enorme respeto por Audiard.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18490\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-300x238.jpg\" alt=\"Dheepan\" width=\"300\" height=\"238\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-300x238.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan-644x511.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/11\/Dheepan.jpg 670w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Porque no es f\u00e1cil la vida de tantas y tantas personas, a todo lo ancho y lo largo del mundo. Y en Dhepaan han encontrado una imagen en la que reflejarse. Una imagen repleta de aristas. Real, como la vida misma.<\/p>\n<p style=\"text-align: justify;\">Como dec\u00edamos al inicio de la rese\u00f1a, una pel\u00edcula que hay que ver. Yo no te aseguro que te vaya a gustar, pero s\u00ed te garantizo que no te va a dejar indiferente. Y que algunas de sus im\u00e1genes se te va a quedar grabada. Y no por ser particularmente escabrosas, sino por ese poder\u00edo visual que acredita a Audiard como uno de los mejores directores del momento.<\/p>\n<p style=\"text-align: justify;\">Un tipo con cosas que contar y talento para hacerlo.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Quiz\u00e1 no sea tan redonda como \u201cUn profeta\u201d y \u201cDe \u00f3xido y hueso\u201d, sus anteriores pel\u00edculas, pero la nueva cinta de Jacques Audiard es poderosa, tiene momentos memorables y conmovedores y secuencias tan duras como necesarias. Y una vez hecha la conclusi\u00f3n y el resumen final, vamos a empezar la rese\u00f1a de \u201cDheepan\u201d, por si [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[11747,11743,11746,11748,11745,11744,9135],"class_list":["post-18486","post","type-post","status-publish","format-standard","hentry","category-cine","tag-claudine-vinasithamby","tag-dhepaan","tag-franck-falise","tag-jacques-audiard","tag-jesuthasan-antonythasan","tag-marc-zinga","tag-vincent-rottiers"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18486","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18486"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18486\/revisions"}],"predecessor-version":[{"id":18492,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18486\/revisions\/18492"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18486"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18486"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18486"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}