{"id":18395,"date":"2015-10-13T11:55:47","date_gmt":"2015-10-13T10:55:47","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18395"},"modified":"2015-10-13T11:57:17","modified_gmt":"2015-10-13T10:57:17","slug":"se-nos-ha-perdido-algo-en-marte","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/se-nos-ha-perdido-algo-en-marte\/","title":{"rendered":"\u00bfSe nos ha perdido algo en Marte?"},"content":{"rendered":"<p style=\"text-align: justify;\">Seg\u00fan la ONU, el n\u00famero de personas en pobreza extrema ha ca\u00eddo por debajo del 10%, por primera vez desde hace muchos a\u00f1os. Aun as\u00ed y por desgracia, son varios cientos de millones de personas las que sufren y padecen en la Tierra, cada d\u00eda. Mientras, las \u00faltimas noticias nos dicen que el hurac\u00e1n Joaqu\u00edn ha golpeado a las Bahamas, pero que ha perdido intensidad. Y, a la vez, yo estoy viendo la posibilidad de sacar un billete de avi\u00f3n de M\u00e1laga a Estambul\u2026 siempre que lo encuentre por menos de 75 euros.<\/p>\n<p style=\"text-align: justify;\">Hace unos d\u00edas, cuando las primeras p\u00e1ginas de todos los peri\u00f3dicos abrieron con la noticia del descubrimiento de agua en Marte, las Redes Sociales se llenaron de concienciadas cr\u00edticas a la millonaria inversi\u00f3n de dinero realizada en semejantes marcianadas: teniendo en cuenta que en la Tierra mueren de hambre miles de personas cada a\u00f1o, \u00bfqu\u00e9 se nos ha perdido en Marte?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Curiosity.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18396\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Curiosity-300x169.jpg\" alt=\"Marcianada Curiosity\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Curiosity-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Curiosity.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y, claro, al ver las im\u00e1genes de los vientres hinchados de los ni\u00f1os de \u00c1frica, sentimos una punzada de indignaci\u00f3n. \u00a1No a las marcianadas! \u00a1Quitemos el dinero a la NASA! \u00a1Acabemos con la Estaci\u00f3n Espacial Internacional! \u00a1Cortemos de ra\u00edz los fondos dedicados a unas investigaciones que, en realidad, no nos llevan a ninguna parte! Quiz\u00e1, en el futuro, a Marte. Pero \u00bfa qui\u00e9n le importa Marte? Y, de esa manera, sentimos nuestra conciencia mucho m\u00e1s tranquila.<\/p>\n<p style=\"text-align: justify;\">Inmediatamente despu\u00e9s, eso s\u00ed, pondremos la tele y querremos tener las noticias m\u00e1s actualizadas sobre ese tal Joaqu\u00edn, que lleg\u00f3 a amenazar con acercarse a Espa\u00f1a y Portugal. Y, de paso, veremos la informaci\u00f3n meteorol\u00f3gica, a ver qu\u00e9 tiempo va a hacer el fin de semana y decidir si bajamos o no a la playa. Y, por supuesto, si hace malo, querremos tumbarnos en el sof\u00e1 a ver en directo todos los partidos de f\u00fatbol del mundo mundial, incluidos los de la excitante liga neozelandesa. Adem\u00e1s, y como estamos preparando una escapada para el Puente, tenemos que buscar una buena tarifa de avi\u00f3n, que hay que ver c\u00f3mo est\u00e1n los billetes\u2026 \u00a1por las nubes!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-sat\u00e9lites.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18397\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-sat\u00e9lites-300x193.jpg\" alt=\"Marcianada sat\u00e9lites\" width=\"300\" height=\"193\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-sat\u00e9lites-300x193.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-sat\u00e9lites.jpg 450w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y nos pensamos que todo eso lo tenemos a nuestro alcance por arte de magia. O de birlibirloque. Como si las comunicaciones v\u00eda sat\u00e9lite y la popularizaci\u00f3n y abaratamiento de la aviaci\u00f3n comercial (por poner solo dos ejemplos) fueran algo que el hombre descubri\u00f3 un buen d\u00eda, por casualidad. Uno de esos d\u00edas en que se despert\u00f3 creativo e ingenioso y se puso a ello. Que ya se sabe: Newton dio con la teor\u00eda de la gravitaci\u00f3n universal porque una tarde, descabezando un sue\u00f1ecito debajo de un \u00e1rbol, le cay\u00f3 una manzana en la cabeza; que si no\u2026<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-newton.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18398\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-newton-300x234.jpg\" alt=\"Marcianada newton\" width=\"300\" height=\"234\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-newton-300x234.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-newton.jpg 320w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Circula por Internet un chiste en el que un tipo le afea a otro que se gaste tanto dinero en fumar. Le hace las cuentas de lo que lleva invertido en tabaco y concluye que, de no haber ca\u00eddo en tan insano vicio, a esas alturas de su vida podr\u00eda tener un Ferrari. La respuesta no se hace esperar:<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 T\u00fa ni fumas ni has fumado en tu vida, \u00bfverdad?<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No.<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 \u00bfY tu Ferrari? Ens\u00e9\u00f1ame el Ferrari.<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 No ver\u00e1s, es que\u2026<\/p>\n<p style=\"text-align: justify;\">&#8211;\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0\u00a0 Ni es que ni pollas \u00a1Qu\u00e9 d\u00f3nde est\u00e1 tu jodido Ferrari!<\/p>\n<p style=\"text-align: justify;\">\u00bfQu\u00e9 nos hace pensar que, si cortamos de ra\u00edz todos los programas de investigaci\u00f3n sobre Marte, vamos a terminar con el hambre en el mundo? Se calcula que, con invertir el 0,3% del PIB mundial de forma consciente, para 2030 se habr\u00eda erradicado la pobreza extrema en la Tierra.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13.jpeg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18399\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13-300x225.jpeg\" alt=\"Martes 13\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13-300x225.jpeg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13-1024x768.jpeg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13-644x483.jpeg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Martes-13.jpeg 1600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">267.000 millones d\u00f3lares anuales. \u00bfDe d\u00f3nde sacarlos? Pues, por ejemplo, del presupuesto que dedicamos a la pamplina \u00e9sa de las marcianadas. \u00bfPor qu\u00e9 no?<\/p>\n<p style=\"text-align: justify;\">Aunque, ya puestos a recortar en actividades no realmente b\u00e1sicas para el ser humano, habr\u00eda que ampliar el espectro de disciplinas a las que cerrar el grifo. El f\u00fatbol, por ejemplo. Y todo el deporte-espect\u00e1culo en su conjunto. \u00a1Se acab\u00f3! \u00bfQui\u00e9n necesita ver a veintid\u00f3s t\u00edos en calzoncillos persiguiendo un bal\u00f3n? \u00bfY Gran Hermano? \u00bfEs necesario Gran Hermano? El que haya alcanzado su edici\u00f3n n\u00famero 16 podr\u00eda hacernos pensar que tiene sus seguidores, pero da igual. No es indispensable. Ni \u00e9l, ni los Alc\u00e1ntara. \u00a1Ni siquiera Wyoming, Pastor o \u00c9vole, con lo sarc\u00e1sticos que son!<\/p>\n<p style=\"text-align: justify;\">Una vez clausuradas las teles, y dado que no habr\u00e1 m\u00e1s Masterchef, habr\u00e1 que cortar nuestro desaforado gasto en gastrochumin\u00e1s, terracitas, bares y locales de copas. Solo en Espa\u00f1a nos gastamos cerca de 40.000 millones de euros al a\u00f1o en este concepto. \u00bfNo resulta vergonzoso, habiendo tanta gente que se muere de hambre?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-el-Marciano.gif\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18400\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-el-Marciano-203x300.gif\" alt=\"Marcianada el Marciano\" width=\"203\" height=\"300\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y as\u00ed podr\u00edamos seguir. Hasta el infinito y m\u00e1s all\u00e1. Pero vamos a quedarnos m\u00e1s cerca. En Santa Fe. \u00a1Ay, aquel 17 de abril de 1492, cuando los Reyes Cat\u00f3licos y Col\u00f3n firmaron las Capitulaciones que permitieron la financiaci\u00f3n del viaje de Crist\u00f3bal a las Indias! \u00a1Ay, Cristob\u00edcal, qu\u00e9 pesadito con la expedici\u00f3n de las narices! Con las penurias que pasaba la gente en la Espa\u00f1a de la \u00e9poca, desgarrada por siglos y siglos de guerra contra los infieles, \u00bfqu\u00e9 necesidad hab\u00eda de soltar la morterada que cost\u00f3 fletar a la Pinta, la Ni\u00f1a y la Santa Mar\u00eda?<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18401\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n-300x169.jpg\" alt=\"Marcianada Col\u00f3n\" width=\"300\" height=\"169\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n-300x169.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n-1024x576.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n-644x362.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/10\/Marcianada-Col\u00f3n.jpg 1920w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Vivimos en el siglo XXI. Vivimos en un mundo complejo, desigual y lleno de injusticias y contradicciones. Tenemos muchos frentes abiertos y cuestiones por resolver. Y, precisamente por eso, a las personas que hemos tenido la suerte de vivir, estudiar y formarnos en los pa\u00edses desarrollados del primer mundo; habr\u00eda que exigirnos un poco esfuerzo, an\u00e1lisis y reflexi\u00f3n a la hora de exponer nuestras tesis y argumentos.<\/p>\n<p style=\"text-align: justify;\">Muy al contrario y por desgracia, parece que cuantas m\u00e1s herramientas tenemos a nuestro alcance para saber, conocer y divulgar, m\u00e1s simples, perezosos y desganados se vuelven nuestros procesos mentales.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\"><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18076 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Seg\u00fan la ONU, el n\u00famero de personas en pobreza extrema ha ca\u00eddo por debajo del 10%, por primera vez desde hace muchos a\u00f1os. Aun as\u00ed y por desgracia, son varios cientos de millones de personas las que sufren y padecen en la Tierra, cada d\u00eda. Mientras, las \u00faltimas noticias nos dicen que el hurac\u00e1n Joaqu\u00edn [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[11651,11660,11654,11657,11658,11652,11653,11659,11655,11656],"class_list":["post-18395","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-agua-en-marte","tag-ciencia","tag-el-marciano","tag-estas-en-marte","tag-lunaticos","tag-marcianada","tag-martes-y-13","tag-no-a-marte","tag-the-martian","tag-vivir-en-marte"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18395","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18395"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18395\/revisions"}],"predecessor-version":[{"id":18403,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18395\/revisions\/18403"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18395"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18395"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18395"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}