{"id":18207,"date":"2015-09-01T12:28:52","date_gmt":"2015-09-01T11:28:52","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18207"},"modified":"2015-09-01T12:28:52","modified_gmt":"2015-09-01T11:28:52","slug":"en-el-adios-de-negra-y-criminal","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/en-el-adios-de-negra-y-criminal\/","title":{"rendered":"En el adi\u00f3s de Negra y Criminal"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>\u201cQue somos una PYME, Jes\u00fas\u201d<\/strong><\/em> \u2013 me dec\u00eda Paco. <em><strong>\u201cY nosotros, sin saberlo, hasta que nos lo dijo la redactora del peri\u00f3dico. Por lo visto, somos un ejemplo de PYME adaptada a la modernidad y la tecnolog\u00eda, por la cosa del Internet.\u201d<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Estas palabras las he sacado de <strong><a href=\"http:\/\/blogs.ideal.es\/pateandoelmundo\/2007\/12\/04\/negra-y-criminal-cumpleanos-feliz\/\" target=\"_blank\">un art\u00edculo que escrib\u00ed en 2007<\/a>,<\/strong> con motivo de la celebraci\u00f3n del quinto cumplea\u00f1os de Negra y Criminal, la m\u00edtica librer\u00eda de la Barceloneta que acaba de anunciar su cierre. Su adi\u00f3s.<\/p>\n<figure id=\"attachment_18208\" aria-describedby=\"caption-attachment-18208\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Jes\u00fas-Lens.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-18208\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Jes\u00fas-Lens-300x274.jpg\" alt=\"Uno de los momentos m\u00e1s felices de mi vida, como escritor\" width=\"300\" height=\"274\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Jes\u00fas-Lens-300x274.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Jes\u00fas-Lens.jpg 390w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-18208\" class=\"wp-caption-text\">Uno de los momentos m\u00e1s felices de mi vida, como escritor<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Porque Montse Clav\u00e9 y Paco Camarasa ya no pueden m\u00e1s. No pueden m\u00e1s con una librer\u00eda de la que todo el mundo habla y a la que mucha gente va. Pero que no vende libros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y as\u00ed, claro, no se puede.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Vender.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Uy, lo que ha dicho!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Paco-Camarasa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18209\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Paco-Camarasa-300x225.jpg\" alt=\"Negra y Criminal Paco Camarasa\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Paco-Camarasa-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Paco-Camarasa.jpg 399w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Es como cada vez que desaparece una cabecera period\u00edstica y las Redes Sociales se llenan de llantos por un peri\u00f3dico que todo el mundo le\u00eda. Pero gratis. Por supuesto. Y es que parece que pagar por leer no se lleva. Y, as\u00ed, Negra y Criminal se hab\u00eda convertido m\u00e1s en un Club Social que en un negocio.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Negocio.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Uy, lo que ha dicho!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Vuelvo sobre aquel escrito de 2007: <em><strong>\u201cEra habitual encontrar referencias sobre la librer\u00eda barcelonesa Negra y Criminal en las mejores revistas literarias de este pa\u00eds, del \u201cQu\u00e9 leer\u201d a \u201cQuimera\u201d y, tambi\u00e9n, en los suplementos culturales de los peri\u00f3dicos nacionales, del Babelia y ABCD a El Cultural. Era igualmente sencillo encontrar referencias sobre ellos en muchas y diversas webs librescas y hasta en programas de televisi\u00f3n y radio.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em><strong>Donde jam\u00e1s pod\u00eda esperar encontrarlos era en un suplemento de El Pa\u00eds\u2026 dedicado al SIMO, una feria de inform\u00e1tica, ordenadores y otras cosas por estilo, te\u00f3ricamente alejadas del mundo de la literatura polic\u00edaca. Y all\u00ed estaban, Paco y Montse, los factotum de Negra y Criminal, muy serios, mirando al objetivo de la c\u00e1mara, con un fondo repleto, eso s\u00ed, de libros y m\u00e1s libros\u201d<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><a href=\"http:\/\/blogs.ideal.es\/pateandoelmundo\/2007\/12\/04\/negra-y-criminal-cumpleanos-feliz\/\" target=\"_blank\"><span style=\"color: #ff00ff;\"><strong>Sigan leyendo aqu\u00ed<\/strong><\/span><\/a> aquel paneg\u00edrico sobre una peque\u00f1a empresa cuyo modelo me parec\u00eda mod\u00e9lico y cuyas bondades no me he cansado de propagar a los cuatro vientos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Empresa.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Uy, lo que ha dicho!<\/p>\n<figure id=\"attachment_18210\" aria-describedby=\"caption-attachment-18210\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Paco-Camarasa-Granada-Noir.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-18210\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Paco-Camarasa-Granada-Noir-300x296.jpg\" alt=\"Paco Camarasa, siempre c\u00f3mplice\" width=\"300\" height=\"296\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Paco-Camarasa-Granada-Noir-300x296.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Paco-Camarasa-Granada-Noir-644x635.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Paco-Camarasa-Granada-Noir.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-18210\" class=\"wp-caption-text\">Paco Camarasa, siempre c\u00f3mplice<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Esto tambi\u00e9n me lo habr\u00e1n le\u00eddo: uno de los momentos m\u00e1s gozosos del mes era el de la recepci\u00f3n de un paquete desde La Barceloneta. A veces, era una caja. Porque yo les ped\u00eda a Montse y Paco un par de libros. Y a ese pedido, ellos a\u00f1ad\u00edan siempre algunos t\u00edtulos m\u00e1s que, sab\u00edan, yo iba a querer y a disfrutar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Porque Montse y Paco son libreros. De los de verdad. De los que conocen a sus clientes y saben qu\u00e9 les gusta. Libreros que, <strong><span style=\"color: #ff00ff;\"><a href=\"http:\/\/otrolunes.com\/archivos\/13\/php\/unos-escriben\/unos-escriben-n13-a13-p01-2010.php\" target=\"_blank\">como dec\u00eda en este otro art\u00edculo<\/a><\/span><\/strong>, siempre te descubren tesoros. \u00a1Con lo complicado que es encontrar un tesoro, hoy en d\u00eda!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Gij\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18211\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Gij\u00f3n-300x235.jpg\" alt=\"Negra y Criminal Gij\u00f3n\" width=\"300\" height=\"235\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Gij\u00f3n-300x235.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-Gij\u00f3n.jpg 383w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">S\u00e9 que no me puedo poner como ejemplo porque yo soy un comprador infatigable de libros. Adem\u00e1s, tambi\u00e9n los leo. Algunos. Porque mi biblioteca es tan grande que podr\u00eda estar leyendo siete vidas y no la agotar\u00eda. Pero, aun as\u00ed, sigo comprando.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Comprar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00a1Uy, lo que ha dicho!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">S\u00ed.<\/p>\n<figure id=\"attachment_18212\" aria-describedby=\"caption-attachment-18212\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-de-viaje.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-18212\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-de-viaje-300x226.jpg\" alt=\"Hasta en Yemen, vest\u00eda to de Negra y Criminal\" width=\"300\" height=\"226\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-de-viaje-300x226.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/09\/Negra-y-Criminal-de-viaje.jpg 399w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-18212\" class=\"wp-caption-text\">Hasta en Yemen, vest\u00eda to de Negra y Criminal<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Hoy es un d\u00eda tr\u00e1gico y luctuoso. Porque hoy se anuncia el cierre de Negra y Criminal. Me queda la tranquilidad de atesorar en mis estanter\u00edas cientos de libros llegados desde aquel reducto de una Barceloneta que, hoy, es m\u00e1s pobre y miserable.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Como todos nosotros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">No.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">No empieza bien esta vuelta a la normalidad vigente. Aunque, en realidad, en los tiempos del gratis total, la pirater\u00eda, las descargas gratuitas y la reclamaci\u00f3n de un supuesto derecho de acceso a la cultura sin coste, \u00bfde verdad nos extra\u00f1a?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lloremos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lloremos virtual y digitalmente lo que no hemos sabido defender como consumidores anal\u00f3gicos y sensatos&#8230;<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Un abrazo, Montse y Paco.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Nos vemos pronto. All\u00ed o por aqu\u00ed\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Siempre vuestro, Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-18076 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Twitter-Lens.jpg\" alt=\"Twitter Lens\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u201cQue somos una PYME, Jes\u00fas\u201d \u2013 me dec\u00eda Paco. \u201cY nosotros, sin saberlo, hasta que nos lo dijo la redactora del peri\u00f3dico. Por lo visto, somos un ejemplo de PYME adaptada a la modernidad y la tecnolog\u00eda, por la cosa del Internet.\u201d Estas palabras las he sacado de un art\u00edculo que escrib\u00ed en 2007, con [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[11478,11479,11480,7616,5882,21,144],"class_list":["post-18207","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-cierra-negra-y-criminal","tag-en-el-cierre-de-negra-y-criminal","tag-hasta-la-polla-del-gratis-total","tag-libreria-negra-y-criminal","tag-montse-clave","tag-negra-y-criminal","tag-paco-camarasa"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18207","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18207"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18207\/revisions"}],"predecessor-version":[{"id":18213,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18207\/revisions\/18213"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18207"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18207"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18207"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}