{"id":18057,"date":"2015-06-19T12:58:15","date_gmt":"2015-06-19T11:58:15","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=18057"},"modified":"2015-06-19T12:59:29","modified_gmt":"2015-06-19T11:59:29","slug":"correr-con-un-gran-campeon-de-la-mano-de-tat-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/correr-con-un-gran-campeon-de-la-mano-de-tat-granada\/","title":{"rendered":"Correr con un gran campe\u00f3n de la mano de TAT Granada"},"content":{"rendered":"<p style=\"text-align: justify;\">Chema Mart\u00ednez lo es todo en el atletismo espa\u00f1ol. Y eso que est\u00e1 retirado. De la alta competici\u00f3n. Porque el t\u00edo no para. Ni deja de correr. Cada vez m\u00e1s lejos. Quiz\u00e1 no tan r\u00e1pido. Pero con el mismo esp\u00edritu. Y si no me crees, lee su <strong><span style=\"color: #ff00ff;\"><a style=\"color: #ff00ff;\" href=\"http:\/\/blogs.20minutos.es\/chema-martinez-no-pienses-corre\/\" target=\"_blank\">Blog<\/a><\/span><\/strong> y s\u00edguelo en Redes Sociales. \u00a1Te quedar\u00e1s sin hipo!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-Mart\u00ednez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18058\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-Mart\u00ednez-300x153.jpg\" alt=\"TAT Chema Mart\u00ednez\" width=\"300\" height=\"153\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-Mart\u00ednez-300x153.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-Mart\u00ednez-644x327.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-Mart\u00ednez.jpg 655w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s, <strong><span style=\"color: #ff00ff;\"><a style=\"color: #ff00ff;\" href=\"https:\/\/es.wikipedia.org\/wiki\/Chema_Mart%C3%ADnez\" target=\"_blank\">mirad su biograf\u00eda<\/a><\/span><\/strong> y ver\u00e9is c\u00f3mo os tiemblan las piernas. Y eso que ah\u00ed no habla de las pruebas de ultrafondo que est\u00e1 haciendo, como esos \u201cCuatro Desiertos\u201d que gan\u00f3 en 2014: Sahara, Gobi, Atacama y Ant\u00e1rtida. \u00a1Ah\u00ed es nada!<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18059\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-300x161.jpg\" alt=\"TAT Chema\" width=\"300\" height=\"161\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-300x161.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema-644x346.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/TAT-Chema.jpg 680w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El lunes, en Granada, los aficionados a esto de correr estamos de enhorabuena. Porque en el marco del Talking About Twitter que organiza IDEAL, adem\u00e1s de poder escuchar a Chema, que tiene m\u00e1s de 50.000 seguidores en Twitter, podremos correr con \u00e9l. <strong><span style=\"color: #ff00ff;\"><a href=\"http:\/\/www.ideal.es\/videos\/granada\/201506\/15\/chema-martinez-tiene-sorpresa-4297250762001-mm.html\" target=\"_blank\">\u00a1Aqu\u00ed lo cuenta!<\/a><\/span><\/strong><\/p>\n<p style=\"text-align: justify;\"><em><span style=\"text-decoration: underline;\"><strong>Ser\u00e1 el mismo lunes 22, a las 20 horas.<\/strong><\/span><\/em><\/p>\n<p style=\"text-align: justify;\">Y no vamos a correr por un sitio cualquiera. No. lo vamos a hacer en un enclave \u00fanico que, a esa hora de la tarde, desprende una magia especial: la Silla del Moro.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-chema.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18061\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-chema-300x188.jpg\" alt=\"Talking about Twitter chema\" width=\"300\" height=\"188\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-chema-300x188.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-chema-644x403.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-chema.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Los aficionados al deporte sabemos que, m\u00e1s all\u00e1 de marcas, ritmos y velocidades, hay ocasiones en que correr se transforma en una experiencia \u00fanica, memorable e inolvidable: d\u00edas con nieve, puestas de sol maravillosas, las arenas de esos desiertos que ha cruzado Chema, subidas a monta\u00f1as complicadas, bosques silenciosos\u2026 o enclaves hist\u00f3rico- art\u00edsticos \u00fanicos en el mundo.<\/p>\n<p style=\"text-align: justify;\">Correr por un enclave como la Silla del Moro ser\u00e1 una de esas experiencias memorables. Porque el Patronato de la Alhambra lo abre solo para nosotros. Por eso, la cita de las 20 horas incluye una explicaci\u00f3n pormenorizada del enclave. Adem\u00e1s de una buena foto con el campe\u00f3n, antes de salir a rodar. Y, los m\u00e1s fuertes, a esprintar.<\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-18060\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-300x200.jpg\" alt=\"Talking about Twitter\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter-644x429.jpg 644w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/06\/Talking-about-Twitter.jpg 890w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Porque Chema Mart\u00ednez estar\u00e1 all\u00ed. Y podremos acompa\u00f1arle, preguntarle y charlar con \u00e9l. Mientras corremos, claro. Unos m\u00e1s y otros menos. Pero todos disfrutando, que el circuito es corto y se le podr\u00e1 dar varias vueltas, a distintos ritmos y velocidades. \u00a1Para todos los gustos, oiga!<\/p>\n<p style=\"text-align: justify;\">Preguntar qui\u00e9n se anima no tiene mucho sentido. La pregunta ser\u00eda, al contrario: \u00bfno te lo ir\u00e1s a perder, verdad?<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\" size-full wp-image-17247 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/10\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Chema Mart\u00ednez lo es todo en el atletismo espa\u00f1ol. Y eso que est\u00e1 retirado. De la alta competici\u00f3n. Porque el t\u00edo no para. Ni deja de correr. Cada vez m\u00e1s lejos. Quiz\u00e1 no tan r\u00e1pido. Pero con el mismo esp\u00edritu. Y si no me crees, lee su Blog y s\u00edguelo en Redes Sociales. \u00a1Te quedar\u00e1s [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[34],"tags":[11374,7486,8666,11373,11372,11375,11376,11377],"class_list":["post-18057","post","type-post","status-publish","format-standard","hentry","category-correr","tag-correr-chema-martinez","tag-correr-granada","tag-talking-about-twitter","tag-talking-about-twitter-chema-martinez","tag-talking-about-twitter-granada","tag-tat-chema","tag-tat-chema-martinez","tag-twittquedada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18057","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=18057"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18057\/revisions"}],"predecessor-version":[{"id":18064,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/18057\/revisions\/18064"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=18057"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=18057"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=18057"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}