{"id":17868,"date":"2015-04-10T21:12:51","date_gmt":"2015-04-10T20:12:51","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=17868"},"modified":"2015-04-10T21:13:02","modified_gmt":"2015-04-10T20:13:02","slug":"crimen-sis-castigo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/crimen-sis-castigo\/","title":{"rendered":"Crimen sin castigo"},"content":{"rendered":"<p style=\"text-align: justify;\"><em>Ni de co\u00f1a. Es que ni de co\u00f1a te puedes\u00a0 hacer una idea de la ilusi\u00f3n que me hace publicar en la colecci\u00f3n Nube Negra que dirijo en la editorial Palabaristas esta salvaje colecci\u00f3n de cuentos de una autora a la que adoro y de una mujer a la que adoro m\u00e1s a\u00fan: Rebeca Murga. Aunque ah\u00ed va la informaci\u00f3n que he preparado para la web de Palabaristas, debes pinchar <a href=\"https:\/\/lektu.com\/l\/palabaristas\/crimen-sin-castigo\/1434\" target=\"_blank\">AQU\u00cd<\/a> y descargarte su libro ya. Vale 1 euro. T\u00fa me entiendes, \u00bfverdad?<\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/04\/Crimen-sin-castigo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17869\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/04\/Crimen-sin-castigo.jpg\" alt=\"Crimen sin castigo\" width=\"282\" height=\"400\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/04\/Crimen-sin-castigo.jpg 282w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/04\/Crimen-sin-castigo-211x300.jpg 211w\" sizes=\"auto, (max-width: 282px) 100vw, 282px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong><em>\u201cMi memoria est\u00e1 hecha de cristales rotos y cuellos cortados, de historia aprendida de los libros de texto y olvidada en las calles del centro de la ciudad, de negros y negras, de perros que no muerden y asesinos, y de una tercera guerra mundial nacida en nuestras manos\u201d.<\/em><\/strong><\/p>\n<p style=\"text-align: justify;\">As\u00ed comienza la \u201cTriste par\u00e1bola de la alegr\u00eda\u201d el primero de los cuentos que conforman \u201cCrimen sin castigo\u201d, una singular, brutal, desoladora y adictiva antolog\u00eda de relatos de la autora cubana Rebeca Murga, el nuevo t\u00edtulo que la editorial Palabaristas publica en su colecci\u00f3n Nube Negra.<\/p>\n<p style=\"text-align: justify;\">\u201cEl beso de la mujer\u2026\u201d, \u201cPu\u00f1aladas\u201d, \u201cIn crescendo\u201d y \u201cAtenuantes\u201d agrupan una selecci\u00f3n de relatos muy distintos entre s\u00ed, pero todos ellos suturados por la letal prosa de Rebeca, una escritora singular, \u00fanica en su especie. Una autora cuyos relatos duelen, por lo que nos vemos obligados a hacer una advertencia al lector, al estilo de las que sol\u00edan anteceder a la proyecci\u00f3n de ciertas pel\u00edculas: \u201cLa lectura de estos cuentos puede herir la sensibilidad del lector\u201d. Y no porque est\u00e9n impregnados de sangre, v\u00edsceras y otros humores del cuerpo, que lo est\u00e1n; sino porque despu\u00e9s de su lectura, ni la lej\u00eda m\u00e1s abrasiva puede eliminar la indeleble huella que dejan en manos, ojos\u2026 y psique.<\/p>\n<p style=\"text-align: justify;\">En estos tiempos de una correcci\u00f3n pol\u00edtica a ultranza y de una literatura insoportablemente light que trata de contentar a todos los p\u00fablicos, Rebeca Murga emerge como una inquietante y desasosegante tit\u00e1n que, en su obra, pone toda su pasi\u00f3n, miedos, anhelos y decepciones. Una obra visceral y salvaje, que no puede dejar indiferente al lector.<\/p>\n<p style=\"text-align: justify;\">Otra recomendaci\u00f3n: lee estos cuentos poco a poco. Muy poco a poco. Palade\u00e1ndolos y dej\u00e1ndote impregnar por su atm\u00f3sfera, disfrutando de la sonoridad de cada palabra, contamin\u00e1ndote por la ponzo\u00f1a de cada p\u00e1rrafo, por la tristeza y la pesadumbre de los personajes, por la violencia que les rodea y por la angustia que les ahoga.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/06\/Nube-Negra.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-16851\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/06\/Nube-Negra.jpg\" alt=\"Nube Negra\" width=\"250\" height=\"354\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/06\/Nube-Negra.jpg 250w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/06\/Nube-Negra-211x300.jpg 211w\" sizes=\"auto, (max-width: 250px) 100vw, 250px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Los cuentos de Rebeca Murga son droga dura y conviene ser muy cuidadosos en la administraci\u00f3n de las justas dosis de lectura. Pero si eres de car\u00e1cter ansioso y adictivo y devoras este libro en dos o tres sentadas, tampoco pasa nada: ya volver\u00e1s, m\u00e1s adelante, a retomar cada uno de los cuentos de una forma m\u00e1s tranquila y sosegada.<\/p>\n<p style=\"text-align: justify;\">Ten en cuenta que hay microrrelatos tan cortos y contundentes como este demoledor \u201cGratitud antisocial\u201d, que reza as\u00ed: \u201cTom\u00f3 la pluma y comenz\u00f3 a escribir sus cuentos infantiles. Solo as\u00ed le creer\u00edan las cosas horribles que hac\u00eda su madrastra\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a1Rebeca en estado puro!<\/p>\n<p style=\"text-align: justify;\">Pero no pienses que la autora, con sus cuentos, mata. No. No es eso. Rebeca nos recuerda a esos m\u00e9dicos de raza que, a veces clandestinamente, salvan la vida de las personas de la mala vida que, heridas a navajazos, balaceadas o apaleadas; no pueden acudir a un hospital. Porque la realidad es dura, cruel y sangrienta. Y el crimen no siempre paga. Pero, en cualquier caso, necesitamos notarios de la realidad como Rebeca Murga, para bucear en lo peor que hay en nosotros mismos. Porque solo as\u00ed podemos superar nuestros miedos y seguir adelante.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Palabaristas-Logo.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16830\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Palabaristas-Logo-236x300.jpg\" alt=\"Palabaristas Logo\" width=\"236\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Palabaristas-Logo-236x300.jpg 236w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Palabaristas-Logo-806x1024.jpg 806w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Palabaristas-Logo.jpg 1169w\" sizes=\"auto, (max-width: 236px) 100vw, 236px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Es dif\u00edcil resumir el contenido de todos estos cuentos en un pu\u00f1ado de l\u00edneas. Sobre todo, porque lo m\u00e1s importante es la densidad, la turbiedad del ambiente que describen. La contradicci\u00f3n de ser maestra de unos alumnos que est\u00e1n pendientes de cualquier cosa, menos de aprender. El absurdo de ser un soldado que no hace m\u00e1s que limpiar las letrinas en las que cagan otros soldados como \u00e9l. O la precariedad de los hospitales, en los que falta casi de todo. Menos veneno. Y drogas.<\/p>\n<p style=\"text-align: justify;\">Y, siempre, los personajes al margen. Personajes que exceden los l\u00edmites de lo convencional. Que sienten, piensan y viven de forma distinta a los dem\u00e1s. Personajes de los que apenas conoceremos unas pinceladas, pero que, gracias a la maestr\u00eda de Rebeca Murga, ya nos acompa\u00f1ar\u00e1n por siempre jam\u00e1s.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16834 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ni de co\u00f1a. Es que ni de co\u00f1a te puedes\u00a0 hacer una idea de la ilusi\u00f3n que me hace publicar en la colecci\u00f3n Nube Negra que dirijo en la editorial Palabaristas esta salvaje colecci\u00f3n de cuentos de una autora a la que adoro y de una mujer a la que adoro m\u00e1s a\u00fan: Rebeca Murga. [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21,10291],"tags":[11244,11243,10390,21,10292,10293,907],"class_list":["post-17868","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","category-nube-negra","tag-coleccion-nube-negra","tag-crimen-sin-castigo","tag-editorial-palabaristas","tag-negra-y-criminal","tag-nube-negra-2","tag-palabaristas","tag-rebeca-murga"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17868","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=17868"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17868\/revisions"}],"predecessor-version":[{"id":17871,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17868\/revisions\/17871"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=17868"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=17868"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=17868"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}