{"id":17755,"date":"2015-02-24T10:39:56","date_gmt":"2015-02-24T09:39:56","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=17755"},"modified":"2015-02-24T10:39:56","modified_gmt":"2015-02-24T09:39:56","slug":"nace-granada-noir","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/nace-granada-noir\/","title":{"rendered":"Nace Granada Noir"},"content":{"rendered":"<p style=\"text-align: justify;\"><strong>Ilusi\u00f3n. La ilusi\u00f3n de organizar algo que me apasiona, doblemente en mi casa (Granada y la Plaza de las Culturas de nuestro Museo), y de la mano de Gustavo G\u00f3mez, uno de esos tipos que consiguen que no haya dudas ni titubeos y que consigue que los planes salgan bien. Y la felicidad y el orgullo de ver que, en los medios de comunicaci\u00f3n, el proyecto est\u00e1 siendo excelentemente acogido<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a1LU-JA-ZO!<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Con la colaboraci\u00f3n de CajaGRANADA Fundaci\u00f3n, libros, cine, m\u00fasica, gastronom\u00eda, narraci\u00f3n oral, ciencia, fotograf\u00eda y un amplio etc\u00e9tera de actividades se dar\u00e1n cita en la Plaza de las Culturas del Museo CajaGRANADA, entre el 25 y el 30 de mayo; adem\u00e1s de apostar por una decida presencia en la Red <\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-IDEAL.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17756\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-IDEAL-225x300.jpg\" alt=\"Presentaci\u00f3n IDEAL\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-IDEAL-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-IDEAL-768x1024.jpg 768w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><\/strong><\/p>\n<p style=\"text-align: justify;\"><strong>Granada Noir, un festival multicultural de car\u00e1cter popular, abierto y gratuito, dirigido a todos los p\u00fablicos; contar\u00e1 con la presencia del escritor Fernando Mar\u00edas, reciente ganador del premio Biblioteca Breve, en su faceta m\u00e1s cin\u00e9fila y como autor e int\u00e9rprete de \u201cMon\u00f3logo de La Corporaci\u00f3n\u201d\u00a0 <\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En los \u00faltimos a\u00f1os, el g\u00e9nero polic\u00edaco, negro y criminal ha alcanzado un enorme auge, tanto en el \u00e1mbito literario como en el cinematogr\u00e1fico o en el mundo del c\u00f3mic. Este a\u00f1o, por ejemplo, dos de las pel\u00edculas espa\u00f1olas m\u00e1s populares y premiadas han sido de corte negro: \u201cLa isla m\u00ednima\u201d y \u201cEl ni\u00f1o\u201d. Las novelas y los tebeos polic\u00edacos copan las listas de los libros m\u00e1s vendidos y, a rebufo de la pionera y famosa Semana Negra de Gij\u00f3n, han ido naciendo diversos cert\u00e1menes y encuentros especializados en el g\u00e9nero polic\u00edaco por toda la geograf\u00eda espa\u00f1ola.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Parad\u00f3jicamente, en el sur de Espa\u00f1a no existe ni un solo certamen de estas caracter\u00edsticas y de ah\u00ed parte la celebraci\u00f3n de la primera edici\u00f3n de Granada Noir, en mayo de 2015, que se plantea como un festival multidisciplinar, muy volcado a las actividades populares y callejeras, tratando de involucrar a los vecinos y visitantes en las diferentes actividades que se realicen.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Hoy.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17757\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Hoy-300x225.jpg\" alt=\"Presentaci\u00f3n Granada Hoy\" width=\"300\" height=\"225\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Hoy-300x225.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Hoy-1024x768.jpg 1024w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Presentaciones de libros, tertulias y mesas redondas con autores de g\u00e9nero negro, conferencias sobre temas cient\u00edficos y proyecciones comentadas de cine negro cl\u00e1sico se acompa\u00f1ar\u00e1n con photocalls animados en un espacio tan emblem\u00e1tico como la Plaza de las Culturas del Museo CajaGRANADA. Igualmente habr\u00e1 m\u00fasica en directo, representaciones teatrales y juegos de pistas para menores; comidas tem\u00e1ticas, charlas en colegios e institutos, etc\u00e9tera.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Adem\u00e1s, el prop\u00f3sito del certamen es consolidar a Granada Noir como el referente de g\u00e9nero negro del sur de Espa\u00f1a y conseguir que su presencia se prolongue en la Red m\u00e1s all\u00e1 de su celebraci\u00f3n anual, a trav\u00e9s de la puesta en marcha, fomento y animaci\u00f3n de un Club de Lectura, un Club de Cine, Talleres de Relatos y Fotograf\u00eda en blanco y negro, c\u00f3mic, etc\u00e9tera.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Granada-Digital.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17761\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Granada-Digital-169x300.png\" alt=\"Presentaci\u00f3n Granada Noir Granada Digital\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Granada-Digital-169x300.png 169w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Granada-Digital-576x1024.png 576w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Granada-Digital.png 640w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><strong>Avance de la programaci\u00f3n de Granada Noir<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Una de las presencias confirmadas para esta primera edici\u00f3n de Granada Noir es la del escritor bilba\u00edno <strong>Fernando Mar\u00edas<\/strong>, reciente ganador del Premio Biblioteca Breve con su libro \u201cLa isla del padre\u201d y que tiene en su curr\u00edculum literario otros galardones tan importantes como el Premio Nadal, el Premio Primavera o el Ateneo de Sevilla.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Mar\u00edas-Lens.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17758\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Mar\u00edas-Lens-300x66.jpg\" alt=\"Mar\u00edas Lens\" width=\"300\" height=\"66\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Mar\u00edas-Lens-300x66.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Mar\u00edas-Lens.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">En Granada Noir, tendremos la oportunidad de contar con el Fernando Mar\u00edas m\u00e1s apasionadamente cin\u00e9filo, que presentar\u00e1 y comentar\u00e1 con el p\u00fablico dos pel\u00edculas de g\u00e9nero negro y criminal, que se proyectar\u00e1n en el Teatro CajaGRANADA los d\u00edas 26 y 27 de mayo, martes y mi\u00e9rcoles, respectivamente. Adem\u00e1s de otra iniciativa muy, muy especial.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Adem\u00e1s, Fernando Mar\u00edas estrenar\u00e1 e interpretar\u00e1 en Granada un espect\u00e1culo muy personal, especial y diferente: Mon\u00f3logo de La Corporaci\u00f3n, basado en su novela \u201cEsta noche morir\u00e9\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Yo-y-Fernando-Mar\u00edas.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17759\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Yo-y-Fernando-Mar\u00edas-300x135.jpg\" alt=\"Yo y Fernando Mar\u00edas\" width=\"300\" height=\"135\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Yo-y-Fernando-Mar\u00edas-300x135.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Yo-y-Fernando-Mar\u00edas.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Adem\u00e1s de contar con varios de los autores locales m\u00e1s comprometidos con el g\u00e9nero polic\u00edaco y con la presencia de escritores venidos de distintos puntos de Espa\u00f1a, el s\u00e1bado 30, se har\u00e1 entrega del I Premio Granada Noir a un autor de reconocido prestigio, atesorador de una brillante trayectoria literaria muy centrada en el g\u00e9nero negro y, como fin de fiesta, un concierto muy, muy especial.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><strong>El equipo de Granada Noir<\/strong><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En colaboraci\u00f3n con CajaGRANADA Fundaci\u00f3n, el Festival ser\u00e1 organizado por <a href=\"http:\/\/www.acentocomunicacion.com\/\" target=\"_blank\">Acento Comunicaci\u00f3n<\/a>, bajo la direcci\u00f3n de Jes\u00fas Lens.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens, escritor y colaborador en distintos medios de comunicaci\u00f3n de Andaluc\u00eda, es cr\u00edtico literario y cinematogr\u00e1fico; especialista en el g\u00e9nero polic\u00edaco, negro y criminal.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Ahora-Granada.png\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17760\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Ahora-Granada-169x300.png\" alt=\"Presentaci\u00f3n Granada Noir Ahora Granada\" width=\"169\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Ahora-Granada-169x300.png 169w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Ahora-Granada-576x1024.png 576w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Presentaci\u00f3n-Granada-Noir-Ahora-Granada.png 640w\" sizes=\"auto, (max-width: 169px) 100vw, 169px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Con cuatro libros publicados, ha participado, entre otros cert\u00e1menes, en diez ediciones de Semana Negra de Gij\u00f3n, donde ha ejercido como jurado de sus diversos premios literarios, adem\u00e1s de haber conducido presentaciones de libros, mesas redondas, talleres, etc\u00e9tera. Actualmente colabora con el peri\u00f3dico Ideal, con la emisora La Voz de Granada y con el programa El P\u00fablico de Canal Sur.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Acento Comunicaci\u00f3n es una empresa fundada y dirigida por el periodista Gustavo G\u00f3mez, con acreditada experiencia en la organizaci\u00f3n de eventos culturales, as\u00ed como en la creaci\u00f3n de contenidos digitales. Desde 2009 a 2014 ha organizado la Feria del Libro de Granada.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17247 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/10\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\n","protected":false},"excerpt":{"rendered":"<p>Ilusi\u00f3n. La ilusi\u00f3n de organizar algo que me apasiona, doblemente en mi casa (Granada y la Plaza de las Culturas de nuestro Museo), y de la mano de Gustavo G\u00f3mez, uno de esos tipos que consiguen que no haya dudas ni titubeos y que consigue que los planes salgan bien. Y la felicidad y el [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[11144],"tags":[106,10664,1449,11146,5701,8538,11145,7224,145,11147],"class_list":["post-17755","post","type-post","status-publish","format-standard","hentry","category-granada-noir","tag-cajagranada","tag-cajagranada-fundacion","tag-fernando-marias","tag-fernando-marias-la-corporacion","tag-genero-negro","tag-granada-negra","tag-granada-noir-2","tag-noir","tag-novela-negra","tag-plaza-culturas-cajagranada"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17755","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=17755"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17755\/revisions"}],"predecessor-version":[{"id":17762,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17755\/revisions\/17762"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=17755"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=17755"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=17755"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}