{"id":17711,"date":"2015-02-05T12:38:14","date_gmt":"2015-02-05T11:38:14","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=17711"},"modified":"2015-02-05T12:38:14","modified_gmt":"2015-02-05T11:38:14","slug":"secretos-del-arenal","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/secretos-del-arenal\/","title":{"rendered":"Secretos del Arenal"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00a1Qu\u00e9 alegr\u00eda me dio, all\u00e1 por el mes de junio, cuando le\u00ed en las redes sociales que F\u00e9lix G. Modro\u00f1o se hab\u00eda alzado con el Ateneo de Sevilla de este a\u00f1o!<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_17713\" aria-describedby=\"caption-attachment-17713\" style=\"width: 225px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-Salobre\u00f1a.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17713\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-Salobre\u00f1a-225x300.jpg\" alt=\"Foto: Silvia Romera\" width=\"225\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-Salobre\u00f1a-225x300.jpg 225w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-Salobre\u00f1a-768x1024.jpg 768w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-Salobre\u00f1a.jpg 960w\" sizes=\"auto, (max-width: 225px) 100vw, 225px\" \/><\/a><figcaption id=\"caption-attachment-17713\" class=\"wp-caption-text\">Foto: Silvia Romera<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/secretos-del-arenal.jpg\">\u00a0<\/a><\/p>\n<p style=\"text-align: justify;\">Alegr\u00eda de las grandes. Por dos razones. La primera, personal: desde que nos conocimos hace unos a\u00f1os, en Semana Negra, siempre hubo simpat\u00eda entre ambos. Por cuestiones literarias, profesionales, por formas de entender la vida, por compartir una importante querencia por Salobre\u00f1a\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y la segunda raz\u00f3n es que su anterior novela, \u201cLa ciudad de los ojos tristes\u201d, me hab\u00eda encantado. Una novela hist\u00f3rica trufada de polic\u00edaca. Una historia de amor con una protagonista fundamental: la ciudad de Bilbao. Un libro mestizo, que tocaba g\u00e9neros diversos, pero que en absoluto era un pastiche.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/secretos-del-arenal.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17712\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/secretos-del-arenal-238x300.jpg\" alt=\"secretos del arenal\" width=\"238\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/secretos-del-arenal-238x300.jpg 238w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/secretos-del-arenal.jpg 424w\" sizes=\"auto, (max-width: 238px) 100vw, 238px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">As\u00ed que, cuando F\u00e9lix me dijo que ven\u00eda a Granada y a Salobre\u00f1a a presentar la novela, le dije que estar\u00eda con \u00e9l en la librer\u00eda 1616 Books, el s\u00e1bado por la tarde, con Antonio, el Librero Loco; y los muchos y buenos amigos de la localidad costera granadina.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Hab\u00eda un problema: a\u00fan no hab\u00eda le\u00eddo el libro. Y no es que quedara mucho tiempo para la presentaci\u00f3n. Unos d\u00edas, apenas.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En otra situaci\u00f3n, con otro autor; me habr\u00eda zafado de la propuesta. Con F\u00e9lix no. Por amistad, claro. Pero, sobre todo, por confianza. Confianza en que su novela, aunque se acercaba a las 400 p\u00e1ginas, me iba a resultar f\u00e1cil de leer.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/F\u00e9lix-Modro\u00f1o.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17714\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/F\u00e9lix-Modro\u00f1o-300x168.jpg\" alt=\"F\u00e9lix Modro\u00f1o\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/F\u00e9lix-Modro\u00f1o-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/F\u00e9lix-Modro\u00f1o.jpg 575w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y esto, querido F\u00e9lix, no es dem\u00e9rito alguno, que no por estar escrita de una forma \u00e1gil y asequible al lector, una novela es menos novela. De hecho, desconf\u00edo de los autores que complican innecesariamente sus narraciones. O que las barroquizan sin necesidad, como si en vez de estar escribiendo una historia, estuvieran espesando la salsa de alg\u00fan guiso de ins\u00edpido de por s\u00ed.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y, efectivamente, la lectura de \u201cSecretos del Arenal\u201d fue un placer. Y un disfrute. En primer lugar, porque me encontr\u00e9 con dos novelas en vez de con una. Literalmente. Porque F\u00e9lix G. Modro\u00f1o introduce una historia que acontece en la Sevilla de los a\u00f1os 40 del pasado siglo en mitad de una trama actual.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y la f\u00f3rmula funciona.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Los saltos espacio temporales consiguen transportarte a dos ciudades diferentes, en \u00e9pocas muy distintas. \u00bfO no tanto? Porque las dos historias que cuenta F\u00e9lix son tr\u00e1gicas. Y en ambas, el papel de la mujer es muy importante. Hasta el punto de que la protagonista de la novela es una de ellas. Una chica de car\u00e1cter fuerte y muy alejada de cualquier arquetipo al uso.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-arenal-portada.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17716\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-arenal-portada-300x200.jpg\" alt=\"Secretos del arenal portada\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-arenal-portada-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-arenal-portada.jpg 600w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/F\u00e9lix-Modro\u00f1o.jpg\"><br \/>\n<\/a><\/p>\n<p style=\"text-align: justify;\">Silvia inicia su relaci\u00f3n con Mateo. Una relaci\u00f3n en la que el mundo del vino est\u00e1 muy presente. Pero hay un recuerdo, un fantasma que no deja de acosarla: el de su hermana, violada, asesinada y mutilada. Por alguien que no ha sido detenido. A\u00fan.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Y, mientras, en Sevilla, los falangistas conspiran contra Franco. Porque, en los primeros cuarenta, los equilibrios de poder entre los ganadores de la Guerra (in)Civil a\u00fan eran muy inestables. Y las conspiraciones estaban al orden del d\u00eda. Y de la noche. Y en ese universo turbio y violento, los m\u00e1s salvajes y desalmados son los que m\u00e1s tienen que ganar. Y los que menos tienen que perder.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_17715\" aria-describedby=\"caption-attachment-17715\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17715\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-300x256.jpg\" alt=\"Foto: Jos\u00e9 Hern\u00e1ndez Lechuga. El Cuate. \" width=\"300\" height=\"256\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n-300x256.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n.jpg 800w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-17715\" class=\"wp-caption-text\">Foto: Jos\u00e9 Hern\u00e1ndez Lechuga. El Cuate.<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2015\/02\/Secretos-del-Arenal-presentaci\u00f3n.jpg\">\u00a0<\/a><\/p>\n<p style=\"text-align: justify;\">A un ritmo endiablado, la novela avanza sin dar tregua al lector. Y las dos historias atrapan de tal manera que, cuando una se interrumpe para dar paso a la otra; ganas dan de saltarse el cap\u00edtulo que toque para seguir descubriendo los avatares de unos y otros.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Pero no.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Seamos disciplinados y pong\u00e1monos en manos de un autor experimentado que nos llevar\u00e1, con el pulso firme, hasta a \u00faltima p\u00e1gina. Y ser\u00e1 entonces y solo entonces cuando podamos respirar tranquilos, con la satisfacci\u00f3n de haber disfrutado una gran novela, tan bien documentada como mejor escrita.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-17247 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/10\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00a1Qu\u00e9 alegr\u00eda me dio, all\u00e1 por el mes de junio, cuando le\u00ed en las redes sociales que F\u00e9lix G. Modro\u00f1o se hab\u00eda alzado con el Ateneo de Sevilla de este a\u00f1o! \u00a0 Alegr\u00eda de las grandes. Por dos razones. La primera, personal: desde que nos conocimos hace unos a\u00f1os, en Semana Negra, siempre hubo simpat\u00eda [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[6604,11087,11088,7049,1601,11089,11086],"class_list":["post-17711","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-1616-books","tag-ateneo-sevilla","tag-editorial-algaida","tag-felix-modrono","tag-salobrena","tag-salobrena-mon-amour","tag-secretos-del-arenal"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17711","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=17711"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17711\/revisions"}],"predecessor-version":[{"id":17717,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17711\/revisions\/17717"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=17711"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=17711"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=17711"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}