{"id":17202,"date":"2014-09-24T08:47:42","date_gmt":"2014-09-24T07:47:42","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=17202"},"modified":"2014-09-24T08:48:06","modified_gmt":"2014-09-24T07:48:06","slug":"un-camino-a-traves-del-infierno","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/un-camino-a-traves-del-infierno\/","title":{"rendered":"Un camino a trav\u00e9s del infierno"},"content":{"rendered":"<p style=\"text-align: justify;\">Si ahora mismo leyera cinco manuscritos, negros y criminales, que disimularan el nombre de su personaje principal, para no dar pistas; creo estar en condiciones de asegurar que no tardar\u00eda ni tres p\u00e1ginas en descubrir cu\u00e1l de ellos ha sido escrito por Javier Hern\u00e1ndez Vel\u00e1zquez. Y no por sus dejes o t\u00e9rminos canarios, precisamente.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u201cLa vida es una derrota asumida. All\u00ed estaba, en aquel sal\u00f3n del hotel, en recuerdo de un tiempo en el que cre\u00ed que una canci\u00f3n podr\u00eda salvar el mundo (una \u00e9poca en que Michael Jackson a\u00fan era negro y estaba vivo)\u201d.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Javier-Hern\u00e1ndez.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17203\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Javier-Hern\u00e1ndez.jpg\" alt=\"UN CAMINO A TRAV\u00c9S DEL INFIERNO Javier Hern\u00e1ndez\" width=\"367\" height=\"496\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Javier-Hern\u00e1ndez.jpg 367w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Javier-Hern\u00e1ndez-221x300.jpg 221w\" sizes=\"auto, (max-width: 367px) 100vw, 367px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">As\u00ed comienza \u201cUn camino a trav\u00e9s del infierno\u201d, novela publicada por MAR Editor; finalista y menci\u00f3n especial del jurado del premio de novela negra L\u2019H Confidencial del a\u00f1o 2013.<\/p>\n<p style=\"text-align: justify;\">Con toda justicia, puedo decir ahora que la he le\u00eddo.<\/p>\n<p style=\"text-align: justify;\">Aunque le\u00eddo no es la expresi\u00f3n exacta. Porque arranqu\u00e9 con ella la noche del martes, en el Puerto de la Cruz, y cuando aterric\u00e9 en el aeropuerto de Granada, el mi\u00e9rcoles; Mat ya se hab\u00eda convertido en uno de esos compa\u00f1eros de viajes literarios con los que te apetecer\u00eda compartir tragos, golpes e historias, hasta bien entrada la madrugada.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-PORTADA.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17204\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-PORTADA-205x300.jpg\" alt=\"UN CAMINO A TRAV\u00c9S DEL INFIERNO PORTADA\" width=\"205\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-PORTADA-205x300.jpg 205w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-PORTADA.jpg 694w\" sizes=\"auto, (max-width: 205px) 100vw, 205px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Mat.<\/p>\n<p style=\"text-align: justify;\">A Mat ven\u00eda sigui\u00e9ndole la pista desde hace tiempo, a trav\u00e9s del Facebook. Es un tipo con gusto por las armas. Cortas. Un tipo que gasta una de esas sonrisas de medio lado que, dependiendo de por d\u00f3nde asome, da alegr\u00eda encontr\u00e1rsela\u2026 o miedo. Mucho miedo.<\/p>\n<p style=\"text-align: justify;\">Mat es detective. Privado. Y, obviamente, no lo lleva bien. Eso de investigar cuernos y bajas laborales es bastante ingrato. Un buen d\u00eda se cita con una clienta muy especial. Su amante, para ser exactos. Y el encargo que le hace es morrocotudo: buscar a la hija que tuvo con Vicente Chinea, a la saz\u00f3n, presidente del gobierno canario\u2026 en pleno proceso de reelecci\u00f3n.<\/p>\n<p style=\"text-align: justify;\">Entonces, el cristal de la ventana del garito en que est\u00e1n hablando salta por los aires\u2026<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Mat.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-17205\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Mat-300x168.jpg\" alt=\"UN CAMINO A TRAV\u00c9S DEL INFIERNO Mat\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Mat-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Mat.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Con esas mimbres, y con el personal\u00edsimo estilo que caracteriza a Javier Hern\u00e1ndez, la narraci\u00f3n de \u201cUn camino a trav\u00e9s del infierno\u201d, nos adentra en la podredumbre, la locura y la insania que yacen en el lado oscuro de cualquier sociedad, por aparentemente bonita y festiva que parezca.<\/p>\n<p style=\"text-align: justify;\">En este caso, por fortuna para \u00e9l y para sus lectores, Mat no estar\u00e1 solo en su particular temporada en el infierno. Por un lado, nos acompa\u00f1a Eva Millar. Por otro, su nueva secretaria. Impagables, ambas. Aunque tan parecidas como el d\u00eda y la noche. Como la cruz y la cara. Como el haz y el env\u00e9s. Y est\u00e1 el pol\u00edtico. Y su familia. La carnal y la otra. Porque muchos pol\u00edticos cada vez tienen un concepto muy laxo de lo que debe ser La Familia. Y el pasado, claro. Un pasado que pesa. Mucho.<\/p>\n<p style=\"text-align: justify;\">Pero, sobre todo, est\u00e1 Mat. Un Mat que ve la vida, como el autor, a trav\u00e9s de un personal\u00edsimo prisma, repleto de referencias a la m\u00fasica, al cine, a la televisi\u00f3n\u2026 y para los amantes del baloncesto, a la NBA.<\/p>\n<p style=\"text-align: justify;\">Porque nada de lo humano nos puede resultar ajeno.<\/p>\n<figure id=\"attachment_17206\" aria-describedby=\"caption-attachment-17206\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Lens.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-17206\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Lens-300x168.jpg\" alt=\"Javier, acreditando buen gusto literario ;-)\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Lens-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Lens.jpg 960w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-17206\" class=\"wp-caption-text\">Javier, acreditando buen gusto literario \ud83d\ude09<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Por ejemplo, la buena literatura. Esa que te sacude y que te noquea. Como \u201cUn camino a trav\u00e9s del infierno\u201d. Hasta el punto de que si la lees y no encuentras en ella un estilo fresco, desenfadado, \u00fanico y, esperemos que repetible por su autor en sus pr\u00f3ximas novelas, que ya esperamos impacientes; te pago una Alhambra Especial bien fresquita.<\/p>\n<p style=\"text-align: justify;\">Y como muestra de lo que digo, especialmente dedicada a mis buenos amigos del mundo de la canasta, unas l\u00edneas muy descriptivas:<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u201cMe tumb\u00e9 en el sill\u00f3n y encend\u00ed la pantalla de plasma para visionar un Detroit-Portland de las finales de la NBA del 89. Los Pistons s\u00ed que eran tipos duros. Despu\u00e9s de tocar fondo a finales de los setenta, la suerte regres\u00f3 a la Motown cuando seleccionaron en el draft al base Isiah Thomas. Al a\u00f1o siguiente adquirieron al p\u00edvot Bill Laimbeer de Cleveland y al base Vinnie Johnson de Seattle. Luego llegaron Dumars, Mahorn, Salley y Rodman. El coach Daly comprendi\u00f3 que deb\u00edan emplear un estilo agresivo que se gan\u00f3 el apodo de los Bad Boys. En aquel grupo mi debilidad era Laimbeer, un Harry el sucio de las canchas. <\/strong><\/em><\/p>\n<p style=\"text-align: justify;\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Laimbeer.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-17207\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Laimbeer.jpg\" alt=\"UN CAMINO A TRAV\u00c9S DEL INFIERNO Laimbeer\" width=\"384\" height=\"400\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Laimbeer.jpg 384w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/09\/UN-CAMINO-A-TRAV\u00c9S-DEL-INFIERNO-Laimbeer-288x300.jpg 288w\" sizes=\"auto, (max-width: 384px) 100vw, 384px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\"><em><strong>Duro, arrogante, provocador, un tipo despreciable. Todos lo consideraban un mat\u00f3n, pero era mucho m\u00e1s que eso. Aquel malcarado, hijo de un multimillonario comerciante de diamantes, era uno de los pocos jugadores que se hubiese ganado mejor la vida fuera de las canchas que dentro de ellas\u201d.<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16834 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Si ahora mismo leyera cinco manuscritos, negros y criminales, que disimularan el nombre de su personaje principal, para no dar pistas; creo estar en condiciones de asegurar que no tardar\u00eda ni tres p\u00e1ginas en descubrir cu\u00e1l de ellos ha sido escrito por Javier Hern\u00e1ndez Vel\u00e1zquez. Y no por sus dejes o t\u00e9rminos canarios, precisamente. \u201cLa [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[21],"tags":[10667,10668,10661,10670,2242,49,10669,21,10666,10665],"class_list":["post-17202","post","type-post","status-publish","format-standard","hentry","category-negra-y-criminal","tag-bill-laimbeer","tag-canarias-negra-y-criminal","tag-javier-hernandez-velazquez","tag-lh-confidencial","tag-lecturas","tag-libros","tag-mar-editor","tag-negra-y-criminal","tag-tenerife-noir","tag-un-camino-a-traves-del-infierno"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17202","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=17202"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17202\/revisions"}],"predecessor-version":[{"id":17209,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/17202\/revisions\/17209"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=17202"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=17202"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=17202"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}