{"id":16953,"date":"2014-07-03T13:18:08","date_gmt":"2014-07-03T12:18:08","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=16953"},"modified":"2014-07-03T13:18:08","modified_gmt":"2014-07-03T12:18:08","slug":"mi-otro-yo","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/mi-otro-yo\/","title":{"rendered":"Mi otro yo"},"content":{"rendered":"<p style=\"text-align: justify;\">\u00bfC\u00f3mo? \u00bfQu\u00e9 la directora espa\u00f1ola Isabel Coixet ha rodado una pel\u00edcula de terror adolescente con est\u00e9tica japonesa en la Gran Breta\u00f1a del siglo XXI? \u00bfEn serio?<\/p>\n<p style=\"text-align: justify;\">\u00a1Y tan en serio!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u201cMi otro yo\u201d se titula la cinta y, aunque reconozco que entr\u00e9 a la sala del cine cargado de prevenciones, reticencias y suspicacias, no tard\u00e9 en apartarlas para sumergirme en una historia de terror que, sin ser arrebatadora ni espeluznante, se deja ver con agrado y con un cierto desasosiego.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/mi-otro-yo\/mi-otro-yo\/\" rel=\"attachment wp-att-16954\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16954\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/07\/Mi-otro-yo-208x300.jpg\" alt=\"Mi otro yo\" width=\"208\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/07\/Mi-otro-yo-208x300.jpg 208w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/07\/Mi-otro-yo.jpg 832w\" sizes=\"auto, (max-width: 208px) 100vw, 208px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Ignoro si, como sostiene Coixet en las entrevistas de promoci\u00f3n de la pel\u00edcula, la adaptaci\u00f3n de la novela de Catherine MacPhail le ha resultado, en efecto, interesante y atractiva o si estamos ante una pel\u00edcula puramente alimenticia y filmada por (leg\u00edtimas) razones cremat\u00edsticas\u2026<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em><strong>(Si tienes inter\u00e9s en continuar leyendo esta rese\u00f1a \u2013lo que obviamente me agradar\u00eda lo que es muy mucho \ud83d\ude09 puedes seguir leyendo <a href=\"http:\/\/www.cinema2000.es\/lensanity\/mi-otro-yo-segun-jesus-lens\/\" target=\"_blank\">aqu\u00ed, en Lensanity<\/a>, el espacio web que me reserva Cinema 2000 para hablar de La pel\u00edcula de la semana)<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\" rel=\"attachment wp-att-16834\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16834 alignleft\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Firma-Twitter.jpg\" alt=\"Firma Twitter\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfC\u00f3mo? \u00bfQu\u00e9 la directora espa\u00f1ola Isabel Coixet ha rodado una pel\u00edcula de terror adolescente con est\u00e9tica japonesa en la Gran Breta\u00f1a del siglo XXI? \u00bfEn serio? \u00a1Y tan en serio! \u201cMi otro yo\u201d se titula la cinta y, aunque reconozco que entr\u00e9 a la sala del cine cargado de prevenciones, reticencias y suspicacias, no tard\u00e9 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[10,5872,7844,10427,9844,10426],"class_list":["post-16953","post","type-post","status-publish","format-standard","hentry","category-cine","tag-cine","tag-cine-de-estreno","tag-cinema-2000","tag-isabel-coixet","tag-lensanity","tag-mi-otro-yo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16953","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=16953"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16953\/revisions"}],"predecessor-version":[{"id":16956,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16953\/revisions\/16956"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=16953"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=16953"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=16953"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}