{"id":16737,"date":"2014-05-07T12:47:57","date_gmt":"2014-05-07T11:47:57","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=16737"},"modified":"2014-05-07T12:47:57","modified_gmt":"2014-05-07T11:47:57","slug":"lunes-negro-y-criminal-en-la-feria-del-libro-de-granada","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/lunes-negro-y-criminal-en-la-feria-del-libro-de-granada\/","title":{"rendered":"Lunes Negro (y criminal) en la Feria del Libro de Granada"},"content":{"rendered":"<p style=\"text-align: justify;\">Hablando con el responsable y coordinador de la <a href=\"http:\/\/www.ferialibrogranada.org\/\" target=\"_blank\">Feria del Libro de Granada<\/a>, el ubicuo, incansable y siempre sonriente Gustavo; planteamos la posibilidad de dedicar este a\u00f1o un espacio al g\u00e9nero negro, \u00e9se que tanto nos gusta, nos arrebata y, a veces, hasta nos enloquece.<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_16738\" aria-describedby=\"caption-attachment-16738\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Salazar-Alcaraz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-16738\" alt=\"We Love Noir\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Salazar-Alcaraz-300x247.jpg\" width=\"300\" height=\"247\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Salazar-Alcaraz-300x247.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Salazar-Alcaraz.jpg 335w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-16738\" class=\"wp-caption-text\">We Love Noir<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Y como Gustavo es un tipo, adem\u00e1s de positivo y calmado; muy efectivo y resolutivo\u2026 \u00a1voil\u00e1!<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Ah\u00ed lo tenemos. El Lunes Negro. Y Criminal.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Un lunes negro que comienza con una presentaci\u00f3n muy especial: al m\u00e1s reciente ganador del Premio Ja\u00e9n de Novela, que todos los a\u00f1os convoca CajaGRANADA y que publica nuestra querida editorial Almuzara: \u201c\u00d3pera Magna\u201d, de Vicente Marco.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Opera-Magna.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16739\" alt=\"Opera Magna\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Opera-Magna-195x300.jpg\" width=\"195\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Opera-Magna-195x300.jpg 195w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Opera-Magna-666x1024.jpg 666w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Opera-Magna.jpg 1042w\" sizes=\"auto, (max-width: 195px) 100vw, 195px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Y justo despu\u00e9s, una mesa redonda sobre el g\u00e9nero negro y su actualidad, en la que contaremos con tres voces j\u00f3venes y autorizadas: Alfonso Salazar, padre del inefable Detective del Zaid\u00edn; Alejandro Pedregosa y su narrativa emocional y Enrique Hormigo, detective privado de profesi\u00f3n, algunas de cuyas andanzas ha convertido en material narrativo para su m\u00e1s reciente novela.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Pedregosa.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16740\" alt=\"Lens Pedregosa\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Pedregosa-199x300.jpg\" width=\"199\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Pedregosa-199x300.jpg 199w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/05\/Lens-Pedregosa.jpg 633w\" sizes=\"auto, (max-width: 199px) 100vw, 199px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Empezaremos el lunes 12, a las siete de la tarde, en el Centro de Exposiciones de CajaGRANADA en Puerta Real, con la presentaci\u00f3n de Vicente Marco. Y mientras el autor valenciano se va a firmar ejemplares de su \u201c\u00d3pera Magna\u201d, en id\u00e9ntico escenario continuaremos hablando de g\u00e9nero negro y sus m\u00faltiples derivaciones.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El Lunes Negro va a ser un d\u00eda muy especial, que nos gustar\u00eda compartir contigo y conocer, de primera mano, en vivo y en directo, qu\u00e9 opinas del actual panorama de la narrativa en nuestro pa\u00eds, de la explosi\u00f3n del g\u00e9nero negro y criminal y del futuro inmediato que tenemos por delante.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfTe vienes?<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p><a href=\"https:\/\/twitter.com\/Jesus_Lens\" target=\"_blank\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-16532 alignleft\" alt=\"Firma Twitter\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/03\/Firma-Twitter.jpg\" width=\"196\" height=\"47\" \/><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hablando con el responsable y coordinador de la Feria del Libro de Granada, el ubicuo, incansable y siempre sonriente Gustavo; planteamos la posibilidad de dedicar este a\u00f1o un espacio al g\u00e9nero negro, \u00e9se que tanto nos gusta, nos arrebata y, a veces, hasta nos enloquece. Y como Gustavo es un tipo, adem\u00e1s de positivo y [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9],"tags":[953,10258,10259,8458,10260],"class_list":["post-16737","post","type-post","status-publish","format-standard","hentry","category-literarios","tag-feria-del-libro-de-granada","tag-lunes-negro","tag-lunes-negro-y-criminal","tag-programa-feria-libro-granada","tag-programa-feria-libro-granada-2014"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=16737"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16737\/revisions"}],"predecessor-version":[{"id":16742,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16737\/revisions\/16742"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=16737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=16737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=16737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}