{"id":16322,"date":"2014-02-19T14:52:59","date_gmt":"2014-02-19T13:52:59","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=16322"},"modified":"2014-02-19T14:52:59","modified_gmt":"2014-02-19T13:52:59","slug":"homenaje-a-benny-golson","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/homenaje-a-benny-golson\/","title":{"rendered":"Homenaje a Benny Golson"},"content":{"rendered":"<p style=\"text-align: justify;\">Hoy mi\u00e9rcoles, desde las 22.30 horas, la Asociaci\u00f3n de Jazz Ool Ya Koo presenta en el Club Magic un homenaje al saxofonista Benny Golson, a trav\u00e9s del grupo Benny Golson\u2019s Legacy, compuesto por Carlos Ligero al saxo tenor, Antoine Mader al tromb\u00f3n, Jos\u00e9 Ignacio Hern\u00e1ndez al piano, Cucu Fern\u00e1ndez al contrabajo y Sergio D\u00edaz a la bater\u00eda.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Benny-Golson.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-16323\" alt=\"Benny Golson\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Benny-Golson-300x212.jpg\" width=\"300\" height=\"212\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Benny-Golson-300x212.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Benny-Golson.jpg 962w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Nacido el 25 de enero de 1929, Benny Golson es un saxofonista tenor, compositor y arreglista estadounidense m\u00e1s asociado con diferentes estilos, como el bebop o el hard bop. Integrante de grupos capitales como The Jazz Messengers, en la discograf\u00eda oficial de Golson hay m\u00e1s de veinte grabaciones como solista, lo que le acreditan como uno de los grandes maestros del jazz de todos los tiempos.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Como homenaje al maestro, el quinteto Benny Golson\u2019s Legacy interpreta algunos de los temas de Golson que m\u00e1s han trascendido hasta nuestros d\u00edas. As\u00ed, tendremos la oportunidad de escuchar canciones como Whisper Not, Along Betty, Blues March o I Remember Clifford, entre otros grandes cl\u00e1sicos, en un concierto irrepetible.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">\u00bfServir\u00e1 este concierto para animar a la publicaci\u00f3n del disco grabado por Golson, dirigiendo a la Big Band de Granada, en uno de los conciertos m\u00e1s memorables del Festival de Jazz de Granada de hace unos a\u00f1os?<\/p>\n<p style=\"text-align: justify;\">\n<figure id=\"attachment_16324\" aria-describedby=\"caption-attachment-16324\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Serio-D\u00edaz.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-16324\" alt=\"Sergio D\u00edaz, a la bater\u00eda\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Serio-D\u00edaz-300x199.jpg\" width=\"300\" height=\"199\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Serio-D\u00edaz-300x199.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2014\/02\/Serio-D\u00edaz.jpg 640w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-16324\" class=\"wp-caption-text\">Sergio D\u00edaz, a la bater\u00eda<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Una nueva ocasi\u00f3n para para disfrutar de la m\u00fasica m\u00e1s caliente en directo, un privilegio que, dada la actual situaci\u00f3n del arte y la cultura en nuestra sociedad, no se debe desde\u00f1ar.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em><strong>Sobre Ool Ya Koo y el Club Magic<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">La Asociaci\u00f3n Ool Ya Koo tiene como objetivo el promover la divulgaci\u00f3n, conocimiento y disfrute de la m\u00fasica de jazz -y otros g\u00e9neros musicales afines- entre los ciudadanos as\u00ed como potenciar la m\u00fasica de jazz en directo. Adem\u00e1s, Ool Ya Koo quiere cultivar la uni\u00f3n y el intercambio de ideas entre aficionados, m\u00fasicos y asociaciones afines, estableciendo v\u00ednculos y favoreciendo la realizaci\u00f3n de actividades conjuntas y fomentando la creaci\u00f3n de nuevos aficionados entre la infancia y la juventud.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">El Club Magic, en los bajos de la Plaza de Toros, se ha convertido en el templo por excelencia del jazz en vivo en Granada, albergando la programaci\u00f3n semanal de conciertos de la Asociaci\u00f3n Ool Ya Koo y colaborando con el Festival de Jazz de la ciudad, adem\u00e1s de ofrecer m\u00fasica variada y adaptada a todo tipo de p\u00fablico a lo largo de la semana y los fines de semana.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">En palabras de Juan Carlos Cifuentes, Cifu, m\u00edtico director del programa \u201cJazz entre Amigos\u201d, el Club Magic hace honor a su nombre: hay magia en el ambiente.<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\"><em><strong>Informaci\u00f3n:<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Fecha: mi\u00e9rcoles 19 de febrero<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Hora: 22.30 horas<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Lugar: Magic Club. Avenida Doctor Ol\u00f3riz, 25 (Bajos de la Plaza de Toros). Granada<\/p>\n<p style=\"text-align: justify;\">\n<p style=\"text-align: justify;\">Precio de la entrada: Gratis para los socios de Ool Ya Koo. 6 euros con consumici\u00f3n para los no socios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy mi\u00e9rcoles, desde las 22.30 horas, la Asociaci\u00f3n de Jazz Ool Ya Koo presenta en el Club Magic un homenaje al saxofonista Benny Golson, a trav\u00e9s del grupo Benny Golson\u2019s Legacy, compuesto por Carlos Ligero al saxo tenor, Antoine Mader al tromb\u00f3n, Jos\u00e9 Ignacio Hern\u00e1ndez al piano, Cucu Fern\u00e1ndez al contrabajo y Sergio D\u00edaz a [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[9999,10000,9502,7931,10001,8107],"class_list":["post-16322","post","type-post","status-publish","format-standard","hentry","category-musica","tag-benny-golson","tag-benny-golsons-legacy","tag-club-magic","tag-jazz-en-granada","tag-magic-granada","tag-ool-ya-koo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16322","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=16322"}],"version-history":[{"count":1,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16322\/revisions"}],"predecessor-version":[{"id":16325,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/16322\/revisions\/16325"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=16322"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=16322"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=16322"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}