{"id":157,"date":"2008-04-07T18:24:00","date_gmt":"2008-04-07T17:24:00","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=157"},"modified":"2008-04-07T18:24:00","modified_gmt":"2008-04-07T17:24:00","slug":"una-mirada-nostalgica-a-dire-straits","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/una-mirada-nostalgica-a-dire-straits\/","title":{"rendered":"UNA MIRADA NOST\u00c1LGICA A DIRE STRAITS"},"content":{"rendered":"<table id=\"HB_Mail_Container\" height=\"100%\" cellspacing=\"0\" cellpadding=\"0\" width=\"100%\" border=\"0\" unselectable=\"on\">\n<tbody>\n<tr height=\"100%\" unselectable=\"on\" width=\"100%\">\n<td id=\"HB_Focus_Element\" valign=\"top\" width=\"100%\" background=\"\" height=\"250\" unselectable=\"off\">\n<div align=\"justify\">El problema fue m\u00edo, lo reconozco.<\/p>\n<p>Ir a un concierto de un tal Mark Knopfler, al que perd\u00ed la pista desde el punto y hora en que disolvi\u00f3 a los Dire Straits, era absurdo. <\/p><\/div>\n<div align=\"justify\"><\/div>\n<p align=\"justify\"><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5186556294990957714\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R_pZeIKAjJI\/AAAAAAAABOc\/0L7LAkAu7RQ\/s400\/_011.jpg\" border=\"0\" \/><br \/>No le hab\u00eda seguido en su carrera en solitario, no conoc\u00eda nada de sus \u00faltimos discos y, lo que es peor, no hice nada por remediarle en los muchos meses que me he pasado con la entrada para el concierto de Atarfe del pasado s\u00e1bado en el bolsillo.<\/p>\n<p>Es decir, que yo iba al concierto a escuchar a los Dire Straits. Como el 85% del p\u00fablico, por otra parte. <\/p>\n<p align=\"justify\"><\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5186556299285925042\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp1.blogger.com\/_r6VY1mvj3jk\/R_pZeYKAjLI\/AAAAAAAABOs\/U9e4Vwk2gFk\/s400\/_012.jpg\" border=\"0\" \/><br \/>Lo que pasa es que yo soy un venado. O un borrico al que no le gusta mirar atr\u00e1s, ni con ira, ni con nostalgia. Adelante y al frente. Siempre. Por eso, cuando son\u00f3 \u201cThe tunnel of love\u201d, con sus Romeo &amp; Juliet, me dio un baj\u00f3n. Y, aunque disfrut\u00e9 del \u201cSultans of swing\u201d desde el Thank youuuuuuu!!!!!!!!! con que fue introducido por Knopfler, el resto de las canciones de los Straits me dejaron trist\u00f3n y apagado.<\/p>\n<p>Demasiados recuerdos de una arcadia feliz en que, con 15 y 17 a\u00f1os, no ten\u00edas preocupaci\u00f3n alguna. D\u00edas de vino y rosas en que escuchar \u201cMoney for nothing\u201d era lo mejor de lo mejor.<\/p>\n<p>Vale. Mark digitaliza como nadie. Sus guitarras son una maravilla y algunas de las notas que les arranca son memorables. Pero el Knopfler en clave \u00edntima, como me dec\u00eda Alberto esta ma\u00f1ana, se perd\u00eda entre las 10.000 personas que quer\u00edan marcha. Y la marcha&#8230; pues que, personalmente, me pill\u00f3 cansado, o melanc\u00f3lico, o de baj\u00f3n. <\/p>\n<p><img decoding=\"async\" id=\"BLOGGER_PHOTO_ID_5186556294990957730\" style=\"DISPLAY: block; MARGIN: 0px auto 10px; CURSOR: hand; TEXT-ALIGN: center\" alt=\"\" src=\"http:\/\/bp0.blogger.com\/_r6VY1mvj3jk\/R_pZeIKAjKI\/AAAAAAAABOk\/hneyGIcA0kk\/s400\/_07.jpg\" border=\"0\" \/><br \/>Y que no. Que ya no quiero escuchar m\u00e1s a gente que vive en el pasado. O que, aunque intenta vivir en el presente, dio lo mejor de s\u00ed hace muchos, muchos a\u00f1os. Es injusto. Lo s\u00e9. Pero as\u00ed lo sent\u00ed y as\u00ed se lo cuento&#8230; reiterando que el problema fue m\u00edo y exclusivamente m\u00edo.<\/p>\n<p>Jes\u00fas Lens Espinosa de los Monteros.<\/p>\n<\/td>\n<\/tr>\n<tr unselectable=\"on\" hb_tag=\"1\">\n<td style=\"FONT-SIZE: 1pt\" height=\"1\" unselectable=\"on\"><\/p>\n<div id=\"hotbar_promo\"><\/div>\n<\/td>\n<\/tr>\n<\/tbody>\n<\/table>\n","protected":false},"excerpt":{"rendered":"<p>El problema fue m\u00edo, lo reconozco. Ir a un concierto de un tal Mark Knopfler, al que perd\u00ed la pista desde el punto y hora en que disolvi\u00f3 a los Dire Straits, era absurdo. No le hab\u00eda seguido en su carrera en solitario, no conoc\u00eda nada de sus \u00faltimos discos y, lo que es peor, [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[17],"tags":[],"class_list":["post-157","post","type-post","status-publish","format-standard","hentry","category-musica"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/157","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=157"}],"version-history":[{"count":0,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/157\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=157"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=157"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=157"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}