{"id":15365,"date":"2013-10-25T12:01:28","date_gmt":"2013-10-25T11:01:28","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=15365"},"modified":"2013-10-25T12:01:48","modified_gmt":"2013-10-25T11:01:48","slug":"carlos-bassas-del-rey-premio-de-novela-negra-ciudad-de-carmona-con-el-honor-es-una-mortaja","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/carlos-bassas-del-rey-premio-de-novela-negra-ciudad-de-carmona-con-el-honor-es-una-mortaja\/","title":{"rendered":"Carlos Bassas del Rey, Premio de novela negra Ciudad de Carmona con \u00abEl honor es una mortaja\u00bb"},"content":{"rendered":"<p style=\"text-align: justify;\">El escritor catal\u00e1n Carlos Bassas del Rey ha sido el ganador del VII Premio Internacional de Novela Negra Ciudad de Carmona con su obra El honor es una mortaja, un galard\u00f3n que recibir\u00e1 hoy vienes a las 20:30 horas en la antigua Capilla de la Residencia de San Pedro de Carmona de manos del Alcalde de la ciudad, Juan Manuel \u00c1vila Guti\u00e9rrez, y de Manuel Pimentel Siles, presidente de la editorial Almuzara.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Carlos-Bassas-del-Rey.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15366\" alt=\"Carlos Bassas del Rey\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Carlos-Bassas-del-Rey-300x263.jpg\" width=\"300\" height=\"263\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Carlos-Bassas-del-Rey-300x263.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Carlos-Bassas-del-Rey.jpg 990w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">El honor es una mortaja es una novela de lenguaje descarnado y di\u00e1logos punzantes y \u00e1giles. Una narraci\u00f3n trepidante por la que discurre un elenco de personajes que remite al m\u00e1s cl\u00e1sico g\u00e9nero negro: polic\u00edas de diferentes pelajes y generaciones, asesinos profesionales, matarifes novatos, un detective de oscuro pasado, mujeres que pagan por los pecados de sus maridos y un turbio empresario del crimen. Pero es tambi\u00e9n un recorrido por distintas formas de entender la venganza, el honor y el deber en dos culturas muy lejanas, pero quiz\u00e1 no tan distintas.<\/p>\n<p style=\"text-align: justify;\">Para su autor se trata de una historia de venganza a la que se le ha eliminado todo el componente emocional.<\/p>\n<p style=\"text-align: justify;\"><em><strong>\u201cMe interesaba explorar la posibilidad de un personaje que decide acometer una venganza sin odio, sin que sus sentimientos jueguen un papel en su motivaci\u00f3n, sino por simple sentido del deber, como un supuesto samur\u00e1i cl\u00e1sico. Por una cuesti\u00f3n de obligaci\u00f3n. Ver si ese hecho anula el propio concepto de venganza tal y como lo entendemos en occidente; si la venganza, para ser comprendida como tal, necesita de esos mimbres o no. As\u00ed es la pena de muerte, por ejemplo: una venganza fr\u00eda, institucionalizada y mecanizada en la que se aplica un deber sin que los sentimientos jueguen un papel en ello\u201d<\/strong><\/em>.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Bassas-del-Rey.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-15367\" alt=\"Bassas del Rey\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Bassas-del-Rey.jpg\" width=\"300\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Bassas-del-Rey.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Bassas-del-Rey-150x150.jpg 150w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">La historia comienza cuando un rumano es asesinado con el cubo de una fregona; un inmigrante muerto que no importa a nadie, salvo al hombre que ha querido arrebatarle la vida y al polic\u00eda que habr\u00e1 de ocuparse del caso. Al primer cad\u00e1ver le seguir\u00e1 el de un c\u00f3mplice, ambos cr\u00edmenes unidos en apariencia por el mismo asesino, torpe pero resuelto.<\/p>\n<p style=\"text-align: justify;\">El inspector Herodoto Corominas tira del hilo hasta relacionar estos cr\u00edmenes con un atraco ocurrido dos a\u00f1os atr\u00e1s en el que muere una mujer y su hijo, cuyo padre amn\u00e9sico est\u00e1 condenado a olvidar qui\u00e9n fue el asesino. \u00bfPor qu\u00e9 iba alguien a vengar la muerte de dos completos extra\u00f1os, a los que no recordar\u00e1 jam\u00e1s?<\/p>\n<p style=\"text-align: justify;\">El honor es una mortaja es una novela que entronca ejemplarmente con los c\u00e1nones cl\u00e1sicos del noir, un \u00e1mbito literario en el que la tradici\u00f3n de los Chandler, Hammett y compa\u00f1\u00eda pesa lo suyo y ha ejercido desde siempre un notable influjo entre los incondicionales del g\u00e9nero. Bassas ha urdido una trama en la que la venganza juega un rol esencial, y en la que los di\u00e1logos, chispeantes y cargados de sarcasmo e iron\u00eda, constituyen una baza ganadora de primer orden.<\/p>\n<figure id=\"attachment_15368\" aria-describedby=\"caption-attachment-15368\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Manuel-Pimentel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15368\" alt=\"Manuel Pimentel, editor y activista cultural\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Manuel-Pimentel-300x209.jpg\" width=\"300\" height=\"209\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Manuel-Pimentel-300x209.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Manuel-Pimentel.jpg 644w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-15368\" class=\"wp-caption-text\">Manuel Pimentel, editor y activista cultural<\/figcaption><\/figure>\n<p style=\"text-align: justify;\"><em><strong>\u201cMe gusta el g\u00e9nero negro porque, m\u00e1s all\u00e1 de las tramas policiales, detectivescas, criminales, es un g\u00e9nero social muy apegado al terreno, al d\u00eda a d\u00eda. De un realismo a veces doloroso, otras ir\u00f3nico, otras mordaz. Al menos el g\u00e9nero negro que a m\u00ed me gusta, el que pari\u00f3 Manuel V\u00e1zquez Montalban y el que practican Camilleri y Petros M\u00e1rkaris, otros dos grandes referentes; y el que nos regalan escritores como Guillermo Orsi, Lorenzo Silva, Fred Vargas, Leonardo Padura o Amir Valle: compromiso con la realidad, cr\u00edtica social, personajes de la calle, que uno se encuentra por la vida. Es la novela negra que inici\u00f3 Hammett\u201d<\/strong><\/em>, comenta el autor.<\/p>\n<p style=\"text-align: justify;\">Carlos Bassas del Rey (Barcelona, 1974) es Doctor en Ciencias de la Informaci\u00f3n por la Universidad de Navarra. Complet\u00f3 su formaci\u00f3n como guionista con seminarios internacionales impartidos por maestros como Richard Walter o Linda Seger y es escritor audiovisual de diversas productoras, labor que compagina con la docencia en la Universidad P\u00fablica de Navarra y en la Escuela de Imagen y Sonido de Pamplona.<\/p>\n<p style=\"text-align: justify;\">Ha escrito cortometrajes, documentales, largometrajes, videoclips y spots publicitarios para empresas nacionales y multinacionales. Tambi\u00e9n ha dirigido e impartido numerosos cursos de escritura creativa y narrativa audiovisual, ciclos de cine y conferencias sobre el s\u00e9ptimo arte, adem\u00e1s de ser comisario de dos exposiciones (\u00abDe Altamira al cinemat\u00f3grafo: una odisea de la imagen\u00bb y \u00abNavarra y el cine\u00bb).<\/p>\n<p style=\"text-align: justify;\">En 2007 fue galardonado con el Premio Pl\u00e1cido al Mejor Gui\u00f3n de Largometraje en el IX Festival Internacional de Cine Negro de Manresa, y su gui\u00f3n Malinche fue subvencionado por el ICAA en las Ayudas al Desarrollo de Gui\u00f3n de Largometraje. Ha desempe\u00f1ado labores como director de fotograf\u00eda y montador, adem\u00e1s de ejercer la cr\u00edtica de cine en diversos medios y ser jurado en cert\u00e1menes de cortometraje (Peralta, Bidasoa, Pamplona).<\/p>\n<p style=\"text-align: justify;\">En 2009 fue coordinador del libro Tasio 25, editado por el Gobierno de Navarra con motivo del aniversario de la pel\u00edcula de Montxo Armend\u00e1riz, y es Vocal de Cine del Ateneo Navarro.<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El escritor catal\u00e1n Carlos Bassas del Rey ha sido el ganador del VII Premio Internacional de Novela Negra Ciudad de Carmona con su obra El honor es una mortaja, un galard\u00f3n que recibir\u00e1 hoy vienes a las 20:30 horas en la antigua Capilla de la Residencia de San Pedro de Carmona de manos del Alcalde [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[9,21],"tags":[9363,9360,9364,9362,9365,9361],"class_list":["post-15365","post","type-post","status-publish","format-standard","hentry","category-literarios","category-negra-y-criminal","tag-bassas-del-rey","tag-carlos-bassas-del-rey","tag-carmona-novela-negra","tag-el-honor-es-una-mortaja","tag-ganador-premio-carmona-novela-negra","tag-premio-de-novela-negra-ciudad-de-carmona"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=15365"}],"version-history":[{"count":2,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15365\/revisions"}],"predecessor-version":[{"id":15370,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15365\/revisions\/15370"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=15365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=15365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=15365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}