{"id":15349,"date":"2013-10-24T10:47:37","date_gmt":"2013-10-24T09:47:37","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=15349"},"modified":"2013-10-24T10:55:12","modified_gmt":"2013-10-24T09:55:12","slug":"participando","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/participando\/","title":{"rendered":"Participando"},"content":{"rendered":"<p style=\"text-align: justify;\"><em><strong>Hoy publico este art\u00edculo en IDEAL. \u00bfC\u00f3mo ves t\u00fa esto de la participaci\u00f3n?<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Yo pensaba que era el acontecimiento pero, en realidad, es la participaci\u00f3n. As\u00ed lo ha puesto de manifiesto, por ejemplo, la nutrida concurrencia a buena parte de las actividades organizadas bajo el paraguas de La Noche en Blanco o los llenazos en varias salas para disfrutar de <a href=\"http:\/\/www.ideal.es\/granada\/20131024\/mas-actualidad\/cultura\/taquillazo-cines-euros-201310240022.html\" target=\"_blank\">La Fiesta del Cine<\/a>. Que el precio tambi\u00e9n importa, por supuesto. Pero que el hecho de participar termina por darle el sentido a infinidad de actividades l\u00fadico-culturales y deportivas.<\/p>\n<figure id=\"attachment_15350\" aria-describedby=\"caption-attachment-15350\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Noche-en-Blanco.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15350\" alt=\"Petada, la Noche en Blanco\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Noche-en-Blanco-300x168.jpg\" width=\"300\" height=\"168\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Noche-en-Blanco-300x168.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Noche-en-Blanco.jpg 619w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-15350\" class=\"wp-caption-text\">Petada, la Noche en Blanco<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">As\u00ed, ir a ver las exposiciones de Dal\u00ed, Vel\u00e1zquez o Hopper ofrece la posibilidad de gozar de un evento cultural multitudinario que, adem\u00e1s, permite participar de las conversaciones posteriores que el mismo genera. Conversaciones de las de verdad, de las de toda la vida. Pero, sobre todo, visitar las muestras temporales del Thyssen o del Reina Sof\u00eda da acceso a esos otros foros cada d\u00eda m\u00e1s importantes: los virtuales.<\/p>\n<p style=\"text-align: justify;\">Cuando cuelgas una foto en tu muro del Facebook, posando frente al tigre desbocado de Dal\u00ed, est\u00e1s abriendo la veda a una sucesiva oleada de comentarios, mails, chats, privados, g\u00fcasaps, etc\u00e9tera que te hacen participar de una conversaci\u00f3n global. Que es lo que se lleva ahora. Ir al Prado est\u00e1 muy bien, pero nadie habla de las grandes obras de Rubens. Sin embargo, en 2013, todos tenemos algo que decir sobre el surrealismo y sus ap\u00f3stoles.<\/p>\n<figure id=\"attachment_15351\" aria-describedby=\"caption-attachment-15351\" style=\"width: 560px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Hopper.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-full wp-image-15351\" alt=\"Hopper, abarrotado\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Hopper.jpg\" width=\"560\" height=\"400\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Hopper.jpg 560w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Hopper-300x214.jpg 300w\" sizes=\"auto, (max-width: 560px) 100vw, 560px\" \/><\/a><figcaption id=\"caption-attachment-15351\" class=\"wp-caption-text\">Hopper, abarrotado<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">Y ah\u00ed radica, tambi\u00e9n, buena parte del \u00e9xito de muchas de las series de televisi\u00f3n que todo el mundo tiene en la boca: si no has visto el comienzo de la tercera temporada de \u201cHomeland\u201d o la vuelta de \u201cThe Walking Dead\u201d, no eres nadie en la barra del bar y corres el riesgo de quedar excluido de buena parte de las conversaciones. \u00a1Ese Twitter, echando humo con todo el mundo comentando en tiempo real lo que pasa en cada cap\u00edtulo! Por eso, adem\u00e1s, todas las grandes cadenas est\u00e1n desarrollando Apps para tratar de canalizar las conversaciones seri\u00e9filas hacia sus dominios, a ver si consiguen que los seguidores de Brody se enganchen a \u201cThe Bridge\u201d o \u201cThe Americans\u201d.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Bridge.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15352\" alt=\"Participaci\u00f3n Bridge\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Bridge-200x300.jpg\" width=\"200\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Bridge-200x300.jpg 200w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Bridge-682x1024.jpg 682w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Bridge.jpg 800w\" sizes=\"auto, (max-width: 200px) 100vw, 200px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">De esta contagiosa y extraordinaria fiebre por la participaci\u00f3n viene, tambi\u00e9n, el \u00e9xito de esos Clubes de Lectura en los que los aficionados a la literatura tienen ocasi\u00f3n de compartir sus vivencias, sus sensaciones, sus gustos y sus disgustos. Y es que la lectura, afici\u00f3n solitaria como pocas, tambi\u00e9n exige su cuota participativa. Por eso, cuando se desatan fen\u00f3menos como los de Grey, Larsson o Da Vinci, sus efectos son como los de un tsunami.<\/p>\n<figure id=\"attachment_15353\" aria-describedby=\"caption-attachment-15353\" style=\"width: 300px\" class=\"wp-caption aligncenter\"><a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Cine.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"size-medium wp-image-15353\" alt=\"El cine, hasta la bola\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Cine-300x200.jpg\" width=\"300\" height=\"200\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Cine-300x200.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Cine-1024x683.jpg 1024w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/10\/Participaci\u00f3n-Cine.jpg 1349w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><figcaption id=\"caption-attachment-15353\" class=\"wp-caption-text\">El cine, hasta la bola<\/figcaption><\/figure>\n<p style=\"text-align: justify;\">O las Jornadas Gastron\u00f3micas. Raro es el restaurante que no organiza alg\u00fan tipo de evento que incite a los clientes a participar en algo que, se supone, debe ser algo m\u00e1s que una comida o una cena. Cuando no es un cocinero invitado, es una cata, un maridaje o una degustaci\u00f3n. Lo que sea, con tal de que el cliente se sienta part\u00edcipe, integrante o protagonista. Es el signo de los tiempos.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens<\/p>\n<p style=\"text-align: justify;\">En Twitter: @Jesus_Lens<\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Hoy publico este art\u00edculo en IDEAL. \u00bfC\u00f3mo ves t\u00fa esto de la participaci\u00f3n? Yo pensaba que era el acontecimiento pero, en realidad, es la participaci\u00f3n. As\u00ed lo ha puesto de manifiesto, por ejemplo, la nutrida concurrencia a buena parte de las actividades organizadas bajo el paraguas de La Noche en Blanco o los llenazos en [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[6],"tags":[9346,9347,9345,9348,9349,9350],"class_list":["post-15349","post","type-post","status-publish","format-standard","hentry","category-opinion","tag-participacion","tag-participamos","tag-participar","tag-participio","tag-queremos-participar","tag-yo-participo"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15349","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=15349"}],"version-history":[{"count":3,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15349\/revisions"}],"predecessor-version":[{"id":15356,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15349\/revisions\/15356"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=15349"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=15349"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=15349"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}