{"id":15007,"date":"2013-09-18T17:31:25","date_gmt":"2013-09-18T16:31:25","guid":{"rendered":"http:\/\/www.granadablogs.com\/pateandoelmundo\/?p=15007"},"modified":"2013-09-18T17:37:22","modified_gmt":"2013-09-18T16:37:22","slug":"renoir","status":"publish","type":"post","link":"https:\/\/www.granadablogs.com\/pateandoelmundo\/renoir\/","title":{"rendered":"Renoir"},"content":{"rendered":"<p style=\"text-align: justify;\">Comencemos con una proclama:<em><strong> \u201c\u00a1Menos mal que nos queda el Madrigal!\u201d<\/strong><\/em><\/p>\n<p style=\"text-align: justify;\">Para quienes se\u00e1is de fuera de Granada, os explico: el Madrigal es el \u00fanico cine de la provincia que pone eso que se ha dado en llamar Cine de Autor. \u00a1El \u00fanico! Tras el cierre de Multicines Centro, en la culta capital cultural de Andaluc\u00eda, de Espa\u00f1a y del resto del mundo libre, hay unas 40 pantallas de cine. Y en ninguna de ellas cabe cualquier pel\u00edcula distinta a las m\u00e1s comerciales. En ninguna.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15008\" alt=\"Renoir\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-221x300.jpg\" width=\"221\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-221x300.jpg 221w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-754x1024.jpg 754w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir.jpg 884w\" sizes=\"auto, (max-width: 221px) 100vw, 221px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Menos mal que, como la aldea de los galos de los tebeos de Asterix, nos queda el Madrigal\u2026<\/p>\n<p style=\"text-align: justify;\">Siento no haber comentado antes esta \u201cRenoir\u201d. La vi el martes de hace dos semanas, pero no tuve ocasi\u00f3n de escribir de ella hasta ahora. Demasiados frentes abiertos\u2026 \u00a1Y ya no est\u00e1 en cartel! Pero bueno. Pronto estar\u00e1 en las plataformas digitales de pago. Y seguro que ya est\u00e1 en las de no pago.<\/p>\n<p style=\"text-align: justify;\">Renoir.<\/p>\n<p style=\"text-align: justify;\">\u00a1Menudo apellido!<\/p>\n<p style=\"text-align: justify;\">A nada que tengas un Bachillerato medianamente terminado (al menos, de los de antes) sabr\u00e1s que Renoir fue un reconocido pintor franc\u00e9s, adscrito originalmente al impresionismo. \u00a1Qui\u00e9n no ha visto, aunque sea una reproducci\u00f3n, de \u201cEl Baile del Molino de la Galette\u201d! Este Renoir, llamado Pierre-Auguste, naci\u00f3 en 1841 y falleci\u00f3 en 1919, poco despu\u00e9s de terminada la I Guerra Mundial.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-pel\u00edcula.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15009\" alt=\"Renoir pel\u00edcula\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-pel\u00edcula-300x180.jpg\" width=\"300\" height=\"180\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-pel\u00edcula-300x180.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-pel\u00edcula.jpg 700w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Pero la sombra del apellido Renoir es alargada y los muy cin\u00e9filos (esto ya excede del Bachillerato, lamentablemente) tenemos en un altar a un director de cine, Jean Renoir, cuya \u201cLa regla del juego\u201d figura, con letras de oro, entre lo mejor y m\u00e1s destacado de la historia del cine europeo. Este Renoir, nacido en 1894 y fallecido en 1979 es, efectivamente, hijo de aquel del pintor.<\/p>\n<p style=\"text-align: justify;\">Y este Renoir particip\u00f3, siendo a\u00fan muy joven, en la I Guerra Mundial. En la que fue herido. En una pierna. La convalecencia la pas\u00f3 en la casa paterna. En la Costa Azul. En uno de esos lugares de ensue\u00f1o, repletos de luz y color. Frente al mar. En mitad del campo. All\u00e1 donde la naturaleza exige ser pintada y retratada, por supuesto, pero tambi\u00e9n olida, saboreada, disfrutada y gozada.<\/p>\n<p style=\"text-align: justify;\">Y hasta all\u00ed, hasta el lugar en el que Pierre-Auguste pinta desesperadamente, en el ocaso de su vida, llega una joven, hermosa y descarada, para servir como musa del maestro. Y el maestro se enamora de su piel. De c\u00f3mo capta y refleja la luz. Se enamora, metaf\u00f3ricamente, de un cuerpo que parece haber nacido para ser pintado.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-poster.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15010\" alt=\"Renoir poster\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-poster-210x300.jpg\" width=\"210\" height=\"300\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-poster-210x300.jpg 210w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-poster-716x1024.jpg 716w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-poster.jpg 1120w\" sizes=\"auto, (max-width: 210px) 100vw, 210px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">Solo que los enamoramientos metaf\u00f3ricos, entre los Renoir, hay veces en que no lo son tanto. Como la llegada de un confuso Jean pondr\u00e1 de manifiesto a lo largo de unas semanas que ser\u00e1n capitales a la hora de decidir su futuro personal, profesional y vital.<\/p>\n<p style=\"text-align: justify;\">La pel\u00edcula es larga y morosa. Se detiene en los paisajes y se delecta en el juego de espejos que se establece entre la realidad y su representaci\u00f3n pict\u00f3rica. A la vez, vemos c\u00f3mo la naturaleza afecta a los personajes. Los condiciona. Los provoca. Los moldea.<\/p>\n<p style=\"text-align: justify;\">Y est\u00e1 el tema del sentido del arte. Y del compromiso con la vida. Algo que, posteriormente, estar\u00e1 en la ra\u00edz de \u201cLa regla del juego\u201d. Y est\u00e1, por supuesto, la pasi\u00f3n por el cine. Ese cine que todav\u00eda era un arte nuevo, revolucionario e incipiente.<\/p>\n<p style=\"text-align: justify;\">\u00a0<a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-cartel.jpg\"><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-medium wp-image-15011\" alt=\"Renoir cartel\" src=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-cartel-300x171.jpg\" width=\"300\" height=\"171\" srcset=\"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-cartel-300x171.jpg 300w, https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-content\/uploads\/2013\/09\/Renoir-cartel.jpg 610w\" sizes=\"auto, (max-width: 300px) 100vw, 300px\" \/><\/a><\/p>\n<p style=\"text-align: justify;\">\u201cRenoir\u201d es una buena pel\u00edcula que gustar\u00e1 a cualquier espectador con un m\u00ednimo de sensibilidad y que, eso s\u00ed, para los amantes del arte y del cine; es de visi\u00f3n obligatoria.<\/p>\n<p style=\"text-align: justify;\">Jes\u00fas Lens, so\u00f1ando con cuadros y fotogramas.<\/p>\n<p style=\"text-align: justify;\">En Twitter: @Jesus_Lens<\/p>\n<p style=\"text-align: justify;\">PD.- Cualquier parecido con <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-artista-y-la-modelo\/\" target=\"_blank\">\u201cEl artista y la modelo\u201d <\/a>deber\u00eda ser mera coincidencia. Y, recuerda, \u00a1No es lo mismo ver una pel\u00edcula que ir al cine! Si compartes dicha filosof\u00eda, comparte <a href=\"http:\/\/www.granadablogs.com\/pateandoelmundo\/el-artista-y-la-modelo\/\" target=\"_blank\">esta fotograf\u00eda<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Comencemos con una proclama: \u201c\u00a1Menos mal que nos queda el Madrigal!\u201d Para quienes se\u00e1is de fuera de Granada, os explico: el Madrigal es el \u00fanico cine de la provincia que pone eso que se ha dado en llamar Cine de Autor. \u00a1El \u00fanico! Tras el cierre de Multicines Centro, en la culta capital cultural de [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"jetpack_post_was_ever_published":false,"_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":""},"categories":[10],"tags":[9136,9142,9139,9140,9130,9141,9131,9134,66,9137,9138,9132,9133,9135],"class_list":["post-15007","post","type-post","status-publish","format-standard","hentry","category-cine","tag-christa-theret","tag-cine-de-autor-granada","tag-cine-madrigal","tag-cine-madrigal-granada","tag-gilles-bourdos","tag-menos-mal-que-nos-queda-el-madrigal","tag-michel-bouquet","tag-michele-gleizer","tag-peliculas","tag-renoir","tag-renoir-pelicula-cine","tag-romane-bohringer","tag-thomas-doret","tag-vincent-rottiers"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"_links":{"self":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15007","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/comments?post=15007"}],"version-history":[{"count":5,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15007\/revisions"}],"predecessor-version":[{"id":15016,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/posts\/15007\/revisions\/15016"}],"wp:attachment":[{"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/media?parent=15007"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/categories?post=15007"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.granadablogs.com\/pateandoelmundo\/wp-json\/wp\/v2\/tags?post=15007"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}